{"text_format":"1","workbook":"xlsx","n_sheets":13,"sheets":["General Inputs","Inflation - Input","Connection Numbers Inputs","No of Connections Summ","Volume Inputs","RAB Calculations","Tariff Inputs","Cost allocators","PTRM Inputs","DORC Calculations","FDC Calculations","StandAlone & Avoidable Tests","Tariff & Rebalancing Tests"],"not_rendered":{"charts":0,"images":6,"macros":1,"external_links":11,"defined_names":120,"comments":2,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"General Inputs","index":0,"n_rows":33,"n_cols":18,"rows_kept":33,"cut":false,"hidden":false,"merged":[[3,0,3,1],[17,0,17,4],[0,0,0,13],[9,0,9,17]]}
["General Inputs"]
[]
[]
["WACC calculation"]
["Inflation from 1/1/06 to 30/6/06",{"$f":"B6","v":2.5700000000000001E-2}]
["Inflation rate (forecast)",2.5700000000000001E-2]
["Real pre-tax WACC (average)",9.1700000000000004E-2]
["Nominal pre-tax WACC (average)",0.10639999999999999]
[]
["Inflation index"]
[null,"1999/00","2000/01","2001/02","2002/03","2003/04","2004/05","2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15","2015/16"]
["March",125.2,132.69999999999999,136.6,141.30000000000001,144.1,147.5,151.9,155.6,162.19999999999999,166.2,171,{"$f":"L15*1.025^0.25","v":175.27500000000009}]
["June",126.2,133.80000000000001,137.6,141.30000000000001,144.80000000000001,148.4,154.30000000000001,157.5,164.6,167,{"$f":"L12*1.025^0.25","v":172.05887412168377},176.36034597472596]
["September",130.9,134.19999999999999,138.5,142.1,145.4,149.80000000000001,155.69999999999999,158.6,166.5,168.6,173.12430505275685,177.45241267907588]
["December",131.30000000000001,135.4,139.5,142.80000000000001,146.5,150.6,155.5,160.1,166,169.5,174.1963333945981,178.55124172946313]
["Annual CPI",null,{"$f":"C12/B12-1","v":5.9904153354632506E-2},2.9389600602863553E-2,3.4407027818448066E-2,1.9815994338287179E-2,2.3594725884802159E-2,2.9830508474576245E-2,2.4358130348913765E-2,4.2416452442159303E-2,2.4660912453760897E-2,2.8880866425992746E-2,2.5000000000000577E-2,-1,{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"}]
[]
["Cost Pools"]
["Tariff class","Short Name","Tariff type","Description of cost centre","Description of tariff"]
[1,"Residential 1","Non-demand","Tariff V - Domestic","Residential tariff - anytime use"]
[2,"Residential 2","Non-demand","Tariff V - Domestic","Residential tariff - HW booster only"]
[3,"Residential 3","Non-demand","Tariff V - Domestic","Residential Tariff - off peak only"]
[4,"Commercial 1","Non-demand","Tariff V - I&C","Commercial customers - anytime use"]
[5,"Commercial 2","Non-demand","Tariff V - I&C","Commercial customers - Off peak only"]
[6,"Demand-AdNr","Demand","Tariff D - MDQ (GJ/d) Tariff D Zone - Northern ","Demand customers in region 1"]
[7,"Demand-AdC","Demand","Tariff D - MDQ (GJ/d) Tariff D Zone - Central","Demand customers in region 2"]
[8,"Demand-AdS","Demand","Tariff D - MDQ (GJ/d) Tariff D Zone - Southern ","Demand customers in region 3"]
[9,"Demand-PP","Demand","Tariff D - MDQ (GJ/d) Tariff D Zone - Port Pirie","Demand customers in region 4"]
[10,"Demand-Peter","Demand","Tariff D - MDQ (GJ/d) Tariff D Zone - Peterborough","Demand customers in region 5"]
[11,"Demand-River","Demand","Tariff D - MDQ (GJ/d) Tariff D Zone - Riverland","Demand customers in region 6"]
[12,"Demand-SE","Demand","Tariff D - MDQ (GJ/d) Tariff D Zone - South East","Demand customers in region 7"]
[13,"Demand-Whyal","Demand","Tariff D - MDQ (GJ/d) Tariff D Zone - Whyalla","Demand customers in region 8"]
[14,"Demand-Town","Demand","Tariff D - MDQ (GJ/d) Tariff D Zone - Major Towns"]

{"sheet":"Inflation - Input","index":1,"n_rows":120,"n_cols":16,"rows_kept":120,"cut":false,"hidden":true,"merged":[[2,1,2,5]]}
[null,{"$f":"\"ENVESTRA - Cost allocation model for \"&'General Inputs'!#REF!&\" (\"&'General Inputs'!#REF!&\")\"","v":{"$error":"#REF!"}}]
[null,"Inflation - inputs"]
[null,"Back to table of contents"]
[null,"This sheet provide inputs for inflation values based on Envestra financial model"]
[null,"Updating the 2000 to 2004 Depreciation Allowance"]
[]
[null,"Period Ending 30 June",null,null,null,null,null,null,null,2005,{"$f":"J7+1","v":2006},2007,2008,2009,2010,2011]
[]
[null,"SAIPAR Inflation"]
[null,"Quarterly inflation values up until December 2002 are the assumed values of SAIPAR."]
[null,"Quartley CPI values at and before September 2002 are baqck calculated from SAIPAR's inflation values."]
[]
[null,"Quarterly CPI"]
[]
[null,"March",null,null,null,null,null,null,null,147.5,151.9,155.6,162.19999999999999,166.2,170.35499999999999,174.61387500000012]
[null,"June",null,null,null,null,null,null,null,148.4,154.30000000000001,157.5,164.6,167.22915133932071,171.4098801228038,175.69512712587394]
[null,"September",null,null,null,null,null,null,null,149.80000000000001,155.69999999999999,158.6,166.5,168.26467543724087,172.47129232317195,176.78307463125131]
[null,"December",null,null,null,null,null,null,null,150.6,155.5,160.1,166,169.30661175545148,173.53927704933781,177.87775897557134]
[]
[null,"Quarterly Inflation"]
[null,null,null,null,null,null,null,null,null,2005,2006,2007,2008,2009,2010,2011]
[null,"March",null,null,null,null,null,null,null,6.8259385665530026E-3,8.6321381142098197E-3,6.430868167202064E-4,1.3116801998750649E-2,1.2048192771083599E-3,6.192246325636086E-3,6.192246325636086E-3]
[null,"June",null,null,null,null,null,null,null,6.1016949152543631E-3,1.5799868334430478E-2,1.2210796915167021E-2,1.4796547472256449E-2,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3]
[null,"September",null,null,null,null,null,null,null,9.4339622641510523E-3,9.0732339598182943E-3,6.9841269841268705E-3,1.1543134872417982E-2,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3]
[null,"December",null,null,null,null,null,null,null,5.3404539385846217E-3,-1.2845215157353262E-3,9.4577553593946373E-3,-3.0030030030030463E-3,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3]
[]
[null,"Six Month Inflation"]
[null,null,null,null,null,null,null,null,null,2005,2006,2007,2008,2009,2010,2011]
[null,"March",null,null,null,null,null,null,null,1.4442916093535096E-2,1.4018691588784993E-2,-6.4226075786766312E-4,2.2698612862547263E-2,-1.8018018018018944E-3,1.2422836565829654E-2,1.2422836565829432E-2]
[null,"June",null,null,null,null,null,null,null,1.2969283276450527E-2,2.4568393094289709E-2,1.2861736334405238E-2,2.810743285446593E-2,7.4045261404862561E-3,1.2422836565829432E-2,1.2422836565829432E-2]
[null,"September",null,null,null,null,null,null,null,1.5593220338983027E-2,2.501645819618159E-2,1.9280205655527016E-2,2.6510480887792953E-2,1.2422836565829654E-2,1.2422836565829432E-2,1.2422836565829432E-2]
[null,"December",null,null,null,null,null,null,null,1.4824797843665749E-2,7.7770576798443791E-3,1.6507936507936583E-2,8.5054678007290274E-3,1.2422836565829654E-2,1.2422836565829432E-2,1.2422836565829654E-2]
[]
[null,"Annual Inflation"]
[null,null,null,null,null,null,null,null,null,2005,2006,2007,2008,2009,2010,2011]
[null,"March",null,null,null,null,null,null,null,2.3594725884802159E-2,2.9830508474576245E-2,2.4358130348913765E-2,4.2416452442159303E-2,2.4660912453760897E-2,2.5000000000000577E-2,2.5000000000000355E-2]
[null,"June",null,null,null,null,null,null,null,2.4861878453038555E-2,3.9757412398921943E-2,2.0738820479585085E-2,4.5079365079365052E-2,1.5972972899882754E-2,2.5000000000000355E-2,2.5000000000000355E-2]
[null,"September",null,null,null,null,null,null,null,3.0261348005502064E-2,3.9385847797062556E-2,1.862556197816323E-2,4.9810844892812067E-2,1.0598651274719817E-2,2.5000000000000355E-2,2.5000000000000355E-2]
[null,"December",null,null,null,null,null,null,null,2.7986348122866822E-2,3.253652058432932E-2,2.9581993569131715E-2,3.6851967520299844E-2,1.9919347924406638E-2,2.5000000000000133E-2,2.5000000000000577E-2]
[]
[null,"Inflation factor to 31 December 2005"]
[null,null,null,null,null,null,null,null,null,2005,2006,2007,2008,2009,2010,2011]
[null,"March",null,null,null,null,null,null,null,1,1.0298305084745762,1.0549152542372882,1.0996610169491525,1.1267796610169492,1.1549491525423734,1.1838228813559331]
[null,"June",null,null,null,null,null,null,null,1.0061016949152544,1.0461016949152544,1.0677966101694916,1.1159322033898305,1.1337569582326827,1.1621008821885004,1.191153404243213]
[null,"September",null,null,null,null,null,null,null,1.015593220338983,1.0555932203389831,1.0752542372881355,1.1288135593220339,1.1407774605914636,1.1692968971062505,1.1985293195339073]
[null,"December",null,null,null,null,null,null,null,1.0210169491525423,1.0542372881355933,1.0854237288135593,1.1254237288135593,1.1478414356301796,1.1765374715209342,1.2059509083089581]
[]
[null,"Actual Inlfation"]
[]
[null,"Quarterly CPI"]
[null,null,null,null,null,null,null,null,null,2005,2006,2007,2008,2009,2010,2011]
[null,"March",null,null,null,null,null,null,null,147.5,151.66094091756128,155.45246444050036,159.33877605151295,163.32224545280084,167.40530158912091,171.59043412884901]
[null,"June",null,null,null,null,null,null,null,148.4,152.60006282170056,156.41506439224312,160.32544100204927,164.33357702710057,168.44191645277814,172.65296436409767]
[null,"September",null,null,null,null,null,null,null,149.80000000000001,153.54499999999999,157.38362500000014,161.31821562500019,165.35117101562528,169.48495029101596,173.72207404829143]
[null,"December",null,null,null,null,null,null,null,150.7275984995803,154.49578846206987,158.35818317362168,162.31713775296228,166.37506619678641,170.53444285170613,174.79780392299884]
[]
[null,"Quarterly Inflation"]
[null,null,null,null,null,null,null,null,null,2005,2006,2007,2008,2009,2010,2011]
[null,"March",null,null,null,null,null,null,null,6.8259385665530026E-3,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3]
[null,"June",null,null,null,null,null,null,null,6.1016949152543631E-3,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3]
[null,"September",null,null,null,null,null,null,null,9.4339622641510523E-3,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3]
[null,"December",null,null,null,null,null,null,null,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3]
[]
[null,"Six Month Inflation"]
[null,null,null,null,null,null,null,null,null,2005,2006,2007,2008,2009,2010,2011]
[null,"March",null,null,null,null,null,null,null,1.4442916093535096E-2,1.2422836565829432E-2,1.2422836565829432E-2,1.2422836565829654E-2,1.2422836565829654E-2,1.2422836565829432E-2,1.2422836565829654E-2]
[null,"June",null,null,null,null,null,null,null,1.2969283276450527E-2,1.2422836565829654E-2,1.2422836565829432E-2,1.2422836565829432E-2,1.2422836565829654E-2,1.2422836565829432E-2,1.2422836565829432E-2]
[null,"September",null,null,null,null,null,null,null,1.5593220338983027E-2,1.2422836565829654E-2,1.2422836565829654E-2,1.2422836565829432E-2,1.2422836565829432E-2,1.2422836565829432E-2,1.2422836565829432E-2]
[null,"December",null,null,null,null,null,null,null,1.5684626007953506E-2,1.2422836565829432E-2,1.2422836565829654E-2,1.2422836565829654E-2,1.2422836565829654E-2,1.2422836565829654E-2,1.2422836565829432E-2]
[]
[null,"Annual Inflation"]
[null,null,null,null,null,null,null,null,null,2005,2006,2007,2008,2009,2010,2011]
[null,"March",null,null,null,null,null,null,null,2.3594725884802159E-2,2.8209768932618839E-2,2.5000000000000355E-2,2.5000000000000577E-2,2.5000000000000355E-2,2.5000000000000355E-2,2.5000000000000577E-2]
[null,"June",null,null,null,null,null,null,null,2.4861878453038555E-2,2.8302310119276086E-2,2.5000000000000355E-2,2.5000000000000355E-2,2.5000000000000355E-2,2.5000000000000355E-2,2.5000000000000355E-2]
[null,"September",null,null,null,null,null,null,null,3.0261348005502064E-2,2.5000000000000355E-2,2.5000000000000355E-2,2.5000000000000355E-2,2.5000000000000577E-2,2.5000000000000355E-2,2.5000000000000355E-2]
[null,"December",null,null,null,null,null,null,null,2.8857327642186403E-2,2.5000000000000355E-2,2.5000000000000355E-2,2.5000000000000355E-2,2.5000000000000355E-2,2.5000000000000355E-2,2.5000000000000355E-2]
[]
[null,"Inflation factor to 31 December 2005"]
[null,null,null,null,null,null,null,null,null,2005,2006,2007,2008,2009,2010,2011]
[null,"March",null,null,null,null,null,null,null,1,1.0282097689326188,1.0539150131559347,1.0802628884848335,1.1072694606969549,1.1349511972143791,1.1633249771447391]
[null,"June",null,null,null,null,null,null,null,1.0061016949152544,1.0345766970962751,1.0604411145236823,1.0869521423867747,1.1141259459464445,1.141979094595106,1.1705285719599843]
[null,"September",null,null,null,null,null,null,null,1.015593220338983,1.040983050847458,1.0670076271186451,1.0936828177966116,1.1210248882415272,1.1490505104475659,1.1777767732087554]
[null,"December",null,null,null,null,null,null,null,1.021882023725968,1.0474290743191177,1.0736148011770961,1.100455171206524,1.1279665504866876,1.1561657142488551,1.1850698571050768]
[]
[null,"Model Inflation"]
[]
[null,"Quarterly CPI"]
[null,null,null,null,null,null,null,null,null,2005,2006,2007,2008,2009,2010,2011]
[null,"March",null,null,null,null,null,null,null,147.5,151.9,155.6,162.19999999999999,166.2,170.35499999999999,174.61387500000012]
[null,"June",null,null,null,null,null,null,null,148.4,154.30000000000001,157.5,164.6,167.22915133932071,171.4098801228038,175.69512712587394]
[null,"September",null,null,null,null,null,null,null,149.80000000000001,155.69999999999999,158.6,166.5,168.26467543724087,172.47129232317195,176.78307463125131]
[null,"December",null,null,null,null,null,null,null,150.6,155.5,160.1,166,169.30661175545148,173.53927704933781,177.87775897557134]
[]
[null,"Quarterly Inflation"]
[null,null,null,null,null,null,null,null,null,2005,2006,2007,2008,2009,2010,2011]
[null,"March",null,null,null,null,null,null,null,6.8259385665530026E-3,8.6321381142098197E-3,6.430868167202064E-4,1.3116801998750649E-2,1.2048192771083599E-3,6.192246325636086E-3,6.192246325636086E-3]
[null,"June",null,null,null,null,null,null,null,6.1016949152543631E-3,1.5799868334430478E-2,1.2210796915167021E-2,1.4796547472256449E-2,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3]
[null,"September",null,null,null,null,null,null,null,9.4339622641510523E-3,9.0732339598182943E-3,6.9841269841268705E-3,1.1543134872417982E-2,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3]
[null,"December",null,null,null,null,null,null,null,5.3404539385846217E-3,-1.2845215157353262E-3,9.4577553593946373E-3,-3.0030030030030463E-3,6.192246325636086E-3,6.192246325636086E-3,6.192246325636086E-3]
[]
[null,"Six Month Inflation"]
[null,null,null,null,null,null,null,null,null,2005,2006,2007,2008,2009,2010,2011]
[null,"March",null,null,null,null,null,null,null,1.4442916093535096E-2,1.4018691588784993E-2,-6.4226075786766312E-4,2.2698612862547263E-2,-1.8018018018018944E-3,1.2422836565829654E-2,1.2422836565829432E-2]
[null,"June",null,null,null,null,null,null,null,1.2969283276450527E-2,2.4568393094289709E-2,1.2861736334405238E-2,2.810743285446593E-2,7.4045261404862561E-3,1.2422836565829432E-2,1.2422836565829432E-2]
[null,"September",null,null,null,null,null,null,null,1.5593220338983027E-2,2.501645819618159E-2,1.9280205655527016E-2,2.6510480887792953E-2,1.2422836565829654E-2,1.2422836565829432E-2,1.2422836565829432E-2]
[null,"December",null,null,null,null,null,null,null,1.4824797843665749E-2,7.7770576798443791E-3,1.6507936507936583E-2,8.5054678007290274E-3,1.2422836565829654E-2,1.2422836565829432E-2,1.2422836565829654E-2]
[]
[null,"Annual Inflation",null,null,null,null,null,null,null,2005,2006,2007,2008,2009,2010,2011]
[]
[null,"March",null,null,null,null,null,null,null,2.3594725884802159E-2,2.9830508474576245E-2,2.4358130348913765E-2,4.2416452442159303E-2,2.4660912453760897E-2,2.5000000000000577E-2,2.5000000000000355E-2]
[null,"June",null,null,null,null,null,null,null,2.4861878453038555E-2,3.9757412398921943E-2,2.0738820479585085E-2,4.5079365079365052E-2,1.5972972899882754E-2,2.5000000000000355E-2,2.5000000000000355E-2]
[null,"September",null,null,null,null,null,null,null,3.0261348005502064E-2,3.9385847797062556E-2,1.862556197816323E-2,4.9810844892812067E-2,1.0598651274719817E-2,2.5000000000000355E-2,2.5000000000000355E-2]
[null,"December",null,null,null,null,null,null,null,2.7986348122866822E-2,3.253652058432932E-2,2.9581993569131715E-2,3.6851967520299844E-2,1.9919347924406638E-2,2.5000000000000133E-2,2.5000000000000577E-2]
[]
[null,"Inflation factor to 31 December 2005"]
[null,null,null,null,null,null,null,null,null,2005,2006,2007,2008,2009,2010,2011]
[null,"March",null,null,null,null,null,null,null,1,1.0298305084745762,1.0549152542372882,1.0996610169491525,1.1267796610169492,1.1549491525423734,1.1838228813559331]
[null,"June",null,null,null,null,null,null,null,1.0061016949152544,1.0461016949152544,1.0677966101694916,1.1159322033898305,1.1337569582326827,1.1621008821885004,1.191153404243213]
[null,"September",null,null,null,null,null,null,null,1.015593220338983,1.0555932203389831,1.0752542372881355,1.1288135593220339,1.1407774605914636,1.1692968971062505,1.1985293195339073]
[null,"December",null,null,null,null,null,null,null,1.0210169491525423,1.0542372881355933,1.0854237288135593,1.1254237288135593,1.1478414356301796,1.1765374715209342,1.2059509083089581]

{"sheet":"Connection Numbers Inputs","index":2,"n_rows":86,"n_cols":15,"rows_kept":86,"cut":false,"hidden":false,"merged":[[0,0,0,14]]}
["Connection Numbers Inputs"]
[]
[]
["Fixed Band","Residential 1","Residential 2","Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Tanunda","Demand-Whyal"]
["2006/07",366251,0,0,9251,0,43,74,20,1,2,2,5,0,1]
["2007/08",374118,0,0,9387,0,43,74,21,1,2,2,5,0,1]
["2008/09",381428,0,0,9506,0,43,74,22,1,2,2,5,3,1]
["2009/10",382348.3146996164,0,0,9090.7376368164732,0,43,75,23,1,2,2,5,4,1]
["2010/11",393154.9,0,0,9929.6,0,43,75,24,1,2,3,5,5,1]
["2011/12",401564.3,0,0,10063.6,0,42.238000000000007,73.965846153846144,16.395,1.0247999999999999,0.98750000000000004,2.1488999999999998,4.8821000000000003,0,0.96889999999999998]
["2012/13",408478.4,0,0,10228.799999999999,0,42.003,73.783076923076919,17.207000000000001,1.0288999999999999,0.98640000000000005,2.1722999999999999,4.8562000000000003,1,0.95489999999999997]
["2013/14",415705.3,0,0,10187.200000000001,0,41.187999999999995,72.256615384615387,17.801000000000002,1.0273000000000001,0.97240000000000004,2.1797,4.7744999999999997,1,0.93179999999999996]
["2014/15",423285.8,0,0,10217.6,0,41.091000000000008,71.16707692307692,18.594000000000001,1.0286999999999999,0.96709999999999996,2.2160000000000002,4.7568000000000001,1,0.91059999999999997]
["2015/16",431480.3,0,0,10314,0,41.253,72.268615384615387,19.484999999999999,1.0327,0.96740000000000004,2.2633000000000001,4.7689000000000004,1,0.89470000000000005]
[]
["Price Band 1","Residential 1","Residential 2","Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Tanunda","Demand-Whyal"]
[{"$f":"A5","v":"2006/07"},0,0,0,0,0,0.97727272727272729,4.1111111111111107,1.9047619047619047,0,0,0,0,0,0]
["2007/08",0,0,0,0,0,0.97727272727272729,4.1111111111111107,2,0,0,0,0,0,0]
["2008/09",0,0,0,0,0,0.97727272727272729,4.1111111111111107,2.0952380952380949,0,0,0,0,0,0]
["2009/10",0,0,0,0,0,0.97727272727272729,4.1666666666666661,2.1904761904761902,0,0,0,0,0,0]
["2010/11",0,0,0,0,0,0.97727272727272729,4.1666666666666661,2.2857142857142856,0,0,0,0,0,0]
["2011/12",0,0,0,0,0,1.9645581395348839,0.99857692307692303,1.7257894736842103,0,0,0,0,0,0.96889999999999998]
["2012/13",0,0,0,0,0,1.9536279069767442,0.99096153846153845,1.706,0,0,0,0,0,0.95489999999999997]
["2013/14",0,0,0,0,0,1.9157209302325582,0.96902564102564104,1.6632631578947368,0,0,0,0,0,0.93179999999999996]
["2014/15",0,0,0,0,0,1.9112093023255816,0.96529487179487183,1.641473684210526,0,0,0,0,0,0.91059999999999997]
["2015/16",0,0,0,0,0,1.9187441860465115,0.9695256410256412,1.6299999999999997,0,0,0,0,0,0.89470000000000005]
[]
["Price Band 2","Residential 1","Residential 2","Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Tanunda","Demand-Whyal"]
[{"$f":"A5","v":"2006/07"},0,0,0,0,0,16.613636363636363,22.611111111111114,7.6190476190476186,1,0,1,3,0,1]
[{"$f":"A6","v":"2007/08"},0,0,0,0,0,16.613636363636363,22.611111111111114,8,1,0,1,3,0,1]
[{"$f":"A7","v":"2008/09"},0,0,0,0,0,16.613636363636363,22.611111111111114,8.3809523809523796,1,0,1,3,3,1]
[{"$f":"A8","v":"2009/10"},0,0,0,0,0,16.613636363636363,22.916666666666668,8.761904761904761,1,0,1,3,4,1]
[{"$f":"A9","v":"2010/11"},0,0,0,0,0,16.613636363636363,22.916666666666668,9.1428571428571423,1,0,1.5,3,5,1]
[{"$f":"A22","v":"2011/12"},0,0,0,0,0,12.769627906976746,22.967269230769229,5.1773684210526314,0,0,0,0,0,0]
[{"$f":"A23","v":"2012/13"},0,0,0,0,0,12.698581395348837,22.792115384615386,6.1180000000000003,0,0,0,0,0,0]
[{"$f":"A24","v":"2013/14"},0,0,0,0,0,12.452186046511628,22.287589743589745,6.9897894736842101,0,0,0,0,0,0]
[{"$f":"A25","v":"2014/15"},0,0,0,0,0,12.422860465116282,22.201782051282052,7.9244210526315779,0,0,0,0,0,0]
[{"$f":"A26","v":"2015/16"},0,0,0,0,0,12.471837209302326,22.29908974358975,8.8899999999999988,0,0,0,0,0,0]
[]
["Price Band 3","Residential 1","Residential 2","Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Tanunda","Demand-Whyal"]
[{"$f":"A5","v":"2006/07"},0,0,0,0,0,24.431818181818183,41.111111111111114,10.476190476190476,0,1,1,2,0,0]
[{"$f":"A6","v":"2007/08"},0,0,0,0,0,24.431818181818183,41.111111111111114,11,0,1,1,2,0,0]
[{"$f":"A7","v":"2008/09"},0,0,0,0,0,24.431818181818183,41.111111111111114,11.523809523809524,0,1,1,2,0,0]
[{"$f":"A8","v":"2009/10"},0,0,0,0,0,24.431818181818183,41.666666666666671,12.047619047619047,0,1,1,2,0,0]
[{"$f":"A9","v":"2010/11"},0,0,0,0,0,24.431818181818183,41.666666666666671,12.571428571428573,0,1,1.5,2,0,0]
[{"$f":"A34","v":"2011/12"},0,0,0,0,0,26.521534883720935,45,9.4918421052631583,1.0247999999999999,0,2.1488999999999998,4.8821000000000003,0,0]
[{"$f":"A35","v":"2012/13"},0,0,0,0,0,26.373976744186045,45,9.3830000000000009,1.0288999999999999,0,2.1722999999999999,4.8562000000000003,1,0]
[{"$f":"A36","v":"2013/14"},0,0,0,0,0,25.862232558139535,44,9.1479473684210539,1.0273000000000001,0,2.1797,4.7744999999999997,1,0]
[{"$f":"A37","v":"2014/15"},0,0,0,0,0,25.801325581395353,43,9.0281052631578955,1.0286999999999999,0,2.2160000000000002,4.7568000000000001,1,0]
[{"$f":"A38","v":"2015/16"},0,0,0,0,0,25.903046511627906,44,8.9649999999999999,1.0327,0,2.2633000000000001,4.7689000000000004,1,0]
[]
["Price Band 4","Residential 1","Residential 2","Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Tanunda","Demand-Whyal"]
[{"$f":"A5","v":"2006/07"},0,0,0,0,0,0.97727272727272729,6.1666666666666661,0,0,1,0,0,0,0]
[{"$f":"A6","v":"2007/08"},0,0,0,0,0,0.97727272727272729,6.1666666666666661,0,0,1,0,0,0,0]
[{"$f":"A7","v":"2008/09"},0,0,0,0,0,0.97727272727272729,6.1666666666666661,0,0,1,0,0,0,0]
[{"$f":"A8","v":"2009/10"},0,0,0,0,0,0.97727272727272729,6.25,0,0,1,0,0,0,0]
[{"$f":"A9","v":"2010/11"},0,0,0,0,0,0.97727272727272729,6.25,0,0,1,0,0,0,0]
[{"$f":"A46","v":"2011/12"},0,0,0,0,0,0.98227906976744195,5,0,0,0,0,0,0,0]
[{"$f":"A47","v":"2012/13"},0,0,0,0,0,0.97681395348837208,5,0,0,0,0,0,0,0]
[{"$f":"A48","v":"2013/14"},0,0,0,0,0,0.95786046511627909,5,0,0,0,0,0,0,0]
[{"$f":"A49","v":"2014/15"},0,0,0,0,0,0.95560465116279081,5,0,0,0,0,0,0,0]
[{"$f":"A50","v":"2015/16"},0,0,0,0,0,0.95937209302325577,5,0,0,0,0,0,0,0]
[]
["Price Band 5","Residential 1","Residential 2","Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Tanunda","Demand-Whyal"]
[{"$f":"A5","v":"2006/07"},0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"A6","v":"2007/08"},0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"A7","v":"2008/09"},0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"A8","v":"2009/10"},0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"A9","v":"2010/11"},0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"A58","v":"2011/12"},0,0,0,0,0,0,0,0,0,0.98750000000000004,0,0,0,0]
[{"$f":"A59","v":"2012/13"},0,0,0,0,0,0,0,0,0,0.98640000000000005,0,0,0,0]
[{"$f":"A60","v":"2013/14"},0,0,0,0,0,0,0,0,0,0.97240000000000004,0,0,0,0]
[{"$f":"A61","v":"2014/15"},0,0,0,0,0,0,0,0,0,0.96709999999999996,0,0,0,0]
[{"$f":"A62","v":"2015/16"},0,0,0,0,0,0,0,0,0,0.96740000000000004,0,0,0,0]
[]
["Summary","Residential 1","Residential 2","Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Tanunda","Demand-Whyal"]
[{"$f":"A65","v":"2006/07"},{"$f":"B5+B17+B29+B41+B53+B65","v":366251},0,0,9251,0,{"$f":"G17+G29+G41+G53+G65","v":43},{"$f":"H17+H29+H41+H53+H65","v":74.000000000000014},20,1,2,2,5,0,1]
["2007/08",374118,0,0,9387,0,43,{"$f":"H18+H30+H42+H54+H66","v":74.000000000000014},21,1,2,2,5,0,1]
["2008/09",381428,0,0,9506,0,43,{"$f":"H19+H31+H43+H55+H67","v":74.000000000000014},22,1,2,2,5,3,1]
["2009/10",382348.3146996164,0,0,9090.7376368164732,0,43,{"$f":"H20+H32+H44+H56+H68","v":75},23,1,2,2,5,4,1]
["2010/11",393154.9,0,0,9929.6,0,43,{"$f":"H21+H33+H45+H57+H69","v":75},24,1,2,3,5,5,1]
["2011/12",401564.3,0,0,10063.6,0,42.238000000000007,{"$f":"H22+H34+H46+H58+H70","v":73.965846153846144},{"$f":"I22+I34+I46+I58+I70","v":16.395},1.0247999999999999,0.98750000000000004,2.1488999999999998,4.8821000000000003,0,0.96889999999999998]
["2012/13",408478.4,0,0,10228.799999999999,0,42.003,{"$f":"H23+H35+H47+H59+H71","v":73.783076923076919},{"$f":"I23+I35+I47+I59+I71","v":17.207000000000001},1.0288999999999999,0.98640000000000005,2.1722999999999999,4.8562000000000003,1,0.95489999999999997]
["2013/14",415705.3,0,0,10187.200000000001,0,41.187999999999995,{"$f":"H24+H36+H48+H60+H72","v":72.256615384615387},{"$f":"I24+I36+I48+I60+I72","v":17.801000000000002},1.0273000000000001,0.97240000000000004,2.1797,4.7744999999999997,1,0.93179999999999996]
["2014/15",423285.8,0,0,10217.6,0,41.091000000000008,{"$f":"H25+H37+H49+H61+H73","v":71.16707692307692},{"$f":"I25+I37+I49+I61+I73","v":18.594000000000001},1.0286999999999999,0.96709999999999996,2.2160000000000002,4.7568000000000001,1,0.91059999999999997]
["2015/16",431480.3,0,0,10314,0,41.253,{"$f":"H26+H38+H50+H62+H74","v":72.268615384615387},{"$f":"I26+I38+I50+I62+I74","v":19.484999999999999},1.0327,0.96740000000000004,2.2633000000000001,4.7689000000000004,1,0.89470000000000005]

{"sheet":"No of Connections Summ","index":3,"n_rows":50,"n_cols":16,"rows_kept":50,"cut":false,"hidden":true,"merged":[[2,1,2,5]]}
[null,{"$f":"\"ENVESTRA - Tariff model for \"&'General Inputs'!#REF!&\" (\"&'General Inputs'!#REF!&\")\"","v":{"$error":"#REF!"}}]
[null,"Number of connections - Summary"]
[null,"Back to table of contents"]
[null,"This page summarises the total number of connections input for each cost pools"]
[]
[]
[null,"Period Ending 30 June",null,null,null,null,null,null,null,2005,{"$f":"J7+1","v":2006},2007,2008,2009,2010,2011]
[]
[]
[]
[null,"Connections data"]
[]
[null,null,"Number of connections"]
[]
[]
[null,null,"Total number of connections"]
[null,null,"in connections units"]
[null,null,null,null,null,"Short name","Price bands"]
[]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!B20","v":"Residential 1"},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!B5,SUM('Connection Numbers Inputs'!B17,'Connection Numbers Inputs'!B29,'Connection Numbers Inputs'!B41,'Connection Numbers Inputs'!B53,'Connection Numbers Inputs'!B65))","v":366251},{"$f":"MAX('Connection Numbers Inputs'!B6,SUM('Connection Numbers Inputs'!B18,'Connection Numbers Inputs'!B30,'Connection Numbers Inputs'!B42,'Connection Numbers Inputs'!B54,'Connection Numbers Inputs'!B66))","v":374118},{"$f":"MAX('Connection Numbers Inputs'!B7,SUM('Connection Numbers Inputs'!B19,'Connection Numbers Inputs'!B31,'Connection Numbers Inputs'!B43,'Connection Numbers Inputs'!B55,'Connection Numbers Inputs'!B67))","v":381428},{"$f":"MAX('Connection Numbers Inputs'!B8,SUM('Connection Numbers Inputs'!B20,'Connection Numbers Inputs'!B32,'Connection Numbers Inputs'!B44,'Connection Numbers Inputs'!B56,'Connection Numbers Inputs'!B68))","v":382348.3146996164},{"$f":"MAX('Connection Numbers Inputs'!B9,SUM('Connection Numbers Inputs'!B21,'Connection Numbers Inputs'!B33,'Connection Numbers Inputs'!B45,'Connection Numbers Inputs'!B57,'Connection Numbers Inputs'!B69))","v":393154.9}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!B21","v":"Residential 2"},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!C5,SUM('Connection Numbers Inputs'!C17,'Connection Numbers Inputs'!C29,'Connection Numbers Inputs'!C41,'Connection Numbers Inputs'!C53,'Connection Numbers Inputs'!C65))","v":0},{"$f":"MAX('Connection Numbers Inputs'!C6,SUM('Connection Numbers Inputs'!C18,'Connection Numbers Inputs'!C30,'Connection Numbers Inputs'!C42,'Connection Numbers Inputs'!C54,'Connection Numbers Inputs'!C66))","v":0},{"$f":"MAX('Connection Numbers Inputs'!C7,SUM('Connection Numbers Inputs'!C19,'Connection Numbers Inputs'!C31,'Connection Numbers Inputs'!C43,'Connection Numbers Inputs'!C55,'Connection Numbers Inputs'!C67))","v":0},{"$f":"MAX('Connection Numbers Inputs'!C8,SUM('Connection Numbers Inputs'!C20,'Connection Numbers Inputs'!C32,'Connection Numbers Inputs'!C44,'Connection Numbers Inputs'!C56,'Connection Numbers Inputs'!C68))","v":0},{"$f":"MAX('Connection Numbers Inputs'!C9,SUM('Connection Numbers Inputs'!C21,'Connection Numbers Inputs'!C33,'Connection Numbers Inputs'!C45,'Connection Numbers Inputs'!C57,'Connection Numbers Inputs'!C69))","v":0}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!B22","v":"Residential 3"},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!D5,SUM('Connection Numbers Inputs'!D17,'Connection Numbers Inputs'!D29,'Connection Numbers Inputs'!D41,'Connection Numbers Inputs'!D53,'Connection Numbers Inputs'!D65))","v":0},{"$f":"MAX('Connection Numbers Inputs'!D6,SUM('Connection Numbers Inputs'!D18,'Connection Numbers Inputs'!D30,'Connection Numbers Inputs'!D42,'Connection Numbers Inputs'!D54,'Connection Numbers Inputs'!D66))","v":0},{"$f":"MAX('Connection Numbers Inputs'!D7,SUM('Connection Numbers Inputs'!D19,'Connection Numbers Inputs'!D31,'Connection Numbers Inputs'!D43,'Connection Numbers Inputs'!D55,'Connection Numbers Inputs'!D67))","v":0},{"$f":"MAX('Connection Numbers Inputs'!D8,SUM('Connection Numbers Inputs'!D20,'Connection Numbers Inputs'!D32,'Connection Numbers Inputs'!D44,'Connection Numbers Inputs'!D56,'Connection Numbers Inputs'!D68))","v":0},{"$f":"MAX('Connection Numbers Inputs'!D9,SUM('Connection Numbers Inputs'!D21,'Connection Numbers Inputs'!D33,'Connection Numbers Inputs'!D45,'Connection Numbers Inputs'!D57,'Connection Numbers Inputs'!D69))","v":0}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!B23","v":"Commercial 1"},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!E5,SUM('Connection Numbers Inputs'!E17,'Connection Numbers Inputs'!E29,'Connection Numbers Inputs'!E41,'Connection Numbers Inputs'!E53,'Connection Numbers Inputs'!E65))","v":9251},{"$f":"MAX('Connection Numbers Inputs'!E6,SUM('Connection Numbers Inputs'!E18,'Connection Numbers Inputs'!E30,'Connection Numbers Inputs'!E42,'Connection Numbers Inputs'!E54,'Connection Numbers Inputs'!E66))","v":9387},{"$f":"MAX('Connection Numbers Inputs'!E7,SUM('Connection Numbers Inputs'!E19,'Connection Numbers Inputs'!E31,'Connection Numbers Inputs'!E43,'Connection Numbers Inputs'!E55,'Connection Numbers Inputs'!E67))","v":9506},{"$f":"MAX('Connection Numbers Inputs'!E8,SUM('Connection Numbers Inputs'!E20,'Connection Numbers Inputs'!E32,'Connection Numbers Inputs'!E44,'Connection Numbers Inputs'!E56,'Connection Numbers Inputs'!E68))","v":9090.7376368164732},{"$f":"MAX('Connection Numbers Inputs'!E9,SUM('Connection Numbers Inputs'!E21,'Connection Numbers Inputs'!E33,'Connection Numbers Inputs'!E45,'Connection Numbers Inputs'!E57,'Connection Numbers Inputs'!E69))","v":9929.6}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!B24","v":"Commercial 2"},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!F5,SUM('Connection Numbers Inputs'!F17,'Connection Numbers Inputs'!F29,'Connection Numbers Inputs'!F41,'Connection Numbers Inputs'!F53,'Connection Numbers Inputs'!F65))","v":0},{"$f":"MAX('Connection Numbers Inputs'!F6,SUM('Connection Numbers Inputs'!F18,'Connection Numbers Inputs'!F30,'Connection Numbers Inputs'!F42,'Connection Numbers Inputs'!F54,'Connection Numbers Inputs'!F66))","v":0},{"$f":"MAX('Connection Numbers Inputs'!F7,SUM('Connection Numbers Inputs'!F19,'Connection Numbers Inputs'!F31,'Connection Numbers Inputs'!F43,'Connection Numbers Inputs'!F55,'Connection Numbers Inputs'!F67))","v":0},{"$f":"MAX('Connection Numbers Inputs'!F8,SUM('Connection Numbers Inputs'!F20,'Connection Numbers Inputs'!F32,'Connection Numbers Inputs'!F44,'Connection Numbers Inputs'!F56,'Connection Numbers Inputs'!F68))","v":0},{"$f":"MAX('Connection Numbers Inputs'!F9,SUM('Connection Numbers Inputs'!F21,'Connection Numbers Inputs'!F33,'Connection Numbers Inputs'!F45,'Connection Numbers Inputs'!F57,'Connection Numbers Inputs'!F69))","v":0}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!B25","v":"Demand-AdNr"},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!H5,SUM('Connection Numbers Inputs'!H17,'Connection Numbers Inputs'!H29,'Connection Numbers Inputs'!H41,'Connection Numbers Inputs'!H53,'Connection Numbers Inputs'!H65))","v":74.000000000000014},{"$f":"MAX('Connection Numbers Inputs'!H6,SUM('Connection Numbers Inputs'!H18,'Connection Numbers Inputs'!H30,'Connection Numbers Inputs'!H42,'Connection Numbers Inputs'!H54,'Connection Numbers Inputs'!H66))","v":74.000000000000014},{"$f":"MAX('Connection Numbers Inputs'!H7,SUM('Connection Numbers Inputs'!H19,'Connection Numbers Inputs'!H31,'Connection Numbers Inputs'!H43,'Connection Numbers Inputs'!H55,'Connection Numbers Inputs'!H67))","v":74.000000000000014},{"$f":"MAX('Connection Numbers Inputs'!H8,SUM('Connection Numbers Inputs'!H20,'Connection Numbers Inputs'!H32,'Connection Numbers Inputs'!H44,'Connection Numbers Inputs'!H56,'Connection Numbers Inputs'!H68))","v":75},{"$f":"MAX('Connection Numbers Inputs'!H9,SUM('Connection Numbers Inputs'!H21,'Connection Numbers Inputs'!H33,'Connection Numbers Inputs'!H45,'Connection Numbers Inputs'!H57,'Connection Numbers Inputs'!H69))","v":75}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!B26","v":"Demand-AdC"},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!G5,SUM('Connection Numbers Inputs'!G17,'Connection Numbers Inputs'!G29,'Connection Numbers Inputs'!G41,'Connection Numbers Inputs'!G53,'Connection Numbers Inputs'!G65))","v":43},{"$f":"MAX('Connection Numbers Inputs'!G6,SUM('Connection Numbers Inputs'!G18,'Connection Numbers Inputs'!G30,'Connection Numbers Inputs'!G42,'Connection Numbers Inputs'!G54,'Connection Numbers Inputs'!G66))","v":43},{"$f":"MAX('Connection Numbers Inputs'!G7,SUM('Connection Numbers Inputs'!G19,'Connection Numbers Inputs'!G31,'Connection Numbers Inputs'!G43,'Connection Numbers Inputs'!G55,'Connection Numbers Inputs'!G67))","v":43},{"$f":"MAX('Connection Numbers Inputs'!G8,SUM('Connection Numbers Inputs'!G20,'Connection Numbers Inputs'!G32,'Connection Numbers Inputs'!G44,'Connection Numbers Inputs'!G56,'Connection Numbers Inputs'!G68))","v":43},{"$f":"MAX('Connection Numbers Inputs'!G9,SUM('Connection Numbers Inputs'!G21,'Connection Numbers Inputs'!G33,'Connection Numbers Inputs'!G45,'Connection Numbers Inputs'!G57,'Connection Numbers Inputs'!G69))","v":43}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!B27","v":"Demand-AdS"},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!I5,SUM('Connection Numbers Inputs'!I17,'Connection Numbers Inputs'!I29,'Connection Numbers Inputs'!I41,'Connection Numbers Inputs'!I53,'Connection Numbers Inputs'!I65))","v":20},{"$f":"MAX('Connection Numbers Inputs'!I6,SUM('Connection Numbers Inputs'!I18,'Connection Numbers Inputs'!I30,'Connection Numbers Inputs'!I42,'Connection Numbers Inputs'!I54,'Connection Numbers Inputs'!I66))","v":21},{"$f":"MAX('Connection Numbers Inputs'!I7,SUM('Connection Numbers Inputs'!I19,'Connection Numbers Inputs'!I31,'Connection Numbers Inputs'!I43,'Connection Numbers Inputs'!I55,'Connection Numbers Inputs'!I67))","v":22},{"$f":"MAX('Connection Numbers Inputs'!I8,SUM('Connection Numbers Inputs'!I20,'Connection Numbers Inputs'!I32,'Connection Numbers Inputs'!I44,'Connection Numbers Inputs'!I56,'Connection Numbers Inputs'!I68))","v":23},{"$f":"MAX('Connection Numbers Inputs'!I9,SUM('Connection Numbers Inputs'!I21,'Connection Numbers Inputs'!I33,'Connection Numbers Inputs'!I45,'Connection Numbers Inputs'!I57,'Connection Numbers Inputs'!I69))","v":24}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!B28","v":"Demand-PP"},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!K5,SUM('Connection Numbers Inputs'!K17,'Connection Numbers Inputs'!K29,'Connection Numbers Inputs'!K41,'Connection Numbers Inputs'!K53,'Connection Numbers Inputs'!K65))","v":2},{"$f":"MAX('Connection Numbers Inputs'!K6,SUM('Connection Numbers Inputs'!K18,'Connection Numbers Inputs'!K30,'Connection Numbers Inputs'!K42,'Connection Numbers Inputs'!K54,'Connection Numbers Inputs'!K66))","v":2},{"$f":"MAX('Connection Numbers Inputs'!K7,SUM('Connection Numbers Inputs'!K19,'Connection Numbers Inputs'!K31,'Connection Numbers Inputs'!K43,'Connection Numbers Inputs'!K55,'Connection Numbers Inputs'!K67))","v":2},{"$f":"MAX('Connection Numbers Inputs'!K8,SUM('Connection Numbers Inputs'!K20,'Connection Numbers Inputs'!K32,'Connection Numbers Inputs'!K44,'Connection Numbers Inputs'!K56,'Connection Numbers Inputs'!K68))","v":2},{"$f":"MAX('Connection Numbers Inputs'!K9,SUM('Connection Numbers Inputs'!K21,'Connection Numbers Inputs'!K33,'Connection Numbers Inputs'!K45,'Connection Numbers Inputs'!K57,'Connection Numbers Inputs'!K69))","v":2}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!B29","v":"Demand-Peter"},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!J5,SUM('Connection Numbers Inputs'!J17,'Connection Numbers Inputs'!J29,'Connection Numbers Inputs'!J41,'Connection Numbers Inputs'!J53,'Connection Numbers Inputs'!J65))","v":1},{"$f":"MAX('Connection Numbers Inputs'!J6,SUM('Connection Numbers Inputs'!J18,'Connection Numbers Inputs'!J30,'Connection Numbers Inputs'!J42,'Connection Numbers Inputs'!J54,'Connection Numbers Inputs'!J66))","v":1},{"$f":"MAX('Connection Numbers Inputs'!J7,SUM('Connection Numbers Inputs'!J19,'Connection Numbers Inputs'!J31,'Connection Numbers Inputs'!J43,'Connection Numbers Inputs'!J55,'Connection Numbers Inputs'!J67))","v":1},{"$f":"MAX('Connection Numbers Inputs'!J8,SUM('Connection Numbers Inputs'!J20,'Connection Numbers Inputs'!J32,'Connection Numbers Inputs'!J44,'Connection Numbers Inputs'!J56,'Connection Numbers Inputs'!J68))","v":1},{"$f":"MAX('Connection Numbers Inputs'!J9,SUM('Connection Numbers Inputs'!J21,'Connection Numbers Inputs'!J33,'Connection Numbers Inputs'!J45,'Connection Numbers Inputs'!J57,'Connection Numbers Inputs'!J69))","v":1}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!B30","v":"Demand-River"},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!L5,SUM('Connection Numbers Inputs'!L17,'Connection Numbers Inputs'!L29,'Connection Numbers Inputs'!L41,'Connection Numbers Inputs'!L53,'Connection Numbers Inputs'!L65))","v":2},{"$f":"MAX('Connection Numbers Inputs'!L6,SUM('Connection Numbers Inputs'!L18,'Connection Numbers Inputs'!L30,'Connection Numbers Inputs'!L42,'Connection Numbers Inputs'!L54,'Connection Numbers Inputs'!L66))","v":2},{"$f":"MAX('Connection Numbers Inputs'!L7,SUM('Connection Numbers Inputs'!L19,'Connection Numbers Inputs'!L31,'Connection Numbers Inputs'!L43,'Connection Numbers Inputs'!L55,'Connection Numbers Inputs'!L67))","v":2},{"$f":"MAX('Connection Numbers Inputs'!L8,SUM('Connection Numbers Inputs'!L20,'Connection Numbers Inputs'!L32,'Connection Numbers Inputs'!L44,'Connection Numbers Inputs'!L56,'Connection Numbers Inputs'!L68))","v":2},{"$f":"MAX('Connection Numbers Inputs'!L9,SUM('Connection Numbers Inputs'!L21,'Connection Numbers Inputs'!L33,'Connection Numbers Inputs'!L45,'Connection Numbers Inputs'!L57,'Connection Numbers Inputs'!L69))","v":3}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!B31","v":"Demand-SE"},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!M5,SUM('Connection Numbers Inputs'!M17,'Connection Numbers Inputs'!M29,'Connection Numbers Inputs'!M41,'Connection Numbers Inputs'!M53,'Connection Numbers Inputs'!M65))","v":5},{"$f":"MAX('Connection Numbers Inputs'!M6,SUM('Connection Numbers Inputs'!M18,'Connection Numbers Inputs'!M30,'Connection Numbers Inputs'!M42,'Connection Numbers Inputs'!M54,'Connection Numbers Inputs'!M66))","v":5},{"$f":"MAX('Connection Numbers Inputs'!M7,SUM('Connection Numbers Inputs'!M19,'Connection Numbers Inputs'!M31,'Connection Numbers Inputs'!M43,'Connection Numbers Inputs'!M55,'Connection Numbers Inputs'!M67))","v":5},{"$f":"MAX('Connection Numbers Inputs'!M8,SUM('Connection Numbers Inputs'!M20,'Connection Numbers Inputs'!M32,'Connection Numbers Inputs'!M44,'Connection Numbers Inputs'!M56,'Connection Numbers Inputs'!M68))","v":5},{"$f":"MAX('Connection Numbers Inputs'!M9,SUM('Connection Numbers Inputs'!M21,'Connection Numbers Inputs'!M33,'Connection Numbers Inputs'!M45,'Connection Numbers Inputs'!M57,'Connection Numbers Inputs'!M69))","v":5}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!B32","v":"Demand-Whyal"},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!O5,SUM('Connection Numbers Inputs'!O17,'Connection Numbers Inputs'!O29,'Connection Numbers Inputs'!O41,'Connection Numbers Inputs'!O53,'Connection Numbers Inputs'!O65))","v":1},{"$f":"MAX('Connection Numbers Inputs'!O6,SUM('Connection Numbers Inputs'!O18,'Connection Numbers Inputs'!O30,'Connection Numbers Inputs'!O42,'Connection Numbers Inputs'!O54,'Connection Numbers Inputs'!O66))","v":1},{"$f":"MAX('Connection Numbers Inputs'!O7,SUM('Connection Numbers Inputs'!O19,'Connection Numbers Inputs'!O31,'Connection Numbers Inputs'!O43,'Connection Numbers Inputs'!O55,'Connection Numbers Inputs'!O67))","v":1},{"$f":"MAX('Connection Numbers Inputs'!O8,SUM('Connection Numbers Inputs'!O20,'Connection Numbers Inputs'!O32,'Connection Numbers Inputs'!O44,'Connection Numbers Inputs'!O56,'Connection Numbers Inputs'!O68))","v":1},{"$f":"MAX('Connection Numbers Inputs'!O9,SUM('Connection Numbers Inputs'!O21,'Connection Numbers Inputs'!O33,'Connection Numbers Inputs'!O45,'Connection Numbers Inputs'!O57,'Connection Numbers Inputs'!O69))","v":1}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!B33","v":"Demand-Town"},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!N5,SUM('Connection Numbers Inputs'!N17,'Connection Numbers Inputs'!N29,'Connection Numbers Inputs'!N41,'Connection Numbers Inputs'!N53,'Connection Numbers Inputs'!N65))","v":0},{"$f":"MAX('Connection Numbers Inputs'!N6,SUM('Connection Numbers Inputs'!N18,'Connection Numbers Inputs'!N30,'Connection Numbers Inputs'!N42,'Connection Numbers Inputs'!N54,'Connection Numbers Inputs'!N66))","v":0},{"$f":"MAX('Connection Numbers Inputs'!N7,SUM('Connection Numbers Inputs'!N19,'Connection Numbers Inputs'!N31,'Connection Numbers Inputs'!N43,'Connection Numbers Inputs'!N55,'Connection Numbers Inputs'!N67))","v":3},{"$f":"MAX('Connection Numbers Inputs'!N8,SUM('Connection Numbers Inputs'!N20,'Connection Numbers Inputs'!N32,'Connection Numbers Inputs'!N44,'Connection Numbers Inputs'!N56,'Connection Numbers Inputs'!N68))","v":4},{"$f":"MAX('Connection Numbers Inputs'!N9,SUM('Connection Numbers Inputs'!N21,'Connection Numbers Inputs'!N33,'Connection Numbers Inputs'!N45,'Connection Numbers Inputs'!N57,'Connection Numbers Inputs'!N69))","v":5}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}}]
[null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},"Total",null,null,null,null,{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}},{"$f":"MAX('Connection Numbers Inputs'!#REF!,SUM('Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!,'Connection Numbers Inputs'!#REF!))","v":{"$error":"#REF!"}}]
[null,null,"Total",null,null,null,null,null,null,null,null,{"$f":"SUM(L20:L49)","v":{"$error":"#REF!"}},{"$f":"SUM(M20:M49)","v":{"$error":"#REF!"}},{"$f":"SUM(N20:N49)","v":{"$error":"#REF!"}},{"$f":"SUM(O20:O49)","v":{"$error":"#REF!"}},{"$f":"SUM(P20:P49)","v":{"$error":"#REF!"}}]

{"sheet":"Volume Inputs","index":4,"n_rows":74,"n_cols":15,"rows_kept":74,"cut":false,"hidden":false,"merged":[[0,0,0,14],[2,1,2,5],[2,6,2,14]]}
["Volume Inputs"]
[]
[null,"GJ/day",null,null,null,null,"MDQ(GJ)"]
["Price Band 1","Residential 1","Residential 2","Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Tanunda","Demand-Whyal"]
[{"$f":"'Connection Numbers Inputs'!A5","v":"2006/07"},5029285.2591099655,0,0,1264745.4999516711,0,2129.3904933358972,3539.4870969863246,1119.1843575418995,50,100,100,206.86805747447877,0,50]
[{"$f":"'Connection Numbers Inputs'!A6","v":"2007/08"},5001450.7796492651,0,0,1212835.7282568684,0,2123.843938100058,3556.8619663569566,1148.1787709497207,50,100,100,213.82217686568762,0,50]
[{"$f":"'Connection Numbers Inputs'!A7","v":"2008/09"},5090813.14115451,0,0,1234779.3942563587,0,2112.8879276202028,3699.1571207803777,1177.1731843575419,50,100,100,221.25275654501652,145.54285714285712,50]
[{"$f":"'Connection Numbers Inputs'!A8","v":"2009/10"},4422098.4766294388,0,0,1147245.5727113287,0,2104.7162424827311,3720.8373609215273,1206.1675977653631,50,100,100,229.19244110675345,192.56603773584905,50]
[{"$f":"'Connection Numbers Inputs'!A9","v":"2010/11"},4379602.9613451939,0,0,1148263.1021267155,0,2097.2788679061623,3609.3489790759086,1235.1620111731843,50,100,100,237.67611178392141,240.45283018867926,50]
[{"$f":"'Connection Numbers Inputs'!A10","v":"2011/12"},3076008.1091524358,0,0,1159573.0517614151,0,2123.7087935983295,3797.8438889740842,838.3565601631542,50.668067226890756,50,100,250,0,50]
[{"$f":"'Connection Numbers Inputs'!A11","v":"2012/13"},3022300.4089596597,0,0,1183318.7510805577,0,2088.949291119422,3736.1307698205801,878.82222977566278,50.852941176470587,50,100,250,50,50]
[{"$f":"'Connection Numbers Inputs'!A12","v":"2013/14"},2972275.8236346645,0,0,1165325.2879625834,0,2034.5724971731752,3603.3223431988963,909.49354180829368,50.777310924369743,50,100,250,50,50]
[{"$f":"'Connection Numbers Inputs'!A13","v":"2014/15"},2924276.126641612,0,0,1173890.9981038773,0,2048.0342698095155,3606.2678270203955,948.54350781781102,50.844537815126053,50,100,250,50,50]
[{"$f":"'Connection Numbers Inputs'!A14","v":"2015/16"},2887724.9473535018,0,0,1195322.7883700114,0,2069.2406714795165,3655.3841435362674,992.44731475186961,51.02521008403361,50,100,250,50,50]
[]
["Price Band 2","Residential 1","Residential 2","Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Tanunda","Demand-Whyal"]
[{"$f":"A5","v":"2006/07"},2759646.4366409937,0,0,1182964.1301707141,0,1581.5563936867527,2842.8426956724434,830.22346368715068,12,100,100,136.532917933156,0,7]
["2007/08",2530729.7249435498,0,0,1158924.3758523096,0,1577.436815843407,2875.3340620635208,851.73184357541902,12,100,100,141.12263673135385,0,7]
["2008/09",2810587.4451109674,0,0,1182708.1604937487,0,1569.2994880597325,2989.9753996798759,873.24022346368702,12,100,100,146.02681931971094,137.45714285714283,7]
["2009/10",3163901.5233705607,0,0,1108532.5675610006,0,1563.2301546439921,3007.4422750608137,894.74860335195501,12,100,100,151.26701113045729,185.43396226415095,7]
["2010/11",3133497.0386548061,0,0,1109515.7611528849,0,1557.7062137084861,2917.6206836281758,916.25698324022335,12,100,100,156.86623377738815,231.54716981132074,7]
["2011/12",1436270.0567602266,0,0,1121411.7317408328,0,1717.1702531095066,3255.5722435209323,716.05513256288248,50.668067226890756,50,100,250,0,0]
["2012/13",1411816.4868756186,0,0,1144480.062751486,0,1689.0647125337043,3202.2299551449164,757.91169272603679,50.852941176470587,50,100,250,50,0]
["2013/14",1389537.4661522335,0,0,1126987.2822669519,0,1645.0971905714532,3087.4357997239686,791.40271923861337,50.777310924369743,50,100,250,50,0]
["2014/15",1368162.5546510741,0,0,1135469.5460785604,0,1655.9819953031226,3089.9817550989105,832.05010197144816,50.844537815126053,50,100,250,50,0]
["2015/16",1352100.7789712809,0,0,1156422.0688729689,0,1673.128885796295,3132.4358840668606,876.84323589395001,51.02521008403361,50,100,250,50,0]
[]
["Price Band 3","Residential 1","Residential 2","Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Tanunda","Demand-Whyal"]
[{"$f":"A17","v":"2006/07"},0,0,0,563699.4533721311,0,6391.6996490069132,13604.581081012826,1910.5921787709497,0,616,550,573.43825531925529,0,0]
["2007/08",0,0,0,567333.51607902383,0,6375.0507932591963,14002.373960041296,1960.0893854748601,0,616,550,592.71507427168615,0,0]
["2008/09",0,0,0,572374.2723577643,0,6342.164608899041,14534.018588157158,2009.5865921787708,0,616,550,613.31264114278599,0,0]
["2009/10",0,0,0,571744.95493352017,0,6317.6360138910159,14615.020525672231,2059.0837988826815,0,616,550,635.32144674792062,0,0]
["2010/11",0,0,0,572252.05413144419,0,6295.3115672386239,14198.476479982672,2108.5810055865923,0,616,550,658.83818186503015,0,0]
["2011/12",2798461.8340873369,0,0,588008.72662874474,0,7482.5339827781154,15065.509185707717,1347.2883072739633,19.253865546218485,400,243.45,395.01,0,0]
["2012/13",2760744.604164721,0,0,600123.91749330866,0,7360.0646690440981,14790.189554899556,1331.9660774983004,19.324117647058824,400,246.86,388.28,75,0]
["2013/14",2732008.710213101,0,0,590931.95327705017,0,7168.4770983734879,14197.693704953232,1300.9037389530931,19.2953781512605,400,247.98000000000002,369.59000000000003,75,0]
["2014/15",2710316.8187073139,0,0,595408.38098182203,0,7215.9074106288608,14210.834339058427,1283.3063902107408,19.3209243697479,400,254.75,364.73,75,0]
["2015/16",2704531.7736752168,0,0,606428.97306201397,0,7290.6246325128313,14429.956080355772,1273.509449354181,19.389579831932771,400,263.75,365.62,75,0]
[]
["Price Band 4","Residential 1","Residential 2","Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Tanunda","Demand-Whyal"]
[{"$f":"A29","v":"2006/07"},0,0,0,234160.21568157387,0,290.37143090944051,24092.481351139326,0,0,500,0,0,0,0]
["2007/08",0,0,0,263505.53055581206,0,289.61508246818971,30373.430011538225,0,0,500,0,0,0,0]
["2008/09",0,0,0,284531.29526304791,0,288.12108103911856,30924.18830715309,0,0,500,0,0,0,0]
["2009/10",0,0,0,216676.90479414994,0,287.00676033855422,31008.102423252432,0,0,500,0,0,0,0]
["2010/11",0,0,0,216869.08258895454,0,285.99257289629486,30576.582801836248,0,0,500,0,0,0,0]
["2011/12",0,0,0,202315.78986900768,0,303.38697051404705,9429.8746817972715,0,0,500,0,0,0,0]
["2012/13",0,0,0,206468.16867464755,0,298.42132730277456,8994.7497201349506,0,0,500,0,0,0,0]
["2013/14",0,0,0,203349.37649341478,0,290.6532138818821,8058.3481521239082,0,0,500,0,0,0,0]
["2014/15",0,0,0,204844.17483574071,0,292.57632425850215,8079.116078822266,0,0,500,0,0,0,0]
["2015/16",0,0,0,208582.26969500509,0,295.60581021135943,8425.4238920410971,0,0,500,0,0,0,0]
[]
["Price Band 5","Residential 1","Residential 2","Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Tanunda","Demand-Whyal"]
[{"$f":"A41","v":"2006/07"},0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["2007/08",0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["2008/09",0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["2009/10",0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["2010/11",0,0,0,0,0,0,0,0,0,0,0,0,0,0]
["2011/12",0,0,0,0,0,0,0,0,0,2290.6,0,0,0,0]
["2012/13",0,0,0,0,0,0,0,0,0,2286.3000000000002,0,0,0,0]
["2013/14",0,0,0,0,0,0,0,0,0,2233.6,0,0,0,0]
["2014/15",0,0,0,0,0,0,0,0,0,2213.5,0,0,0,0]
["2015/16",0,0,0,0,0,0,0,0,0,2214.6,0,0,0,0]
[]
["Summary","Residential 1","Residential 2","Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Tanunda","Demand-Whyal"]
[{"$f":"A53","v":"2006/07"},{"$f":"B5+B17+B29+B41+B53","v":7788931.6957509592},0,0,3245569.2991760899,0,10393.017966939004,44079.392224810916,3860,62,1316,750,916.83923072689004,0,57]
["2007/08",{"$f":"B6+B18+B30+B42+B54","v":7532180.5045928154},0,0,3202599.1507440144,0,10365.946629670852,50808,3960,62,1316,750,947.65988786872765,0,57]
["2008/09",{"$f":"B7+B19+B31+B43+B55","v":7901400.5862654774},0,0,3274393.1223709192,0,10312.473105618095,52147.339415770504,4060,62,1316,750,980.59221700751345,282.99999999999994,57]
["2009/10",{"$f":"B8+B20+B32+B44+B56","v":7586000},0,0,3044200,0,10272.589171356292,52351.402584907002,4160,62,1316,750,1015.7808989851313,378,57]
["2010/11",{"$f":"B9+B21+B33+B45+B57","v":7513100},0,0,3046899.9999999991,0,10236.289221749568,51302.028944523001,4260,62,1316,750,1053.3805274263398,472,57]
["2011/12",{"$f":"B10+B22+B34+B46+B58","v":7310740},0,0,3071309.3000000007,0,11626.8,31548.800000000003,2901.7,120.59,3290.6,443.45,895.01,0,50]
["2012/13",{"$f":"B11+B23+B35+B47+B59","v":7194861.5},0,0,3134390.9,0,11436.5,30723.300000000003,2968.7,121.03,3286.3,446.86,888.28,175,50]
["2013/14",{"$f":"B12+B24+B36+B48+B60","v":7093821.9999999981},0,0,3086593.9,0,11138.799999999997,28946.800000000003,3001.8,120.85,3233.6,447.98,869.59,175,50]
["2014/15",{"$f":"B13+B25+B37+B49+B61","v":7002755.5},0,0,3109613.1,0,11212.5,28986.2,3063.8999999999996,121.01,3213.5,454.75,864.73,175,50]
["2015/16",{"$f":"B14+B26+B38+B50+B62","v":6944357.5},0,0,3166756.0999999992,0,11328.600000000002,29643.199999999997,3142.8000000000006,121.44,3214.6,463.75,865.62,175,50]

{"sheet":"RAB Calculations","index":5,"n_rows":647,"n_cols":16,"rows_kept":647,"cut":false,"hidden":true,"merged":[[2,1,2,5]]}
[null,{"$f":"\"ENVESTRA - Cost allocation model for \"&'General Inputs'!#REF!&\" (\"&'General Inputs'!#REF!&\")\"","v":{"$error":"#REF!"}}]
[null,"Regulatory Asset Base Calculations"]
[]
[]
[]
[]
[null,"Period Ending 30 June",null,null,null,null,null,null,null,2005,{"$f":"J7+1","v":2006},2007,2008,2009,2010,2011]
[]
[]
[]
[null,"Summary of Regulatory Asset Base Calculations (in $million)"]
[null,null,"Depreciation",null,null,null,null,null,"5-year NPV"]
[null,null,null,null,"Mains and Inlets",null,null,null,{"$f":"NPV(realpretaxwacc,L13:P13)","v":36.360465507580983},null,{"$f":"K82","v":{"$error":"#REF!"}},8.229431321843931,8.7843678102258647,9.5151949688322812,10.163772708139899,10.82815563008295]
[null,null,null,null,"Meters",null,null,null,15.490254859520554,null,{"$f":"K183","v":{"$error":"#REF!"}},3.2436114809747862,3.6110674274150023,4.0626326679072982,4.5016585444206791,4.9581695780278645]
[null,null,null,null,"Telemetry",null,null,null,0.30442932490369462,null,{"$f":"+K278","v":{"$error":"#REF!"}},3.3011186201717772E-2,6.029364985954741E-2,8.3744651913413015E-2,0.10625346212483093,0.13092451593503959]
[null,null,null,null,"IT Systems",null,null,null,9.340414900671977,null,{"$f":"+K383","v":{"$error":"#REF!"}},0.92689547046764975,1.7626994396785995,3.0159145332413315,3.4689467501358684,3.4923493189510824]
[null,null,null,null,"Other Distribution Equipment",null,null,null,26.425164962318615,null,{"$f":"+K483","v":{"$error":"#REF!"}},6.3678537157254995,6.5513399469149389,6.8518775631548277,7.1282107119170668,7.4595601258422279]
[null,null,null,null,"Other Assets",null,null,null,4.0553099698277428,null,{"$f":"+K583","v":{"$error":"#REF!"}},0.86346855650095145,0.95729018869476301,1.0737716526263716,1.1662380079807293,1.2634877078685456]
[null,null,null,"Total",null,null,null,null,{"$f":"SUM(I13:I18)","v":91.976039524823577},null,{"$f":"SUM(K13:K18)","v":{"$error":"#REF!"}},19.664271731714535,21.727058462788715,24.603136037675522,26.535080184719074,28.132646876707707]
[]
[]
[null,null,"Asset return"]
[null,null,null,null,{"$f":"E13","v":"Mains and Inlets"},null,null,null,{"$f":"NPV(NompretaxWACC,L23:P23)","v":147.55705505263995},null,{"$f":"K115","v":{"$error":"#REF!"}},34.744411093870852,37.375454928640927,40.331288037089514,42.783298195626088,45.246805527806131]
[null,null,null,null,"Meters",null,null,null,18.753723311139595,null,{"$f":"K216","v":{"$error":"#REF!"}},4.1772236917343557,4.6426589366330644,5.1475062840183652,5.6008693069175699,6.046685691302371]
[null,null,null,null,"Telemetry",null,null,null,0.85239357800497728,null,{"$f":"K316","v":{"$error":"#REF!"}},9.5699116211903537E-2,0.17885434513282539,0.24752259338495042,0.31130309843351139,0.38013116028406257]
[null,null,null,null,"IT Systems",null,null,null,1.6509571580913389,null,{"$f":"K416","v":{"$error":"#REF!"}},0.1789110275624754,0.35614812221452413,0.5919885719753325,0.64083434342138756,0.55300431229987457]
[null,null,null,null,"Other Distribution Equipment",null,null,null,49.188605155295193,null,{"$f":"K516","v":{"$error":"#REF!"}},12.830807040953223,13.005391732483472,13.23487476240676,13.395946082839666,13.68721065720014]
[null,null,null,null,"Other Assets",null,null,null,1.028844794456391,null,{"$f":"K616","v":{"$error":"#REF!"}},0.29235244895540041,0.29157603433775919,0.28741722745310438,0.26203699247196022,0.23099735870114285]
[null,null,null,{"$f":"D19","v":"Total"},null,null,null,null,{"$f":"SUM(I23:I28)","v":219.03157904962745},null,{"$f":"SUM(K23:K28)","v":{"$error":"#REF!"}},52.319404419288212,55.850084099442576,59.840597476328028,62.99428801971019,66.144834707593731]
[]
[]
[null,null,"Closing written down value"]
[null,null,null,null,{"$f":"E23","v":"Mains and Inlets"},null,null,null,null,null,{"$f":"K147","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[null,null,null,null,{"$f":"E24","v":"Meters"},null,null,null,null,null,{"$f":"K247","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[null,null,null,null,"Telemetry",null,null,null,null,null,{"$f":"K347","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[null,null,null,null,"IT Systems",null,null,null,null,null,{"$f":"K447","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[null,null,null,null,"Other Distribution Equipment",null,null,null,null,null,{"$f":"K547","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[null,null,null,null,"Other Assets",null,null,null,null,null,{"$f":"K647","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[null,null,null,"Total",null,null,null,null,{"$f":"SUM(I33:I38)","v":0},null,{"$f":"SUM(K34:K38)","v":{"$error":"#REF!"}},{"$f":"SUM(L33:L38)","v":{"$error":"#REF!"}},{"$f":"SUM(M33:M38)","v":{"$error":"#REF!"}},{"$f":"SUM(N33:N38)","v":{"$error":"#REF!"}},{"$f":"SUM(O33:O38)","v":{"$error":"#REF!"}},{"$f":"SUM(P33:P38)","v":{"$error":"#REF!"}}]
[]
[]
[]
[]
[]
[]
[null,null,"Index"]
[null,null,null,"For initial capital base and 2005/06 capex",null,null,null,null,null,1,{"$f":"J47*(1+'General Inputs'!$B$6)","v":1.0257000000000001},{"$f":"K47*(1+'General Inputs'!$B$6)","v":1.0520604900000001},{"$f":"L47*(1+'General Inputs'!$B$6)","v":1.0790984445930001},{"$f":"M47*(1+'General Inputs'!$B$6)","v":1.1068312746190403},{"$f":"N47*(1+'General Inputs'!$B$6)","v":1.1352768383767498},{"$f":"O47*(1+'General Inputs'!$B$6)","v":1.1644534531230324}]
[null,null,null,"For capex from",null,null,"2005/06",null,null,null,1,{"$f":"K48*(1+'General Inputs'!$B$6)","v":1.0257000000000001},{"$f":"L48*(1+'General Inputs'!$B$6)","v":1.0520604900000001},{"$f":"M48*(1+'General Inputs'!$B$6)","v":1.0790984445930001},{"$f":"N48*(1+'General Inputs'!$B$6)","v":1.1068312746190403},{"$f":"O48*(1+'General Inputs'!$B$6)","v":1.1352768383767498}]
[null,null,null,null,null,null,"2006/07",null,null,null,null,1,{"$f":"L49*(1+'General Inputs'!$B$6)","v":1.0257000000000001},{"$f":"M49*(1+'General Inputs'!$B$6)","v":1.0520604900000001},{"$f":"N49*(1+'General Inputs'!$B$6)","v":1.0790984445930001},{"$f":"O49*(1+'General Inputs'!$B$6)","v":1.1068312746190403}]
[null,null,null,null,null,null,"2007/08",null,null,null,null,null,1,{"$f":"M50*(1+'General Inputs'!$B$6)","v":1.0257000000000001},{"$f":"N50*(1+'General Inputs'!$B$6)","v":1.0520604900000001},{"$f":"O50*(1+'General Inputs'!$B$6)","v":1.0790984445930001}]
[null,null,null,null,null,null,"2008/09",null,null,null,null,null,null,1,{"$f":"N51*(1+'General Inputs'!$B$6)","v":1.0257000000000001},{"$f":"O51*(1+'General Inputs'!$B$6)","v":1.0520604900000001}]
[null,null,null,null,null,null,"2009/10",null,null,null,null,null,null,null,1,{"$f":"O52*(1+'General Inputs'!$B$6)","v":1.0257000000000001}]
[null,null,null,null,null,null,"2010/11",null,null,null,null,null,null,null,null,1]
[]
[]
[]
[]
[]
[]
[null,"RAB Calculations"]
[null,null,{"$f":"\"Asset Class 1 - \"&E13","v":"Asset Class 1 - Mains and Inlets"}]
[]
[null,null,"Real calculations"]
[]
[null,null,null,"Real asset value"]
[]
[null,null,null,null,"Opening balance",null,null,null,null,null,{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"K75","v":{"$error":"#REF!"}},{"$f":"L75","v":{"$error":"#REF!"}},{"$f":"M75","v":{"$error":"#REF!"}},{"$f":"N75","v":{"$error":"#REF!"}},{"$f":"O75","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"Capex"]
[null,null,null,null,null,"First 50%",null,null,null,null,{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Remainder",null,null,null,null,{"$f":"K70","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[null,null,null,null,"Depreciation",null,null,null,null,null,{"$f":"K77","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[null,null,null,null,"Closing balance",null,null,null,null,null,{"$f":"-K73+K71+K70+K67","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[null,null,null,null,"Depreciation",null,null,null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}}]
[]
[]
[null,null,"Depreciation"]
[]
[null,null,null,"Total depreciation",null,null,null,null,null,{"$f":"J77","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,"Asset Returns"]
[]
[null,null,null,"Initial assets"]
[null,null,null,null,"Regulatory value of initial assets",null,null,null,null,null,{"$f":"IF($K82=0,0,$K67*'RAB Calculations'!K$47*('RAB Calculations'!K82/'RAB Calculations'!$K82))","v":{"$error":"#REF!"}},{"$f":"IF($K82=0,0,$K67*'RAB Calculations'!L$47*('RAB Calculations'!L82/'RAB Calculations'!$K82))","v":{"$error":"#REF!"}},{"$f":"IF($K82=0,0,$K67*'RAB Calculations'!M$47*('RAB Calculations'!M82/'RAB Calculations'!$K82))","v":{"$error":"#REF!"}},{"$f":"IF($K82=0,0,$K67*'RAB Calculations'!N$47*('RAB Calculations'!N82/'RAB Calculations'!$K82))","v":{"$error":"#REF!"}},{"$f":"IF($K82=0,0,$K67*'RAB Calculations'!O$47*('RAB Calculations'!O82/'RAB Calculations'!$K82))","v":{"$error":"#REF!"}},{"$f":"IF($K82=0,0,$K67*'RAB Calculations'!P$47*('RAB Calculations'!P82/'RAB Calculations'!$K82))","v":{"$error":"#REF!"}}]
[]
[]
[null,null,null,"Capex"]
[null,null,null,null,"Regulatory value of remainder of year1 capex",null,null,null,null,null,{"$f":"$K70*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"$K70*'RAB Calculations'!L$47","v":{"$error":"#REF!"}},{"$f":"$K70*'RAB Calculations'!M$47","v":{"$error":"#REF!"}},{"$f":"$K70*'RAB Calculations'!N$47","v":{"$error":"#REF!"}},{"$f":"$K70*'RAB Calculations'!O$47","v":{"$error":"#REF!"}},{"$f":"$K70*'RAB Calculations'!P$47","v":{"$error":"#REF!"}}]
[null,null,null,null,"cost base of 50% of capex"]
[null,null,null,null,null,"Year 1 capex",null,null,null,null,{"$f":"$K70*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"$K70*'RAB Calculations'!L$47","v":{"$error":"#REF!"}},{"$f":"$K70*'RAB Calculations'!M$47","v":{"$error":"#REF!"}},{"$f":"$K70*'RAB Calculations'!N$47","v":{"$error":"#REF!"}},{"$f":"$K70*'RAB Calculations'!O$47","v":{"$error":"#REF!"}},{"$f":"$K70*'RAB Calculations'!P$47","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 2 capex",null,null,null,null,null,{"$f":"$L70*'RAB Calculations'!L$48","v":{"$error":"#REF!"}},{"$f":"$L70*'RAB Calculations'!M$48","v":{"$error":"#REF!"}},{"$f":"$L70*'RAB Calculations'!N$48","v":{"$error":"#REF!"}},{"$f":"$L70*'RAB Calculations'!O$48","v":{"$error":"#REF!"}},{"$f":"$L70*'RAB Calculations'!P$48","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 3 capex",null,null,null,null,null,null,{"$f":"$M70*'RAB Calculations'!M$49","v":{"$error":"#REF!"}},{"$f":"$M70*'RAB Calculations'!N$49","v":{"$error":"#REF!"}},{"$f":"$M70*'RAB Calculations'!O$49","v":{"$error":"#REF!"}},{"$f":"$M70*'RAB Calculations'!P$49","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 4 capex",null,null,null,null,null,null,null,{"$f":"$N70*'RAB Calculations'!N$50","v":{"$error":"#REF!"}},{"$f":"$N70*'RAB Calculations'!O$50","v":{"$error":"#REF!"}},{"$f":"$N70*'RAB Calculations'!P$50","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 5 capex",null,null,null,null,null,null,null,null,{"$f":"$O70*'RAB Calculations'!O$51","v":{"$error":"#REF!"}},{"$f":"$O70*'RAB Calculations'!P$51","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 6 capex",null,null,null,null,null,null,null,null,null,{"$f":"$P70*'RAB Calculations'!P$52","v":{"$error":"#REF!"}}]
[null,null,null,"Total",null,null,null,null,null,null,{"$f":"SUM(K94:K99)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,null,"Asset returns"]
[null,null,null,null,"Regulatory value of initial assets for return purposes"]
[null,null,null,null,null,"cost base",null,null,null,null,{"$f":"$K67*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"$K67*'RAB Calculations'!L$47","v":{"$error":"#REF!"}},{"$f":"$K67*'RAB Calculations'!M$47","v":{"$error":"#REF!"}},{"$f":"$K67*'RAB Calculations'!N$47","v":{"$error":"#REF!"}},{"$f":"$K67*'RAB Calculations'!O$47","v":{"$error":"#REF!"}},{"$f":"$K67*'RAB Calculations'!P$47","v":{"$error":"#REF!"}}]
[null,null,null,null,"Value of Year 1 remainder assets for return purposes"]
[null,null,null,null,null,"cost base",null,null,null,null,{"$f":"$K92/'RAB Calculations'!$K$48*'RAB Calculations'!K$48","v":{"$error":"#REF!"}},{"$f":"$K92/'RAB Calculations'!$K$48*'RAB Calculations'!L$48","v":{"$error":"#REF!"}},{"$f":"$K92/'RAB Calculations'!$K$48*'RAB Calculations'!M$48","v":{"$error":"#REF!"}},{"$f":"$K92/'RAB Calculations'!$K$48*'RAB Calculations'!N$48","v":{"$error":"#REF!"}},{"$f":"$K92/'RAB Calculations'!$K$48*'RAB Calculations'!O$48","v":{"$error":"#REF!"}},{"$f":"$K92/'RAB Calculations'!$K$48*'RAB Calculations'!P$48","v":{"$error":"#REF!"}}]
[null,null,null,null,"WDV of 50% of capex"]
[null,null,null,null,null,"cost base",null,null,null,null,{"$f":"K94","v":{"$error":"#REF!"}},{"$f":"K109*(1+'General Inputs'!$B$6)+'RAB Calculations'!L95","v":{"$error":"#REF!"}},{"$f":"L109*(1+'General Inputs'!$B$6)+'RAB Calculations'!M96","v":{"$error":"#REF!"}},{"$f":"M109*(1+'General Inputs'!$B$6)+'RAB Calculations'!N97","v":{"$error":"#REF!"}},{"$f":"N109*(1+'General Inputs'!$B$6)+'RAB Calculations'!O98","v":{"$error":"#REF!"}},{"$f":"O109*(1+'General Inputs'!$B$6)+'RAB Calculations'!P99","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,null,"accumulated depreciation (to start of year)",null,null,null,null,{"$f":"J82*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"(K111+K82)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(L111+L82)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(M111+M82)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(N111+N82)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(O111+O82)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"Total WDV of 50% of capex",null,null,null,null,null,{"$f":"K105-K111+K109+(K109+((J109-(J109/'RAB Calculations'!$J$47*'RAB Calculations'!I47)))+K70)","v":{"$error":"#REF!"}},{"$f":"L105-L111+L109+(L109+((K109-(K109/'RAB Calculations'!$J$47*'RAB Calculations'!J$47)))+L70)","v":{"$error":"#REF!"}},{"$f":"M105-M111+M109+(M109+((L109-(L109/'RAB Calculations'!$J$47*'RAB Calculations'!K$47)))+M70)","v":{"$error":"#REF!"}},{"$f":"N105-N111+N109+(N109+((M109-(M109/'RAB Calculations'!$J$47*'RAB Calculations'!L$47)))+N70)","v":{"$error":"#REF!"}},{"$f":"O105-O111+O109+(O109+((N109-(N109/'RAB Calculations'!$J$47*'RAB Calculations'!M$47)))+O70)","v":{"$error":"#REF!"}},{"$f":"P105-P111+P109+(P109+((O109-(O109/'RAB Calculations'!$J$47*'RAB Calculations'!N$47)))+P70)","v":{"$error":"#REF!"}}]
[]
[null,null,null,"Total asset returns",null,null,null,null,null,null,{"$f":"(K105+K109-K111)*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(L105+L109-L111)*'General Inputs'!$B$7+((K109-($K109/'RAB Calculations'!$K$47*'RAB Calculations'!K$47)))*'General Inputs'!$B$7+L107*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(M105+M109-M111)*'General Inputs'!$B$7+((L109-($K109/'RAB Calculations'!$K$47*'RAB Calculations'!L$47)))*'General Inputs'!$B$7+M107*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(N105+N109-N111)*'General Inputs'!$B$7+((M109-($K109/'RAB Calculations'!$K$47*'RAB Calculations'!M$47)))*'General Inputs'!$B$7+N107*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(O105+O109-O111)*'General Inputs'!$B$7+((N109-($K109/'RAB Calculations'!$K$47*'RAB Calculations'!N$47)))*'General Inputs'!$B$7+O107*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(P105+P109-P111)*'General Inputs'!$B$7+((O109-($K109/'RAB Calculations'!$K$47*'RAB Calculations'!O$47)))*'General Inputs'!$B$7+P107*'General Inputs'!$B$7","v":{"$error":"#REF!"}}]
[]
[]
[]
[null,null,"Proof of Calculations"]
[]
[null,null,null,"Initial assets"]
[null,null,null,null,"Opening balance",null,null,null,null,null,null,{"$f":"K88-K82-K111","v":{"$error":"#REF!"}}]
[]
[null,null,null,"First 50% of capex"]
[null,null,null,null,"Spend",null,null,null,null,null,{"$f":"K70","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[null,null,null,null,"Carried forward balance",null,null,null,null,null,null,{"$f":"K94","v":{"$error":"#REF!"}}]
[null,null,null,null,"NPV at nominal WACC of",null,null,null,{"$f":"'General Inputs'!B8","v":0.10639999999999999},null,null,{"$f":"L126+L125+NPV(I127,M125:P125)","v":{"$error":"#REF!"}}]
[]
[null,null,null,"Remainder of capex"]
[null,null,null,null,"Spend",null,null,null,null,null,{"$f":"K71","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[null,null,null,null,"Carried forward balance",null,null,null,null,null,null,{"$f":"K92","v":{"$error":"#REF!"}}]
[null,null,null,null,"NPV at nominal WACC of",null,null,null,{"$f":"I127","v":0.10639999999999999},null,null,{"$f":"L131+NPV(I132,L130:P130)","v":{"$error":"#REF!"}}]
[null,null,null,null,null,null,null,null,null,null,null,{"$f":"L135-L127-L132","v":{"$error":"#REF!"}}]
[]
[null,null,null,"Total opening balance",null,null,null,null,null,null,null,{"$f":"L122+L127+L132","v":{"$error":"#REF!"}}]
[null,null,null,null,"Revenue stream"]
[null,null,null,null,null,"depreciation",null,null,null,null,null,{"$f":"L82","v":{"$error":"#REF!"}},{"$f":"M82","v":{"$error":"#REF!"}},{"$f":"N82","v":{"$error":"#REF!"}},{"$f":"O82","v":{"$error":"#REF!"}},{"$f":"P82","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Return on assets",null,null,null,null,null,{"$f":"L115","v":{"$error":"#REF!"}},{"$f":"M115","v":{"$error":"#REF!"}},{"$f":"N115","v":{"$error":"#REF!"}},{"$f":"O115","v":{"$error":"#REF!"}},{"$f":"P115","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Residual value"]
[null,null,null,null,null,"residual value of initial assets",null,null,null,null,null,null,null,null,null,{"$f":"(P105-P111-P137+P109+P107+P130)+(O109-(K109/'RAB Calculations'!K47*'RAB Calculations'!O47))","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"residual value of remainder of capex"]
[null,null,null,null,"Total",null,null,null,null,null,null,{"$f":"L137+L138+L140","v":{"$error":"#REF!"}},{"$f":"M137+M138+M140","v":{"$error":"#REF!"}},{"$f":"N137+N138+N140","v":{"$error":"#REF!"}},{"$f":"O137+O138+O140","v":{"$error":"#REF!"}},{"$f":"P137+P138+P140","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"NPV at nominal WACC of",null,null,null,{"$f":"I132","v":0.10639999999999999},null,null,{"$f":"NPV(I144,L142:P142)","v":{"$error":"#REF!"}},{"$f":"L135-L144","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Check",null,null,null,null,null,{"$f":"IF(ROUND(L135-L144,5)=0,\"ok\",\"problem\")","v":{"$error":"#REF!"}}]
[]
[null,null,null,"Closing written down value",null,null,null,null,null,null,{"$f":"K105-K111-K82+K100+K109","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"RAB Calculations"]
[null,null,{"$f":"\"Asset Class 2 - \"&E14","v":"Asset Class 2 - Meters"}]
[]
[null,null,"Real calculations"]
[]
[null,null,null,"Real asset value"]
[]
[null,null,null,null,"Opening balance",null,null,null,null,null,{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"K176","v":{"$error":"#REF!"}},{"$f":"L176","v":{"$error":"#REF!"}},{"$f":"M176","v":{"$error":"#REF!"}},{"$f":"N176","v":{"$error":"#REF!"}},{"$f":"O176","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"Capex"]
[null,null,null,null,null,"First 50%",null,null,null,null,{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Remainder",null,null,null,null,{"$f":"K171","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[null,null,null,null,"Depreciation",null,null,null,null,null,{"$f":"K178","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[null,null,null,null,"Closing balance",null,null,null,null,null,{"$f":"-K174+K172+K171+K168","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[null,null,null,null,"Depreciation",null,null,null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}}]
[]
[]
[null,null,"Depreciation"]
[]
[null,null,null,"Total depreciation",null,null,null,null,null,{"$f":"J178","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,"Asset Returns"]
[]
[null,null,null,"Initial assets"]
[null,null,null,null,"Regulatory value of initial assets",null,null,null,null,null,{"$f":"IF($K183=0,0,$K168*'RAB Calculations'!K$47*('RAB Calculations'!K183/'RAB Calculations'!$K183))","v":{"$error":"#REF!"}},{"$f":"IF($K183=0,0,$K168*'RAB Calculations'!L$47*('RAB Calculations'!L183/'RAB Calculations'!$K183))","v":{"$error":"#REF!"}},{"$f":"IF($K183=0,0,$K168*'RAB Calculations'!M$47*('RAB Calculations'!M183/'RAB Calculations'!$K183))","v":{"$error":"#REF!"}},{"$f":"IF($K183=0,0,$K168*'RAB Calculations'!N$47*('RAB Calculations'!N183/'RAB Calculations'!$K183))","v":{"$error":"#REF!"}},{"$f":"IF($K183=0,0,$K168*'RAB Calculations'!O$47*('RAB Calculations'!O183/'RAB Calculations'!$K183))","v":{"$error":"#REF!"}},{"$f":"IF($K183=0,0,$K168*'RAB Calculations'!P$47*('RAB Calculations'!P183/'RAB Calculations'!$K183))","v":{"$error":"#REF!"}}]
[]
[]
[null,null,null,"Capex"]
[null,null,null,null,"Regulatory value of remainder of year1 capex",null,null,null,null,null,{"$f":"$K171*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"$K171*'RAB Calculations'!L$47","v":{"$error":"#REF!"}},{"$f":"$K171*'RAB Calculations'!M$47","v":{"$error":"#REF!"}},{"$f":"$K171*'RAB Calculations'!N$47","v":{"$error":"#REF!"}},{"$f":"$K171*'RAB Calculations'!O$47","v":{"$error":"#REF!"}},{"$f":"$K171*'RAB Calculations'!P$47","v":{"$error":"#REF!"}}]
[null,null,null,null,"cost base of 50% of capex"]
[null,null,null,null,null,"Year 1 capex",null,null,null,null,{"$f":"$K171*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"$K171*'RAB Calculations'!L$47","v":{"$error":"#REF!"}},{"$f":"$K171*'RAB Calculations'!M$47","v":{"$error":"#REF!"}},{"$f":"$K171*'RAB Calculations'!N$47","v":{"$error":"#REF!"}},{"$f":"$K171*'RAB Calculations'!O$47","v":{"$error":"#REF!"}},{"$f":"$K171*'RAB Calculations'!P$47","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 2 capex",null,null,null,null,null,{"$f":"$L171*'RAB Calculations'!L$48","v":{"$error":"#REF!"}},{"$f":"$L171*'RAB Calculations'!M$48","v":{"$error":"#REF!"}},{"$f":"$L171*'RAB Calculations'!N$48","v":{"$error":"#REF!"}},{"$f":"$L171*'RAB Calculations'!O$48","v":{"$error":"#REF!"}},{"$f":"$L171*'RAB Calculations'!P$48","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 3 capex",null,null,null,null,null,null,{"$f":"$M171*'RAB Calculations'!M$49","v":{"$error":"#REF!"}},{"$f":"$M171*'RAB Calculations'!N$49","v":{"$error":"#REF!"}},{"$f":"$M171*'RAB Calculations'!O$49","v":{"$error":"#REF!"}},{"$f":"$M171*'RAB Calculations'!P$49","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 4 capex",null,null,null,null,null,null,null,{"$f":"$N171*'RAB Calculations'!N$50","v":{"$error":"#REF!"}},{"$f":"$N171*'RAB Calculations'!O$50","v":{"$error":"#REF!"}},{"$f":"$N171*'RAB Calculations'!P$50","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 5 capex",null,null,null,null,null,null,null,null,{"$f":"$O171*'RAB Calculations'!O$51","v":{"$error":"#REF!"}},{"$f":"$O171*'RAB Calculations'!P$51","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 6 capex",null,null,null,null,null,null,null,null,null,{"$f":"$P171*'RAB Calculations'!P$52","v":{"$error":"#REF!"}}]
[null,null,null,"Total",null,null,null,null,null,null,{"$f":"SUM(K195:K200)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,null,"Asset returns"]
[null,null,null,null,"Regulatory value of initial assets for return purposes"]
[null,null,null,null,null,"cost base",null,null,null,null,{"$f":"$K168*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"$K168*'RAB Calculations'!L$47","v":{"$error":"#REF!"}},{"$f":"$K168*'RAB Calculations'!M$47","v":{"$error":"#REF!"}},{"$f":"$K168*'RAB Calculations'!N$47","v":{"$error":"#REF!"}},{"$f":"$K168*'RAB Calculations'!O$47","v":{"$error":"#REF!"}},{"$f":"$K168*'RAB Calculations'!P$47","v":{"$error":"#REF!"}}]
[null,null,null,null,"Value of Year 1 remainder assets for return purposes"]
[null,null,null,null,null,"cost base",null,null,null,null,{"$f":"$K193/'RAB Calculations'!$K$48*'RAB Calculations'!K$48","v":{"$error":"#REF!"}},{"$f":"$K193/'RAB Calculations'!$K$48*'RAB Calculations'!L$48","v":{"$error":"#REF!"}},{"$f":"$K193/'RAB Calculations'!$K$48*'RAB Calculations'!M$48","v":{"$error":"#REF!"}},{"$f":"$K193/'RAB Calculations'!$K$48*'RAB Calculations'!N$48","v":{"$error":"#REF!"}},{"$f":"$K193/'RAB Calculations'!$K$48*'RAB Calculations'!O$48","v":{"$error":"#REF!"}},{"$f":"$K193/'RAB Calculations'!$K$48*'RAB Calculations'!P$48","v":{"$error":"#REF!"}}]
[null,null,null,null,"WDV of 50% of capex"]
[null,null,null,null,null,"cost base",null,null,null,null,{"$f":"K195","v":{"$error":"#REF!"}},{"$f":"K210*(1+'General Inputs'!$B$6)+'RAB Calculations'!L196","v":{"$error":"#REF!"}},{"$f":"L210*(1+'General Inputs'!$B$6)+'RAB Calculations'!M197","v":{"$error":"#REF!"}},{"$f":"M210*(1+'General Inputs'!$B$6)+'RAB Calculations'!N198","v":{"$error":"#REF!"}},{"$f":"N210*(1+'General Inputs'!$B$6)+'RAB Calculations'!O199","v":{"$error":"#REF!"}},{"$f":"O210*(1+'General Inputs'!$B$6)+'RAB Calculations'!P200","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,null,"accumulated depreciation (to start of year)",null,null,null,null,{"$f":"J183*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"(K212+K183)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(L212+L183)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(M212+M183)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(N212+N183)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(O212+O183)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"Total WDV of 50% of capex",null,null,null,null,null,{"$f":"K206-K212+K210+(K210+((J210-(J210/'RAB Calculations'!$J$47*'RAB Calculations'!$I$47)))+K171)","v":{"$error":"#REF!"}},{"$f":"L206-L212+L210+(L210+((K210-(K210/'RAB Calculations'!$J$47*'RAB Calculations'!J$47)))+L171)","v":{"$error":"#REF!"}},{"$f":"M206-M212+M210+(M210+((L210-(L210/'RAB Calculations'!$J$47*'RAB Calculations'!K$47)))+M171)","v":{"$error":"#REF!"}},{"$f":"N206-N212+N210+(N210+((M210-(M210/'RAB Calculations'!$J$47*'RAB Calculations'!L$47)))+N171)","v":{"$error":"#REF!"}},{"$f":"O206-O212+O210+(O210+((N210-(N210/'RAB Calculations'!$J$47*'RAB Calculations'!M$47)))+O171)","v":{"$error":"#REF!"}},{"$f":"P206-P212+P210+(P210+((O210-(O210/'RAB Calculations'!$J$47*'RAB Calculations'!N$47)))+P171)","v":{"$error":"#REF!"}}]
[]
[null,null,null,"Total asset returns",null,null,null,null,null,null,{"$f":"(K206+K210-K212)*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(L206+L210-L212)*'General Inputs'!$B$7+((K210-($K210/'RAB Calculations'!$K$47*'RAB Calculations'!K$47)))*'General Inputs'!$B$7+L208*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(M206+M210-M212)*'General Inputs'!$B$7+((L210-($K210/'RAB Calculations'!$K$47*'RAB Calculations'!L$47)))*'General Inputs'!$B$7+M208*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(N206+N210-N212)*'General Inputs'!$B$7+((M210-($K210/'RAB Calculations'!$K$47*'RAB Calculations'!M$47)))*'General Inputs'!$B$7+N208*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(O206+O210-O212)*'General Inputs'!$B$7+((N210-($K210/'RAB Calculations'!$K$47*'RAB Calculations'!N$47)))*'General Inputs'!$B$7+O208*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(P206+P210-P212)*'General Inputs'!$B$7+((O210-($K210/'RAB Calculations'!$K$47*'RAB Calculations'!O$47)))*'General Inputs'!$B$7+P208*'General Inputs'!$B$7","v":{"$error":"#REF!"}}]
[]
[]
[null,null,"Proof of Calculations"]
[]
[null,null,null,"Initial assets"]
[null,null,null,null,"Opening balance",null,null,null,null,null,null,{"$f":"K189-K183-K212","v":{"$error":"#REF!"}}]
[]
[null,null,null,"First 50% of capex"]
[null,null,null,null,"Spend",null,null,null,null,null,{"$f":"K171","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[null,null,null,null,"Carried forward balance",null,null,null,null,null,null,{"$f":"K195","v":{"$error":"#REF!"}}]
[null,null,null,null,"NPV at nominal WACC of",null,null,null,{"$f":"NompretaxWACC","v":0.10639999999999999},null,null,{"$f":"L226+L225+NPV(I227,M225:P225)","v":{"$error":"#REF!"}}]
[]
[null,null,null,"Remainder of capex"]
[null,null,null,null,"Spend",null,null,null,null,null,{"$f":"K172","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[null,null,null,null,"Carried forward balance",null,null,null,null,null,null,{"$f":"K193","v":{"$error":"#REF!"}}]
[null,null,null,null,"NPV at nominal WACC of",null,null,null,{"$f":"I227","v":0.10639999999999999},null,null,{"$f":"L231+NPV(I232,L230:P230)","v":{"$error":"#REF!"}}]
[null,null,null,null,null,null,null,null,null,null,null,{"$f":"L235-L227-L232","v":{"$error":"#REF!"}}]
[]
[null,null,null,"Total opening balance",null,null,null,null,null,null,null,{"$f":"L222+L227+L232","v":{"$error":"#REF!"}}]
[null,null,null,null,"Revenue stream"]
[null,null,null,null,null,"depreciation",null,null,null,null,null,{"$f":"L183","v":{"$error":"#REF!"}},{"$f":"M183","v":{"$error":"#REF!"}},{"$f":"N183","v":{"$error":"#REF!"}},{"$f":"O183","v":{"$error":"#REF!"}},{"$f":"P183","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Return on assets",null,null,null,null,null,{"$f":"L216","v":{"$error":"#REF!"}},{"$f":"M216","v":{"$error":"#REF!"}},{"$f":"N216","v":{"$error":"#REF!"}},{"$f":"O216","v":{"$error":"#REF!"}},{"$f":"P216","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Residual value"]
[null,null,null,null,null,"residual value of initial assets",null,null,null,null,null,null,null,null,null,{"$f":"(P206-P212-P237+P210)+P208+P230+(O210-(K210/'RAB Calculations'!K47*'RAB Calculations'!O47))","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"residual value of remainder of capex"]
[null,null,null,null,"Total",null,null,null,null,null,null,{"$f":"L237+L238+L240","v":{"$error":"#REF!"}},{"$f":"M237+M238+M240","v":{"$error":"#REF!"}},{"$f":"N237+N238+N240","v":{"$error":"#REF!"}},{"$f":"O237+O238+O240","v":{"$error":"#REF!"}},{"$f":"P237+P238+P240","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"NPV at nominal WACC of",null,null,null,{"$f":"I232","v":0.10639999999999999},null,null,{"$f":"NPV(I244,L242:P242)","v":{"$error":"#REF!"}},{"$f":"L235-L244","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Check",null,null,null,null,null,{"$f":"IF(ROUND(L235-L244,5)=0,\"ok\",\"problem\")","v":{"$error":"#REF!"}}]
[]
[null,null,null,"Closing written down value",null,null,null,null,null,null,{"$f":"K206-K212-K183+K201+K210","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"RAB Calculations"]
[null,null,{"$f":"\"Asset Class 3 - \"&E15","v":"Asset Class 3 - Telemetry"}]
[]
[null,null,"Real calculations"]
[]
[null,null,null,"Real asset value"]
[]
[null,null,null,null,"Opening balance",null,null,null,null,null,{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"K276","v":{"$error":"#REF!"}},{"$f":"L276","v":{"$error":"#REF!"}},{"$f":"M276","v":{"$error":"#REF!"}},{"$f":"N276","v":{"$error":"#REF!"}},{"$f":"O276","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"Capex"]
[null,null,null,null,null,"First 50%",null,null,null,null,{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Remainder",null,null,null,null,{"$f":"K271","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[null,null,null,null,"Depreciation",null,null,null,null,null,{"$f":"K278","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[null,null,null,null,"Closing balance",null,null,null,null,null,{"$f":"-K274+K272+K271+K268","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[null,null,null,null,"Depreciation",null,null,null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}}]
[]
[]
[null,null,"Depreciation"]
[]
[null,null,null,"Total depreciation",null,null,null,null,null,{"$f":"J278","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,"Asset Returns"]
[]
[null,null,null,"Initial assets"]
[null,null,null,null,"Regulatory value of initial assets",null,null,null,null,null,{"$f":"IF($K283=0,0,$K268*'RAB Calculations'!K$47*('RAB Calculations'!K283/'RAB Calculations'!$K283))","v":{"$error":"#REF!"}},{"$f":"IF($K283=0,0,$K268*'RAB Calculations'!L$47*('RAB Calculations'!L283/'RAB Calculations'!$K283))","v":{"$error":"#REF!"}},{"$f":"IF($K283=0,0,$K268*'RAB Calculations'!M$47*('RAB Calculations'!M283/'RAB Calculations'!$K283))","v":{"$error":"#REF!"}},{"$f":"IF($K283=0,0,$K268*'RAB Calculations'!N$47*('RAB Calculations'!N283/'RAB Calculations'!$K283))","v":{"$error":"#REF!"}},{"$f":"IF($K283=0,0,$K268*'RAB Calculations'!O$47*('RAB Calculations'!O283/'RAB Calculations'!$K283))","v":{"$error":"#REF!"}},{"$f":"IF($K283=0,0,$K268*'RAB Calculations'!P$47*('RAB Calculations'!P283/'RAB Calculations'!$K283))","v":{"$error":"#REF!"}}]
[]
[]
[null,null,null,"Capex"]
[null,null,null,null,"Regulatory value of remainder of year1 capex",null,null,null,null,null,{"$f":"$K271*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"$K271*'RAB Calculations'!L$47","v":{"$error":"#REF!"}},{"$f":"$K271*'RAB Calculations'!M$47","v":{"$error":"#REF!"}},{"$f":"$K271*'RAB Calculations'!N$47","v":{"$error":"#REF!"}},{"$f":"$K271*'RAB Calculations'!O$47","v":{"$error":"#REF!"}},{"$f":"$K271*'RAB Calculations'!P$47","v":{"$error":"#REF!"}}]
[null,null,null,null,"cost base of 50% of capex"]
[null,null,null,null,null,"Year 1 capex",null,null,null,null,{"$f":"$K271*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"$K271*'RAB Calculations'!L$47","v":{"$error":"#REF!"}},{"$f":"$K271*'RAB Calculations'!M$47","v":{"$error":"#REF!"}},{"$f":"$K271*'RAB Calculations'!N$47","v":{"$error":"#REF!"}},{"$f":"$K271*'RAB Calculations'!O$47","v":{"$error":"#REF!"}},{"$f":"$K271*'RAB Calculations'!P$47","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 2 capex",null,null,null,null,null,{"$f":"$L271*'RAB Calculations'!L$48","v":{"$error":"#REF!"}},{"$f":"$L271*'RAB Calculations'!M$48","v":{"$error":"#REF!"}},{"$f":"$L271*'RAB Calculations'!N$48","v":{"$error":"#REF!"}},{"$f":"$L271*'RAB Calculations'!O$48","v":{"$error":"#REF!"}},{"$f":"$L271*'RAB Calculations'!P$48","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 3 capex",null,null,null,null,null,null,{"$f":"$M271*'RAB Calculations'!M$49","v":{"$error":"#REF!"}},{"$f":"$M271*'RAB Calculations'!N$49","v":{"$error":"#REF!"}},{"$f":"$M271*'RAB Calculations'!O$49","v":{"$error":"#REF!"}},{"$f":"$M271*'RAB Calculations'!P$49","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 4 capex",null,null,null,null,null,null,null,{"$f":"$N271*'RAB Calculations'!N$50","v":{"$error":"#REF!"}},{"$f":"$N271*'RAB Calculations'!O$50","v":{"$error":"#REF!"}},{"$f":"$N271*'RAB Calculations'!P$50","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 5 capex",null,null,null,null,null,null,null,null,{"$f":"$O271*'RAB Calculations'!O$51","v":{"$error":"#REF!"}},{"$f":"$O271*'RAB Calculations'!P$51","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 6 capex",null,null,null,null,null,null,null,null,null,{"$f":"$P271*'RAB Calculations'!P$52","v":{"$error":"#REF!"}}]
[null,null,null,"Total",null,null,null,null,null,null,{"$f":"SUM(K295:K300)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,null,"Asset returns"]
[null,null,null,null,"Regulatory value of initial assets for return purposes"]
[null,null,null,null,null,"cost base",null,null,null,null,{"$f":"$K268*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"$K268*'RAB Calculations'!L$47","v":{"$error":"#REF!"}},{"$f":"$K268*'RAB Calculations'!M$47","v":{"$error":"#REF!"}},{"$f":"$K268*'RAB Calculations'!N$47","v":{"$error":"#REF!"}},{"$f":"$K268*'RAB Calculations'!O$47","v":{"$error":"#REF!"}},{"$f":"$K268*'RAB Calculations'!P$47","v":{"$error":"#REF!"}}]
[null,null,null,null,"Value of Year 1 remainder assets for return purposes"]
[null,null,null,null,null,"cost base",null,null,null,null,{"$f":"$K293/'RAB Calculations'!$K$48*'RAB Calculations'!K$48","v":{"$error":"#REF!"}},{"$f":"$K293/'RAB Calculations'!$K$48*'RAB Calculations'!L$48","v":{"$error":"#REF!"}},{"$f":"$K293/'RAB Calculations'!$K$48*'RAB Calculations'!M$48","v":{"$error":"#REF!"}},{"$f":"$K293/'RAB Calculations'!$K$48*'RAB Calculations'!N$48","v":{"$error":"#REF!"}},{"$f":"$K293/'RAB Calculations'!$K$48*'RAB Calculations'!O$48","v":{"$error":"#REF!"}},{"$f":"$K293/'RAB Calculations'!$K$48*'RAB Calculations'!P$48","v":{"$error":"#REF!"}}]
[null,null,null,null,"WDV of 50% of capex"]
[null,null,null,null,null,"cost base",null,null,null,null,{"$f":"K295","v":{"$error":"#REF!"}},{"$f":"K310*(1+'General Inputs'!$B$6)+'RAB Calculations'!L296","v":{"$error":"#REF!"}},{"$f":"L310*(1+'General Inputs'!$B$6)+'RAB Calculations'!M297","v":{"$error":"#REF!"}},{"$f":"M310*(1+'General Inputs'!$B$6)+'RAB Calculations'!N298","v":{"$error":"#REF!"}},{"$f":"N310*(1+'General Inputs'!$B$6)+'RAB Calculations'!O299","v":{"$error":"#REF!"}},{"$f":"O310*(1+'General Inputs'!$B$6)+'RAB Calculations'!P300","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,null,"accumulated depreciation (to start of year)",null,null,null,null,{"$f":"J283*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"(K312+K283)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(L312+L283)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(M312+M283)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(N312+N283)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(O312+O283)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"Total WDV of 50% of capex",null,null,null,null,null,{"$f":"K306-K312+K310+(K310+((J310-(J310/'RAB Calculations'!$J$47*'RAB Calculations'!I$47)))+K271)","v":{"$error":"#REF!"}},{"$f":"L306-L312+L310+(L310+((K310-(K310/'RAB Calculations'!$J$47*'RAB Calculations'!J$47)))+L271)","v":{"$error":"#REF!"}},{"$f":"M306-M312+M310+(M310+((L310-(L310/'RAB Calculations'!$J$47*'RAB Calculations'!K$47)))+M271)","v":{"$error":"#REF!"}},{"$f":"N306-N312+N310+(N310+((M310-(M310/'RAB Calculations'!$J$47*'RAB Calculations'!L$47)))+N271)","v":{"$error":"#REF!"}},{"$f":"O306-O312+O310+(O310+((N310-(N310/'RAB Calculations'!$J$47*'RAB Calculations'!M$47)))+O271)","v":{"$error":"#REF!"}},{"$f":"P306-P312+P310+(P310+((O310-(O310/'RAB Calculations'!$J$47*'RAB Calculations'!N$47)))+P271)","v":{"$error":"#REF!"}}]
[]
[null,null,null,"Total asset returns",null,null,null,null,null,null,{"$f":"(K306+K310-K312)*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(L306+L310-L312)*'General Inputs'!$B$7+((K310-($K310/'RAB Calculations'!$K$47*'RAB Calculations'!K$47)))*'General Inputs'!$B$7+L308*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(M306+M310-M312)*'General Inputs'!$B$7+((L310-($K310/'RAB Calculations'!$K$47*'RAB Calculations'!L$47)))*'General Inputs'!$B$7+M308*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(N306+N310-N312)*'General Inputs'!$B$7+((M310-($K310/'RAB Calculations'!$K$47*'RAB Calculations'!M$47)))*'General Inputs'!$B$7+N308*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(O306+O310-O312)*'General Inputs'!$B$7+((N310-($K310/'RAB Calculations'!$K$47*'RAB Calculations'!N$47)))*'General Inputs'!$B$7+O308*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(P306+P310-P312)*'General Inputs'!$B$7+((O310-($K310/'RAB Calculations'!$K$47*'RAB Calculations'!O$47)))*'General Inputs'!$B$7+P308*'General Inputs'!$B$7","v":{"$error":"#REF!"}}]
[]
[]
[null,null,"Proof of Calculations"]
[]
[null,null,null,"Initial assets"]
[null,null,null,null,"Opening balance",null,null,null,null,null,null,{"$f":"K289-K283-K312","v":{"$error":"#REF!"}}]
[]
[null,null,null,"First 50% of capex"]
[null,null,null,null,"Spend",null,null,null,null,null,{"$f":"K271","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[null,null,null,null,"Carried forward balance",null,null,null,null,null,null,{"$f":"K295","v":{"$error":"#REF!"}}]
[null,null,null,null,"NPV at nominal WACC of",null,null,null,{"$f":"NompretaxWACC","v":0.10639999999999999},null,null,{"$f":"L326+L325+NPV(I327,M325:P325)","v":{"$error":"#REF!"}}]
[]
[null,null,null,"Remainder of capex"]
[null,null,null,null,"Spend",null,null,null,null,null,{"$f":"K272","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[null,null,null,null,"Carried forward balance",null,null,null,null,null,null,{"$f":"K293","v":{"$error":"#REF!"}}]
[null,null,null,null,"NPV at nominal WACC of",null,null,null,{"$f":"I327","v":0.10639999999999999},null,null,{"$f":"L331+NPV(I332,L330:P330)","v":{"$error":"#REF!"}}]
[]
[]
[null,null,null,"Total opening balance",null,null,null,null,null,null,null,{"$f":"L322+L327+L332","v":{"$error":"#REF!"}}]
[null,null,null,null,"Revenue stream"]
[null,null,null,null,null,"depreciation",null,null,null,null,null,{"$f":"L283","v":{"$error":"#REF!"}},{"$f":"M283","v":{"$error":"#REF!"}},{"$f":"N283","v":{"$error":"#REF!"}},{"$f":"O283","v":{"$error":"#REF!"}},{"$f":"P283","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Return on assets",null,null,null,null,null,{"$f":"L316","v":{"$error":"#REF!"}},{"$f":"M316","v":{"$error":"#REF!"}},{"$f":"N316","v":{"$error":"#REF!"}},{"$f":"O316","v":{"$error":"#REF!"}},{"$f":"P316","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Residual value"]
[null,null,null,null,null,"residual value of initial assets",null,null,null,null,null,null,null,null,null,{"$f":"(P306-P312-P337+P310+P308+P330)+(O310-(K310/'RAB Calculations'!K47*'RAB Calculations'!O47))","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"residual value of remainder of capex"]
[null,null,null,null,"Total",null,null,null,null,null,null,{"$f":"L337+L338+L340","v":{"$error":"#REF!"}},{"$f":"M337+M338+M340","v":{"$error":"#REF!"}},{"$f":"N337+N338+N340","v":{"$error":"#REF!"}},{"$f":"O337+O338+O340","v":{"$error":"#REF!"}},{"$f":"P337+P338+P340","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"NPV at nominal WACC of",null,null,null,{"$f":"I332","v":0.10639999999999999},null,null,{"$f":"NPV(I344,L342:P342)","v":{"$error":"#REF!"}},{"$f":"L335-L344","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Check",null,null,null,null,null,{"$f":"IF(ROUND(L335-L344,5)=0,\"ok\",\"problem\")","v":{"$error":"#REF!"}}]
[]
[null,null,null,"Closing written down value",null,null,null,null,null,null,{"$f":"K306-K312-K283+K301+K310","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"RAB Calculations"]
[null,null,{"$f":"\"Asset Class 4 - \"&E16","v":"Asset Class 4 - IT Systems"}]
[]
[null,null,"Real calculations"]
[]
[null,null,null,"Real asset value"]
[]
[null,null,null,null,"Opening balance",null,null,null,null,null,{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"K376","v":{"$error":"#REF!"}},{"$f":"L376","v":{"$error":"#REF!"}},{"$f":"M376","v":{"$error":"#REF!"}},{"$f":"N376","v":{"$error":"#REF!"}},{"$f":"O376","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"Capex"]
[null,null,null,null,null,"First 50%",null,null,null,null,{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Remainder",null,null,null,null,{"$f":"K371","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[null,null,null,null,"Depreciation",null,null,null,null,null,{"$f":"K378","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[null,null,null,null,"Closing balance",null,null,null,null,null,{"$f":"-K374+K372+K371+K368","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[null,null,null,null,"Depreciation",null,null,null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}}]
[]
[]
[null,null,"Depreciation"]
[]
[null,null,null,"Total depreciation",null,null,null,null,null,{"$f":"J378","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,"Asset Returns"]
[]
[null,null,null,"Initial assets"]
[null,null,null,null,"Regulatory value of initial assets",null,null,null,null,null,{"$f":"IF($K383=0,0,$K368*'RAB Calculations'!K$47*('RAB Calculations'!K383/'RAB Calculations'!$K383))","v":{"$error":"#REF!"}},{"$f":"IF($K383=0,0,$K368*'RAB Calculations'!L$47*('RAB Calculations'!L383/'RAB Calculations'!$K383))","v":{"$error":"#REF!"}},{"$f":"IF($K383=0,0,$K368*'RAB Calculations'!M$47*('RAB Calculations'!M383/'RAB Calculations'!$K383))","v":{"$error":"#REF!"}},{"$f":"IF($K383=0,0,$K368*'RAB Calculations'!N$47*('RAB Calculations'!N383/'RAB Calculations'!$K383))","v":{"$error":"#REF!"}},{"$f":"IF($K383=0,0,$K368*'RAB Calculations'!O$47*('RAB Calculations'!O383/'RAB Calculations'!$K383))","v":{"$error":"#REF!"}},{"$f":"IF($K383=0,0,$K368*'RAB Calculations'!P$47*('RAB Calculations'!P383/'RAB Calculations'!$K383))","v":{"$error":"#REF!"}}]
[]
[]
[null,null,null,"Capex"]
[null,null,null,null,"Regulatory value of remainder of year1 capex",null,null,null,null,null,{"$f":"$K371*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"$K371*'RAB Calculations'!L$47","v":{"$error":"#REF!"}},{"$f":"$K371*'RAB Calculations'!M$47","v":{"$error":"#REF!"}},{"$f":"$K371*'RAB Calculations'!N$47","v":{"$error":"#REF!"}},{"$f":"$K371*'RAB Calculations'!O$47","v":{"$error":"#REF!"}},{"$f":"$K371*'RAB Calculations'!P$47","v":{"$error":"#REF!"}}]
[null,null,null,null,"cost base of 50% of capex"]
[null,null,null,null,null,"Year 1 capex",null,null,null,null,{"$f":"$K371*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"$K371*'RAB Calculations'!L$47","v":{"$error":"#REF!"}},{"$f":"$K371*'RAB Calculations'!M$47","v":{"$error":"#REF!"}},{"$f":"$K371*'RAB Calculations'!N$47","v":{"$error":"#REF!"}},{"$f":"$K371*'RAB Calculations'!O$47","v":{"$error":"#REF!"}},{"$f":"$K371*'RAB Calculations'!P$47","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 2 capex",null,null,null,null,null,{"$f":"$L371*'RAB Calculations'!L$48","v":{"$error":"#REF!"}},{"$f":"$L371*'RAB Calculations'!M$48","v":{"$error":"#REF!"}},{"$f":"$L371*'RAB Calculations'!N$48","v":{"$error":"#REF!"}},{"$f":"$L371*'RAB Calculations'!O$48","v":{"$error":"#REF!"}},{"$f":"$L371*'RAB Calculations'!P$48","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 3 capex",null,null,null,null,null,null,{"$f":"$M371*'RAB Calculations'!M$49","v":{"$error":"#REF!"}},{"$f":"$M371*'RAB Calculations'!N$49","v":{"$error":"#REF!"}},{"$f":"$M371*'RAB Calculations'!O$49","v":{"$error":"#REF!"}},{"$f":"$M371*'RAB Calculations'!P$49","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 4 capex",null,null,null,null,null,null,null,{"$f":"$N371*'RAB Calculations'!N$50","v":{"$error":"#REF!"}},{"$f":"$N371*'RAB Calculations'!O$50","v":{"$error":"#REF!"}},{"$f":"$N371*'RAB Calculations'!P$50","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 5 capex",null,null,null,null,null,null,null,null,{"$f":"$O371*'RAB Calculations'!O$51","v":{"$error":"#REF!"}},{"$f":"$O371*'RAB Calculations'!P$51","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 6 capex",null,null,null,null,null,null,null,null,null,{"$f":"$P371*'RAB Calculations'!P$52","v":{"$error":"#REF!"}}]
[null,null,null,"Total",null,null,null,null,null,null,{"$f":"SUM(K395:K400)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,null,"Asset returns"]
[null,null,null,null,"Regulatory value of initial assets for return purposes"]
[null,null,null,null,null,"cost base",null,null,null,null,{"$f":"$K368*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"$K368*'RAB Calculations'!L$47","v":{"$error":"#REF!"}},{"$f":"$K368*'RAB Calculations'!M$47","v":{"$error":"#REF!"}},{"$f":"$K368*'RAB Calculations'!N$47","v":{"$error":"#REF!"}},{"$f":"$K368*'RAB Calculations'!O$47","v":{"$error":"#REF!"}},{"$f":"$K368*'RAB Calculations'!P$47","v":{"$error":"#REF!"}}]
[null,null,null,null,"Value of Year 1 remainder assets for return purposes"]
[null,null,null,null,null,"cost base",null,null,null,null,{"$f":"$K393/'RAB Calculations'!$K$48*'RAB Calculations'!K$48","v":{"$error":"#REF!"}},{"$f":"$K393/'RAB Calculations'!$K$48*'RAB Calculations'!L$48","v":{"$error":"#REF!"}},{"$f":"$K393/'RAB Calculations'!$K$48*'RAB Calculations'!M$48","v":{"$error":"#REF!"}},{"$f":"$K393/'RAB Calculations'!$K$48*'RAB Calculations'!N$48","v":{"$error":"#REF!"}},{"$f":"$K393/'RAB Calculations'!$K$48*'RAB Calculations'!O$48","v":{"$error":"#REF!"}},{"$f":"$K393/'RAB Calculations'!$K$48*'RAB Calculations'!P$48","v":{"$error":"#REF!"}}]
[null,null,null,null,"WDV of 50% of capex"]
[null,null,null,null,null,"cost base",null,null,null,null,{"$f":"K395","v":{"$error":"#REF!"}},{"$f":"K410*(1+'General Inputs'!$B$6)+'RAB Calculations'!L396","v":{"$error":"#REF!"}},{"$f":"L410*(1+'General Inputs'!$B$6)+'RAB Calculations'!M397","v":{"$error":"#REF!"}},{"$f":"M410*(1+'General Inputs'!$B$6)+'RAB Calculations'!N398","v":{"$error":"#REF!"}},{"$f":"N410*(1+'General Inputs'!$B$6)+'RAB Calculations'!O399","v":{"$error":"#REF!"}},{"$f":"O410*(1+'General Inputs'!$B$6)+'RAB Calculations'!P400","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,null,"accumulated depreciation (to start of year)",null,null,null,null,{"$f":"J383*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"(K412+K383)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(L412+L383)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(M412+M383)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(N412+N383)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(O412+O383)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"Total WDV of 50% of capex",null,null,null,null,null,{"$f":"K406-K412+K410+(K410+((J410-(J410/'RAB Calculations'!$J$47*'RAB Calculations'!I$47)))+K371)","v":{"$error":"#REF!"}},{"$f":"L406-L412+L410+(L410+((K410-(K410/'RAB Calculations'!$J$47*'RAB Calculations'!J$47)))+L371)","v":{"$error":"#REF!"}},{"$f":"M406-M412+M410+(M410+((L410-(L410/'RAB Calculations'!$J$47*'RAB Calculations'!K$47)))+M371)","v":{"$error":"#REF!"}},{"$f":"N406-N412+N410+(N410+((M410-(M410/'RAB Calculations'!$J$47*'RAB Calculations'!L$47)))+N371)","v":{"$error":"#REF!"}},{"$f":"O406-O412+O410+(O410+((N410-(N410/'RAB Calculations'!$J$47*'RAB Calculations'!M$47)))+O371)","v":{"$error":"#REF!"}},{"$f":"P406-P412+P410+(P410+((O410-(O410/'RAB Calculations'!$J$47*'RAB Calculations'!N$47)))+P371)","v":{"$error":"#REF!"}}]
[]
[null,null,null,"Total asset returns",null,null,null,null,null,null,{"$f":"(K406+K410-K412)*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(L406+L410-L412)*'General Inputs'!$B$7+((K410-($K410/'RAB Calculations'!$K$47*'RAB Calculations'!K$47)))*'General Inputs'!$B$7+L408*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(M406+M410-M412)*'General Inputs'!$B$7+((L410-($K410/'RAB Calculations'!$K$47*'RAB Calculations'!L$47)))*'General Inputs'!$B$7+M408*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(N406+N410-N412)*'General Inputs'!$B$7+((M410-($K410/'RAB Calculations'!$K$47*'RAB Calculations'!M$47)))*'General Inputs'!$B$7+N408*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(O406+O410-O412)*'General Inputs'!$B$7+((N410-($K410/'RAB Calculations'!$K$47*'RAB Calculations'!N$47)))*'General Inputs'!$B$7+O408*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(P406+P410-P412)*'General Inputs'!$B$7+((O410-($K410/'RAB Calculations'!$K$47*'RAB Calculations'!O$47)))*'General Inputs'!$B$7+P408*'General Inputs'!$B$7","v":{"$error":"#REF!"}}]
[]
[]
[null,null,"Proof of Calculations"]
[]
[null,null,null,"Initial assets"]
[null,null,null,null,"Opening balance",null,null,null,null,null,null,{"$f":"K389-K383-K412","v":{"$error":"#REF!"}}]
[]
[null,null,null,"First 50% of capex"]
[null,null,null,null,"Spend",null,null,null,null,null,{"$f":"K371","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[null,null,null,null,"Carried forward balance",null,null,null,null,null,null,{"$f":"K395","v":{"$error":"#REF!"}}]
[null,null,null,null,"NPV at nominal WACC of",null,null,null,{"$f":"NompretaxWACC","v":0.10639999999999999},null,null,{"$f":"L426+L425+NPV(I427,M425:P425)","v":{"$error":"#REF!"}}]
[]
[null,null,null,"Remainder of capex"]
[null,null,null,null,"Spend",null,null,null,null,null,{"$f":"K372","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[null,null,null,null,"Carried forward balance",null,null,null,null,null,null,{"$f":"K393","v":{"$error":"#REF!"}}]
[null,null,null,null,"NPV at nominal WACC of",null,null,null,{"$f":"I427","v":0.10639999999999999},null,null,{"$f":"L431+NPV(I432,L430:P430)","v":{"$error":"#REF!"}}]
[]
[]
[null,null,null,"Total opening balance",null,null,null,null,null,null,null,{"$f":"L422+L427+L432","v":{"$error":"#REF!"}}]
[null,null,null,null,"Revenue stream"]
[null,null,null,null,null,"depreciation",null,null,null,null,null,{"$f":"L383","v":{"$error":"#REF!"}},{"$f":"M383","v":{"$error":"#REF!"}},{"$f":"N383","v":{"$error":"#REF!"}},{"$f":"O383","v":{"$error":"#REF!"}},{"$f":"P383","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Return on assets",null,null,null,null,null,{"$f":"L416","v":{"$error":"#REF!"}},{"$f":"M416","v":{"$error":"#REF!"}},{"$f":"N416","v":{"$error":"#REF!"}},{"$f":"O416","v":{"$error":"#REF!"}},{"$f":"P416","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Residual value"]
[null,null,null,null,null,"residual value of initial assets",null,null,null,null,null,null,null,null,null,{"$f":"(P406-P412-P437+P410+P408+P430)+(O410-(K410/'RAB Calculations'!K47*'RAB Calculations'!O47))","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"residual value of remainder of capex"]
[null,null,null,null,"Total",null,null,null,null,null,null,{"$f":"L437+L438+L440","v":{"$error":"#REF!"}},{"$f":"M437+M438+M440","v":{"$error":"#REF!"}},{"$f":"N437+N438+N440","v":{"$error":"#REF!"}},{"$f":"O437+O438+O440","v":{"$error":"#REF!"}},{"$f":"P437+P438+P440","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"NPV at nominal WACC of",null,null,null,{"$f":"I432","v":0.10639999999999999},null,null,{"$f":"NPV(I444,L442:P442)","v":{"$error":"#REF!"}},{"$f":"L435-L444","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Check",null,null,null,null,null,{"$f":"IF(ROUND(L435-L444,5)=0,\"ok\",\"problem\")","v":{"$error":"#REF!"}}]
[]
[null,null,null,"Closing written down value",null,null,null,null,null,null,{"$f":"K406-K412-K383+K401+K410","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"RAB Calculations"]
[null,null,{"$f":"\"Asset Class 5 - \"&E17","v":"Asset Class 5 - Other Distribution Equipment"}]
[]
[null,null,"Real calculations"]
[]
[null,null,null,"Real asset value"]
[]
[null,null,null,null,"Opening balance",null,null,null,null,null,{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"K476","v":{"$error":"#REF!"}},{"$f":"L476","v":{"$error":"#REF!"}},{"$f":"M476","v":{"$error":"#REF!"}},{"$f":"N476","v":{"$error":"#REF!"}},{"$f":"O476","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"Capex"]
[null,null,null,null,null,"First 50%",null,null,null,null,{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Remainder",null,null,null,null,{"$f":"K471","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[null,null,null,null,"Depreciation",null,null,null,null,null,{"$f":"K478","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[null,null,null,null,"Closing balance",null,null,null,null,null,{"$f":"-K474+K472+K471+K468","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[null,null,null,null,"Depreciation",null,null,null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}}]
[]
[]
[null,null,"Depreciation"]
[]
[null,null,null,"Total depreciation",null,null,null,null,null,{"$f":"J478","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,"Asset Returns"]
[]
[null,null,null,"Initial assets"]
[null,null,null,null,"Regulatory value of initial assets",null,null,null,null,null,{"$f":"IF($K483=0,0,$K468*'RAB Calculations'!K$47*('RAB Calculations'!K483/'RAB Calculations'!$K483))","v":{"$error":"#REF!"}},{"$f":"IF($K483=0,0,$K468*'RAB Calculations'!L$47*('RAB Calculations'!L483/'RAB Calculations'!$K483))","v":{"$error":"#REF!"}},{"$f":"IF($K483=0,0,$K468*'RAB Calculations'!M$47*('RAB Calculations'!M483/'RAB Calculations'!$K483))","v":{"$error":"#REF!"}},{"$f":"IF($K483=0,0,$K468*'RAB Calculations'!N$47*('RAB Calculations'!N483/'RAB Calculations'!$K483))","v":{"$error":"#REF!"}},{"$f":"IF($K483=0,0,$K468*'RAB Calculations'!O$47*('RAB Calculations'!O483/'RAB Calculations'!$K483))","v":{"$error":"#REF!"}},{"$f":"IF($K483=0,0,$K468*'RAB Calculations'!P$47*('RAB Calculations'!P483/'RAB Calculations'!$K483))","v":{"$error":"#REF!"}}]
[]
[]
[null,null,null,"Capex"]
[null,null,null,null,"Regulatory value of remainder of year1 capex",null,null,null,null,null,{"$f":"$K471*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"$K471*'RAB Calculations'!L$47","v":{"$error":"#REF!"}},{"$f":"$K471*'RAB Calculations'!M$47","v":{"$error":"#REF!"}},{"$f":"$K471*'RAB Calculations'!N$47","v":{"$error":"#REF!"}},{"$f":"$K471*'RAB Calculations'!O$47","v":{"$error":"#REF!"}},{"$f":"$K471*'RAB Calculations'!P$47","v":{"$error":"#REF!"}}]
[null,null,null,null,"cost base of 50% of capex"]
[null,null,null,null,null,"Year 1 capex",null,null,null,null,{"$f":"$K471*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"$K471*'RAB Calculations'!L$47","v":{"$error":"#REF!"}},{"$f":"$K471*'RAB Calculations'!M$47","v":{"$error":"#REF!"}},{"$f":"$K471*'RAB Calculations'!N$47","v":{"$error":"#REF!"}},{"$f":"$K471*'RAB Calculations'!O$47","v":{"$error":"#REF!"}},{"$f":"$K471*'RAB Calculations'!P$47","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 2 capex",null,null,null,null,null,{"$f":"$L471*'RAB Calculations'!L$48","v":{"$error":"#REF!"}},{"$f":"$L471*'RAB Calculations'!M$48","v":{"$error":"#REF!"}},{"$f":"$L471*'RAB Calculations'!N$48","v":{"$error":"#REF!"}},{"$f":"$L471*'RAB Calculations'!O$48","v":{"$error":"#REF!"}},{"$f":"$L471*'RAB Calculations'!P$48","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 3 capex",null,null,null,null,null,null,{"$f":"$M471*'RAB Calculations'!M$49","v":{"$error":"#REF!"}},{"$f":"$M471*'RAB Calculations'!N$49","v":{"$error":"#REF!"}},{"$f":"$M471*'RAB Calculations'!O$49","v":{"$error":"#REF!"}},{"$f":"$M471*'RAB Calculations'!P$49","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 4 capex",null,null,null,null,null,null,null,{"$f":"$N471*'RAB Calculations'!N$50","v":{"$error":"#REF!"}},{"$f":"$N471*'RAB Calculations'!O$50","v":{"$error":"#REF!"}},{"$f":"$N471*'RAB Calculations'!P$50","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 5 capex",null,null,null,null,null,null,null,null,{"$f":"$O471*'RAB Calculations'!O$51","v":{"$error":"#REF!"}},{"$f":"$O471*'RAB Calculations'!P$51","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 6 capex",null,null,null,null,null,null,null,null,null,{"$f":"$P471*'RAB Calculations'!P$52","v":{"$error":"#REF!"}}]
[null,null,null,"Total",null,null,null,null,null,null,{"$f":"SUM(K495:K500)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,null,"Asset returns"]
[null,null,null,null,"Regulatory value of initial assets for return purposes"]
[null,null,null,null,null,"cost base",null,null,null,null,{"$f":"$K468*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"$K468*'RAB Calculations'!L$47","v":{"$error":"#REF!"}},{"$f":"$K468*'RAB Calculations'!M$47","v":{"$error":"#REF!"}},{"$f":"$K468*'RAB Calculations'!N$47","v":{"$error":"#REF!"}},{"$f":"$K468*'RAB Calculations'!O$47","v":{"$error":"#REF!"}},{"$f":"$K468*'RAB Calculations'!P$47","v":{"$error":"#REF!"}}]
[null,null,null,null,"Value of Year 1 remainder assets for return purposes"]
[null,null,null,null,null,"cost base",null,null,null,null,{"$f":"$K493/'RAB Calculations'!$K$48*'RAB Calculations'!K$48","v":{"$error":"#REF!"}},{"$f":"$K493/'RAB Calculations'!$K$48*'RAB Calculations'!L$48","v":{"$error":"#REF!"}},{"$f":"$K493/'RAB Calculations'!$K$48*'RAB Calculations'!M$48","v":{"$error":"#REF!"}},{"$f":"$K493/'RAB Calculations'!$K$48*'RAB Calculations'!N$48","v":{"$error":"#REF!"}},{"$f":"$K493/'RAB Calculations'!$K$48*'RAB Calculations'!O$48","v":{"$error":"#REF!"}},{"$f":"$K493/'RAB Calculations'!$K$48*'RAB Calculations'!P$48","v":{"$error":"#REF!"}}]
[null,null,null,null,"WDV of 50% of capex"]
[null,null,null,null,null,"cost base",null,null,null,null,{"$f":"K495","v":{"$error":"#REF!"}},{"$f":"K510*(1+'General Inputs'!$B$6)+'RAB Calculations'!L496","v":{"$error":"#REF!"}},{"$f":"L510*(1+'General Inputs'!$B$6)+'RAB Calculations'!M497","v":{"$error":"#REF!"}},{"$f":"M510*(1+'General Inputs'!$B$6)+'RAB Calculations'!N498","v":{"$error":"#REF!"}},{"$f":"N510*(1+'General Inputs'!$B$6)+'RAB Calculations'!O499","v":{"$error":"#REF!"}},{"$f":"O510*(1+'General Inputs'!$B$6)+'RAB Calculations'!P500","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,null,"accumulated depreciation (to start of year)",null,null,null,null,{"$f":"J483*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"(K512+K483)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(L512+L483)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(M512+M483)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(N512+N483)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(O512+O483)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"Total WDV of 50% of capex",null,null,null,null,null,{"$f":"K506-K512+K510+(K510+((J510-(J510/'RAB Calculations'!$J$47*'RAB Calculations'!I$47)))+K471)","v":{"$error":"#REF!"}},{"$f":"L506-L512+L510+(L510+((K510-(K510/'RAB Calculations'!$J$47*'RAB Calculations'!J$47)))+L471)","v":{"$error":"#REF!"}},{"$f":"M506-M512+M510+(M510+((L510-(L510/'RAB Calculations'!$J$47*'RAB Calculations'!K$47)))+M471)","v":{"$error":"#REF!"}},{"$f":"N506-N512+N510+(N510+((M510-(M510/'RAB Calculations'!$J$47*'RAB Calculations'!L$47)))+N471)","v":{"$error":"#REF!"}},{"$f":"O506-O512+O510+(O510+((N510-(N510/'RAB Calculations'!$J$47*'RAB Calculations'!M$47)))+O471)","v":{"$error":"#REF!"}},{"$f":"P506-P512+P510+(P510+((O510-(O510/'RAB Calculations'!$J$47*'RAB Calculations'!N$47)))+P471)","v":{"$error":"#REF!"}}]
[]
[null,null,null,"Total asset returns",null,null,null,null,null,null,{"$f":"(K506+K510-K512)*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(L506+L510-L512)*'General Inputs'!$B$7+((K510-($K510/'RAB Calculations'!$K$47*'RAB Calculations'!K$47)))*'General Inputs'!$B$7+L508*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(M506+M510-M512)*'General Inputs'!$B$7+((L510-($K510/'RAB Calculations'!$K$47*'RAB Calculations'!L$47)))*'General Inputs'!$B$7+M508*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(N506+N510-N512)*'General Inputs'!$B$7+((M510-($K510/'RAB Calculations'!$K$47*'RAB Calculations'!M$47)))*'General Inputs'!$B$7+N508*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(O506+O510-O512)*'General Inputs'!$B$7+((N510-($K510/'RAB Calculations'!$K$47*'RAB Calculations'!N$47)))*'General Inputs'!$B$7+O508*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(P506+P510-P512)*'General Inputs'!$B$7+((O510-($K510/'RAB Calculations'!$K$47*'RAB Calculations'!O$47)))*'General Inputs'!$B$7+P508*'General Inputs'!$B$7","v":{"$error":"#REF!"}}]
[]
[]
[null,null,"Proof of Calculations"]
[]
[null,null,null,"Initial assets"]
[null,null,null,null,"Opening balance",null,null,null,null,null,null,{"$f":"K489-K483-K512","v":{"$error":"#REF!"}}]
[]
[null,null,null,"First 50% of capex"]
[null,null,null,null,"Spend",null,null,null,null,null,{"$f":"K471","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[null,null,null,null,"Carried forward balance",null,null,null,null,null,null,{"$f":"K495","v":{"$error":"#REF!"}}]
[null,null,null,null,"NPV at nominal WACC of",null,null,null,{"$f":"NompretaxWACC","v":0.10639999999999999},null,null,{"$f":"L526+L525+NPV(I527,M525:P525)","v":{"$error":"#REF!"}}]
[]
[null,null,null,"Remainder of capex"]
[null,null,null,null,"Spend",null,null,null,null,null,{"$f":"K472","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[null,null,null,null,"Carried forward balance",null,null,null,null,null,null,{"$f":"K493","v":{"$error":"#REF!"}}]
[null,null,null,null,"NPV at nominal WACC of",null,null,null,{"$f":"I527","v":0.10639999999999999},null,null,{"$f":"L531+NPV(I532,L530:P530)","v":{"$error":"#REF!"}}]
[]
[]
[null,null,null,"Total opening balance",null,null,null,null,null,null,null,{"$f":"L522+L527+L532","v":{"$error":"#REF!"}}]
[null,null,null,null,"Revenue stream"]
[null,null,null,null,null,"depreciation",null,null,null,null,null,{"$f":"L483","v":{"$error":"#REF!"}},{"$f":"M483","v":{"$error":"#REF!"}},{"$f":"N483","v":{"$error":"#REF!"}},{"$f":"O483","v":{"$error":"#REF!"}},{"$f":"P483","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Return on assets",null,null,null,null,null,{"$f":"L516","v":{"$error":"#REF!"}},{"$f":"M516","v":{"$error":"#REF!"}},{"$f":"N516","v":{"$error":"#REF!"}},{"$f":"O516","v":{"$error":"#REF!"}},{"$f":"P516","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Residual value"]
[null,null,null,null,null,"residual value of initial assets",null,null,null,null,null,null,null,null,null,{"$f":"(P506-P512-P537+P510+P508+P530)+(O510-(K510/'RAB Calculations'!K47*'RAB Calculations'!O47))","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"residual value of remainder of capex"]
[null,null,null,null,"Total",null,null,null,null,null,null,{"$f":"L537+L538+L540","v":{"$error":"#REF!"}},{"$f":"M537+M538+M540","v":{"$error":"#REF!"}},{"$f":"N537+N538+N540","v":{"$error":"#REF!"}},{"$f":"O537+O538+O540","v":{"$error":"#REF!"}},{"$f":"P537+P538+P540","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"NPV at nominal WACC of",null,null,null,{"$f":"I532","v":0.10639999999999999},null,null,{"$f":"NPV(I544,L542:P542)","v":{"$error":"#REF!"}},{"$f":"L535-L544","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Check",null,null,null,null,null,{"$f":"IF(ROUND(L535-L544,5)=0,\"ok\",\"problem\")","v":{"$error":"#REF!"}}]
[]
[null,null,null,"Closing written down value",null,null,null,null,null,null,{"$f":"K506-K512-K483+K501+K510","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"RAB Calculations"]
[null,null,{"$f":"\"Asset Class 6 - \"&E18","v":"Asset Class 6 - Other Assets"}]
[]
[null,null,"Real calculations"]
[]
[null,null,null,"Real asset value"]
[]
[null,null,null,null,"Opening balance",null,null,null,null,null,{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"K576","v":{"$error":"#REF!"}},{"$f":"L576","v":{"$error":"#REF!"}},{"$f":"M576","v":{"$error":"#REF!"}},{"$f":"N576","v":{"$error":"#REF!"}},{"$f":"O576","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"Capex"]
[null,null,null,null,null,"First 50%",null,null,null,null,{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}},{"$f":"#REF!/2","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Remainder",null,null,null,null,{"$f":"K571","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[null,null,null,null,"Depreciation",null,null,null,null,null,{"$f":"K578","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[null,null,null,null,"Closing balance",null,null,null,null,null,{"$f":"-K574+K572+K571+K568","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[null,null,null,null,"Depreciation",null,null,null,null,{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}},{"$f":"'General Inputs'!#REF!","v":{"$error":"#REF!"}}]
[]
[]
[null,null,"Depreciation"]
[]
[null,null,null,"Total depreciation",null,null,null,null,null,{"$f":"J578","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,"Asset Returns"]
[]
[null,null,null,"Initial assets"]
[null,null,null,null,"Regulatory value of initial assets",null,null,null,null,null,{"$f":"IF($K583=0,0,$K568*'RAB Calculations'!K$47*('RAB Calculations'!K583/'RAB Calculations'!$K583))","v":{"$error":"#REF!"}},{"$f":"IF($K583=0,0,$K568*'RAB Calculations'!L$47*('RAB Calculations'!L583/'RAB Calculations'!$K583))","v":{"$error":"#REF!"}},{"$f":"IF($K583=0,0,$K568*'RAB Calculations'!M$47*('RAB Calculations'!M583/'RAB Calculations'!$K583))","v":{"$error":"#REF!"}},{"$f":"IF($K583=0,0,$K568*'RAB Calculations'!N$47*('RAB Calculations'!N583/'RAB Calculations'!$K583))","v":{"$error":"#REF!"}},{"$f":"IF($K583=0,0,$K568*'RAB Calculations'!O$47*('RAB Calculations'!O583/'RAB Calculations'!$K583))","v":{"$error":"#REF!"}},{"$f":"IF($K583=0,0,$K568*'RAB Calculations'!P$47*('RAB Calculations'!P583/'RAB Calculations'!$K583))","v":{"$error":"#REF!"}}]
[]
[]
[null,null,null,"Capex"]
[null,null,null,null,"Regulatory value of remainder of year1 capex",null,null,null,null,null,{"$f":"$K571*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"$K571*'RAB Calculations'!L$47","v":{"$error":"#REF!"}},{"$f":"$K571*'RAB Calculations'!M$47","v":{"$error":"#REF!"}},{"$f":"$K571*'RAB Calculations'!N$47","v":{"$error":"#REF!"}},{"$f":"$K571*'RAB Calculations'!O$47","v":{"$error":"#REF!"}},{"$f":"$K571*'RAB Calculations'!P$47","v":{"$error":"#REF!"}}]
[null,null,null,null,"cost base of 50% of capex"]
[null,null,null,null,null,"Year 1 capex",null,null,null,null,{"$f":"$K571*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"$K571*'RAB Calculations'!L$47","v":{"$error":"#REF!"}},{"$f":"$K571*'RAB Calculations'!M$47","v":{"$error":"#REF!"}},{"$f":"$K571*'RAB Calculations'!N$47","v":{"$error":"#REF!"}},{"$f":"$K571*'RAB Calculations'!O$47","v":{"$error":"#REF!"}},{"$f":"$K571*'RAB Calculations'!P$47","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 2 capex",null,null,null,null,null,{"$f":"$L571*'RAB Calculations'!L$48","v":{"$error":"#REF!"}},{"$f":"$L571*'RAB Calculations'!M$48","v":{"$error":"#REF!"}},{"$f":"$L571*'RAB Calculations'!N$48","v":{"$error":"#REF!"}},{"$f":"$L571*'RAB Calculations'!O$48","v":{"$error":"#REF!"}},{"$f":"$L571*'RAB Calculations'!P$48","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 3 capex",null,null,null,null,null,null,{"$f":"$M571*'RAB Calculations'!M$49","v":{"$error":"#REF!"}},{"$f":"$M571*'RAB Calculations'!N$49","v":{"$error":"#REF!"}},{"$f":"$M571*'RAB Calculations'!O$49","v":{"$error":"#REF!"}},{"$f":"$M571*'RAB Calculations'!P$49","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 4 capex",null,null,null,null,null,null,null,{"$f":"$N571*'RAB Calculations'!N$50","v":{"$error":"#REF!"}},{"$f":"$N571*'RAB Calculations'!O$50","v":{"$error":"#REF!"}},{"$f":"$N571*'RAB Calculations'!P$50","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 5 capex",null,null,null,null,null,null,null,null,{"$f":"$O571*'RAB Calculations'!O$51","v":{"$error":"#REF!"}},{"$f":"$O571*'RAB Calculations'!P$51","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Year 6 capex",null,null,null,null,null,null,null,null,null,{"$f":"$P571*'RAB Calculations'!P$52","v":{"$error":"#REF!"}}]
[null,null,null,"Total",null,null,null,null,null,null,{"$f":"SUM(K595:K600)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,null,"Asset returns"]
[null,null,null,null,"Regulatory value of initial assets for return purposes"]
[null,null,null,null,null,"cost base",null,null,null,null,{"$f":"$K568*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"$K568*'RAB Calculations'!L$47","v":{"$error":"#REF!"}},{"$f":"$K568*'RAB Calculations'!M$47","v":{"$error":"#REF!"}},{"$f":"$K568*'RAB Calculations'!N$47","v":{"$error":"#REF!"}},{"$f":"$K568*'RAB Calculations'!O$47","v":{"$error":"#REF!"}},{"$f":"$K568*'RAB Calculations'!P$47","v":{"$error":"#REF!"}}]
[null,null,null,null,"Value of Year 1 remainder assets for return purposes"]
[null,null,null,null,null,"cost base",null,null,null,null,{"$f":"$K593/'RAB Calculations'!$K$48*'RAB Calculations'!K$48","v":{"$error":"#REF!"}},{"$f":"$K593/'RAB Calculations'!$K$48*'RAB Calculations'!L$48","v":{"$error":"#REF!"}},{"$f":"$K593/'RAB Calculations'!$K$48*'RAB Calculations'!M$48","v":{"$error":"#REF!"}},{"$f":"$K593/'RAB Calculations'!$K$48*'RAB Calculations'!N$48","v":{"$error":"#REF!"}},{"$f":"$K593/'RAB Calculations'!$K$48*'RAB Calculations'!O$48","v":{"$error":"#REF!"}},{"$f":"$K593/'RAB Calculations'!$K$48*'RAB Calculations'!P$48","v":{"$error":"#REF!"}}]
[null,null,null,null,"WDV of 50% of capex"]
[null,null,null,null,null,"cost base",null,null,null,null,{"$f":"K595","v":{"$error":"#REF!"}},{"$f":"K610*(1+'General Inputs'!$B$6)+'RAB Calculations'!L596","v":{"$error":"#REF!"}},{"$f":"L610*(1+'General Inputs'!$B$6)+'RAB Calculations'!M597","v":{"$error":"#REF!"}},{"$f":"M610*(1+'General Inputs'!$B$6)+'RAB Calculations'!N598","v":{"$error":"#REF!"}},{"$f":"N610*(1+'General Inputs'!$B$6)+'RAB Calculations'!O599","v":{"$error":"#REF!"}},{"$f":"O610*(1+'General Inputs'!$B$6)+'RAB Calculations'!P600","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,null,"accumulated depreciation (to start of year)",null,null,null,null,{"$f":"J583*'RAB Calculations'!K$47","v":{"$error":"#REF!"}},{"$f":"(K612+K583)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(L612+L583)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(M612+M583)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(N612+N583)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}},{"$f":"(O612+O583)*(1+'General Inputs'!$B$6)","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"Total WDV of 50% of capex",null,null,null,null,null,{"$f":"K606-K612+K610+(K610+((J610-(J610/'RAB Calculations'!$J$47*'RAB Calculations'!I$47)))+K571)","v":{"$error":"#REF!"}},{"$f":"L606-L612+L610+(L610+((K610-(K610/'RAB Calculations'!$J$47*'RAB Calculations'!J$47)))+L571)","v":{"$error":"#REF!"}},{"$f":"M606-M612+M610+(M610+((L610-(L610/'RAB Calculations'!$J$47*'RAB Calculations'!K$47)))+M571)","v":{"$error":"#REF!"}},{"$f":"N606-N612+N610+(N610+((M610-(M610/'RAB Calculations'!$J$47*'RAB Calculations'!L$47)))+N571)","v":{"$error":"#REF!"}},{"$f":"O606-O612+O610+(O610+((N610-(N610/'RAB Calculations'!$J$47*'RAB Calculations'!M$47)))+O571)","v":{"$error":"#REF!"}},{"$f":"P606-P612+P610+(P610+((O610-(O610/'RAB Calculations'!$J$47*'RAB Calculations'!N$47)))+P571)","v":{"$error":"#REF!"}}]
[]
[null,null,null,"Total asset returns",null,null,null,null,null,null,{"$f":"(K606+K610-K612)*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(L606+L610-L612)*'General Inputs'!$B$7+((K610-($K610/'RAB Calculations'!$K$47*'RAB Calculations'!K$47)))*'General Inputs'!$B$7+L608*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(M606+M610-M612)*'General Inputs'!$B$7+((L610-($K610/'RAB Calculations'!$K$47*'RAB Calculations'!L$47)))*'General Inputs'!$B$7+M608*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(N606+N610-N612)*'General Inputs'!$B$7+((M610-($K610/'RAB Calculations'!$K$47*'RAB Calculations'!M$47)))*'General Inputs'!$B$7+N608*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(O606+O610-O612)*'General Inputs'!$B$7+((N610-($K610/'RAB Calculations'!$K$47*'RAB Calculations'!N$47)))*'General Inputs'!$B$7+O608*'General Inputs'!$B$7","v":{"$error":"#REF!"}},{"$f":"(P606+P610-P612)*'General Inputs'!$B$7+((O610-($K610/'RAB Calculations'!$K$47*'RAB Calculations'!O$47)))*'General Inputs'!$B$7+P608*'General Inputs'!$B$7","v":{"$error":"#REF!"}}]
[]
[]
[null,null,"Proof of Calculations"]
[]
[null,null,null,"Initial assets"]
[null,null,null,null,"Opening balance",null,null,null,null,null,null,{"$f":"K589-K583-K612","v":{"$error":"#REF!"}}]
[]
[null,null,null,"First 50% of capex"]
[null,null,null,null,"Spend",null,null,null,null,null,{"$f":"K571","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[null,null,null,null,"Carried forward balance",null,null,null,null,null,null,{"$f":"K595","v":{"$error":"#REF!"}}]
[null,null,null,null,"NPV at nominal WACC of",null,null,null,{"$f":"NompretaxWACC","v":0.10639999999999999},null,null,{"$f":"L626+L625+NPV(I627,M625:P625)","v":{"$error":"#REF!"}}]
[]
[null,null,null,"Remainder of capex"]
[null,null,null,null,"Spend",null,null,null,null,null,{"$f":"K572","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[null,null,null,null,"Carried forward balance",null,null,null,null,null,null,{"$f":"K593","v":{"$error":"#REF!"}}]
[null,null,null,null,"NPV at nominal WACC of",null,null,null,{"$f":"I627","v":0.10639999999999999},null,null,{"$f":"L631+NPV(I632,L630:P630)","v":{"$error":"#REF!"}}]
[]
[]
[null,null,null,"Total opening balance",null,null,null,null,null,null,null,{"$f":"L622+L627+L632","v":{"$error":"#REF!"}}]
[null,null,null,null,"Revenue stream"]
[null,null,null,null,null,"depreciation",null,null,null,null,null,{"$f":"L583","v":{"$error":"#REF!"}},{"$f":"M583","v":{"$error":"#REF!"}},{"$f":"N583","v":{"$error":"#REF!"}},{"$f":"O583","v":{"$error":"#REF!"}},{"$f":"P583","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Return on assets",null,null,null,null,null,{"$f":"L616","v":{"$error":"#REF!"}},{"$f":"M616","v":{"$error":"#REF!"}},{"$f":"N616","v":{"$error":"#REF!"}},{"$f":"O616","v":{"$error":"#REF!"}},{"$f":"P616","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Residual value"]
[null,null,null,null,null,"residual value of initial assets",null,null,null,null,null,null,null,null,null,{"$f":"(P606-P612-P637+P610+P608+P630)+(O610-(K610/'RAB Calculations'!K47*'RAB Calculations'!O47))","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"residual value of remainder of capex"]
[null,null,null,null,"Total",null,null,null,null,null,null,{"$f":"L637+L638+L640","v":{"$error":"#REF!"}},{"$f":"M637+M638+M640","v":{"$error":"#REF!"}},{"$f":"N637+N638+N640","v":{"$error":"#REF!"}},{"$f":"O637+O638+O640","v":{"$error":"#REF!"}},{"$f":"P637+P638+P640","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"NPV at nominal WACC of",null,null,null,{"$f":"I632","v":0.10639999999999999},null,null,{"$f":"NPV(I644,L642:P642)","v":{"$error":"#REF!"}},{"$f":"L635-L644","v":{"$error":"#REF!"}}]
[null,null,null,null,null,"Check",null,null,null,null,null,{"$f":"IF(ROUND(L635-L644,5)=0,\"ok\",\"problem\")","v":{"$error":"#REF!"}}]
[]
[null,null,null,"Closing written down value",null,null,null,null,null,null,{"$f":"K606-K612-K583+K601+K610","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"}]

{"sheet":"Tariff Inputs","index":6,"n_rows":119,"n_cols":13,"rows_kept":119,"cut":false,"hidden":false,"merged":[[0,0,0,14]]}
["Tariff Inputs"]
[]
[]
[{"$f":"'General Inputs'!B20","v":"Residential 1"},"2004/05","2005/06",{"$f":"'Volume Inputs'!A5","v":"2006/07"},{"$f":"'Volume Inputs'!A6","v":"2007/08"},{"$f":"'Volume Inputs'!A7","v":"2008/09"},{"$f":"'Volume Inputs'!A8","v":"2009/10"},{"$f":"'Volume Inputs'!A9","v":"2010/11"},"2011/12","2012/13","2013/14","2014/15","2015/16"]
[{"$f":"'General Inputs'!E20","v":"Residential tariff - anytime use"}]
["Fixed ($/day)",0,0,0.22900000000000001,0.248,0.26,0.28000000000000003,{"$f":"'[8]Alternative Tariff Schedule'!$B$6","v":0.31},0,0,0,0,0]
["Band 1 ($/GJ)",0,0,9.9770000000000003,10.15,10.82,11.02,{"$f":"'[8]Alternative Tariff Schedule'!$B$7","v":14},0,0,0,0,0]
["Band 2 ($/GJ)",0,0,4.758,4.82,5.0599999999999996,5.14,{"$f":"'[8]Alternative Tariff Schedule'!$B$8","v":8.3446499999999997},0,0,0,0,0]
["Band 3 ($/GJ)",0,0,0,0,0,0,{"$f":"'[8]Alternative Tariff Schedule'!$B$9","v":3.4959830097564191},0,0,0,0,0]
["Band 4 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
["Band 5 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
[]
[{"$f":"'General Inputs'!B21","v":"Residential 2"},{"$f":"B4","v":"2004/05"},{"$f":"C4","v":"2005/06"},"2006/07","2007/08","2008/09","2009/10","2010/11",{"$f":"I4","v":"2011/12"},{"$f":"J4","v":"2012/13"},{"$f":"K4","v":"2013/14"},{"$f":"L4","v":"2014/15"},{"$f":"M4","v":"2015/16"}]
[{"$f":"'General Inputs'!E21","v":"Residential tariff - HW booster only"}]
[{"$f":"A6","v":"Fixed ($/day)"},0,0,0,0,0,0,0,0,0,0,0,0]
["Band 1 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
["Band 2 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
["Band 3 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
["Band 4 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
["Band 5 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
[]
[{"$f":"'General Inputs'!B22","v":"Residential 3"},{"$f":"B13","v":"2004/05"},{"$f":"C13","v":"2005/06"},"2006/07","2007/08","2008/09","2009/10","2010/11",{"$f":"I13","v":"2011/12"},{"$f":"J13","v":"2012/13"},{"$f":"K13","v":"2013/14"},{"$f":"L13","v":"2014/15"},{"$f":"M13","v":"2015/16"}]
[{"$f":"'General Inputs'!E22","v":"Residential Tariff - off peak only"}]
[{"$f":"A15","v":"Fixed ($/day)"},0,0,0,0,0,0,0,0,0,0,0,0]
["Band 1 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
["Band 2 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
["Band 3 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
["Band 4 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
["Band 5 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
[]
[{"$f":"'General Inputs'!B23","v":"Commercial 1"},{"$f":"B22","v":"2004/05"},{"$f":"C22","v":"2005/06"},"2006/07","2007/08","2008/09","2009/10","2010/11",{"$f":"I22","v":"2011/12"},{"$f":"J22","v":"2012/13"},{"$f":"K22","v":"2013/14"},{"$f":"L22","v":"2014/15"},{"$f":"M22","v":"2015/16"}]
[{"$f":"'General Inputs'!E23","v":"Commercial customers - anytime use"}]
[{"$f":"A24","v":"Fixed ($/day)"},0,0,0.46700000000000003,0.53900000000000003,0.52,0.56000000000000005,{"$f":"'[8]Alternative Tariff Schedule'!$B$13","v":0.62},0,0,0,0,0]
["Band 1 ($/GJ)",0,0,7.359,7.55,8.06,8.3000000000000007,{"$f":"'[8]Alternative Tariff Schedule'!$B$14","v":8.8000000000000007},0,0,0,0,0]
["Band 2 ($/GJ)",0,0,4.2270000000000003,4.32,4.5599999999999996,4.6900000000000004,{"$f":"'[8]Alternative Tariff Schedule'!$B$15","v":4.72},0,0,0,0,0]
["Band 3 ($/GJ)",0,0,1.85,1.88,1.99,2.04,{"$f":"'[8]Alternative Tariff Schedule'!$B$16","v":2.06},0,0,0,0,0]
["Band 4 ($/GJ)",0,0,0.78800000000000003,0.79,0.85,0.86,{"$f":"'[8]Alternative Tariff Schedule'!$B$17","v":0.86},0,0,0,0,0]
["Band 5 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
[]
[{"$f":"'General Inputs'!B24","v":"Commercial 2"},{"$f":"B31","v":"2004/05"},{"$f":"C31","v":"2005/06"},"2006/07","2007/08","2008/09","2009/10","2010/11",{"$f":"I31","v":"2011/12"},{"$f":"J31","v":"2012/13"},{"$f":"K31","v":"2013/14"},{"$f":"L31","v":"2014/15"},{"$f":"M31","v":"2015/16"}]
[{"$f":"'General Inputs'!E24","v":"Commercial customers - Off peak only"}]
[{"$f":"A33","v":"Fixed ($/day)"},0,0,0,0,0,0,0,0,0,0,0,0]
["Band 1 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
["Band 2 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
["Band 3 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
["Band 4 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
["Band 5 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
[]
["Demand-AdNr",{"$f":"B40","v":"2004/05"},{"$f":"C40","v":"2005/06"},"2006/07","2007/08","2008/09","2009/10","2010/11",{"$f":"I40","v":"2011/12"},{"$f":"J40","v":"2012/13"},{"$f":"K40","v":"2013/14"},{"$f":"L40","v":"2014/15"},{"$f":"M40","v":"2015/16"}]
["Demand customers in region 1"]
["Fixed ($/month)",0,0,2130,2317,2419,2506,{"$f":"'[8]Alternative Tariff Schedule'!C21","v":2682},0,0,0,0,0]
["Band 1 ($/GJ)",0,0,28.43,29.28,30.86,32.4,{"$f":"'[8]Alternative Tariff Schedule'!C22","v":34.06},0,0,0,0,0]
["Band 2 ($/GJ)",0,0,18.920000000000002,19.3,20.3,20.91,{"$f":"'[8]Alternative Tariff Schedule'!C23","v":21.33},0,0,0,0,0]
["Band 3 ($/GJ)",0,0,5.61,5.67,5.94,6.04,{"$f":"'[8]Alternative Tariff Schedule'!C24","v":6.4},0,0,0,0,0]
["Band 4 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
["Band 5 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
[]
["Demand-AdC",{"$f":"B49","v":"2004/05"},{"$f":"C49","v":"2005/06"},"2006/07","2007/08","2008/09","2009/10","2010/11",{"$f":"I49","v":"2011/12"},{"$f":"J49","v":"2012/13"},{"$f":"K49","v":"2013/14"},{"$f":"L49","v":"2014/15"},{"$f":"M49","v":"2015/16"}]
["Demand customers in region 2"]
[{"$f":"A51","v":"Fixed ($/month)"},0,0,2130,2317,2419,2506,{"$f":"'[8]Alternative Tariff Schedule'!B21","v":2682},0,0,0,0,0]
["Band 1 ($/GJ)",0,0,33.880000000000003,34.9,36.78,38.619999999999997,{"$f":"'[8]Alternative Tariff Schedule'!B22","v":40.590000000000003},0,0,0,0,0]
["Band 2 ($/GJ)",0,0,22.89,23.34,24.55,25.29,{"$f":"'[8]Alternative Tariff Schedule'!B23","v":25.8},0,0,0,0,0]
["Band 3 ($/GJ)",0,0,6.49,6.55,6.86,6.97,{"$f":"'[8]Alternative Tariff Schedule'!B24","v":7.4},0,0,0,0,0]
["Band 4 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
["Band 5 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
[]
["Demand-AdS",{"$f":"B58","v":"2004/05"},{"$f":"C58","v":"2005/06"},"2006/07","2007/08","2008/09","2009/10","2010/11",{"$f":"I58","v":"2011/12"},{"$f":"J58","v":"2012/13"},{"$f":"K58","v":"2013/14"},{"$f":"L58","v":"2014/15"},{"$f":"M58","v":"2015/16"}]
["Demand customers in region 3"]
[{"$f":"A60","v":"Fixed ($/month)"},0,0,2130,2317,2419,2506,{"$f":"'[8]Alternative Tariff Schedule'!D21","v":2682},0,0,0,0,0]
["Band 1 ($/GJ)",0,0,39.950000000000003,41.15,43.37,45.54,{"$f":"'[8]Alternative Tariff Schedule'!D22","v":47.86},0,0,0,0,0]
["Band 2 ($/GJ)",0,0,26.59,27.12,28.53,29.39,{"$f":"'[8]Alternative Tariff Schedule'!D23","v":29.97},0,0,0,0,0]
["Band 3 ($/GJ)",0,0,7.93,8.01,8.39,8.5299999999999994,{"$f":"'[8]Alternative Tariff Schedule'!D24","v":9.0399999999999991},0,0,0,0,0]
["Band 4 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
["Band 5 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
[]
["Demand-PP",{"$f":"B67","v":"2004/05"},{"$f":"C67","v":"2005/06"},"2006/07","2007/08","2008/09","2009/10","2010/11",{"$f":"I67","v":"2011/12"},{"$f":"J67","v":"2012/13"},{"$f":"K67","v":"2013/14"},{"$f":"L67","v":"2014/15"},{"$f":"M67","v":"2015/16"}]
["Demand customers in region 4"]
[{"$f":"A69","v":"Fixed ($/month)"},0,0,2130,2317,2419,2506,{"$f":"'[8]Alternative Tariff Schedule'!C28","v":2682},0,0,0,0,0]
["Band 1 ($/GJ)",0,0,28.42,29.27,30.85,32.39,{"$f":"'[8]Alternative Tariff Schedule'!C29","v":34.049999999999997},0,0,0,0,0]
["Band 2 ($/GJ)",0,0,15.43,15.74,16.559999999999999,17.059999999999999,{"$f":"'[8]Alternative Tariff Schedule'!C30","v":17.399999999999999},0,0,0,0,0]
["Band 3 ($/GJ)",0,0,6.36,6.42,6.75,6.86,{"$f":"'[8]Alternative Tariff Schedule'!C31","v":7.34},0,0,0,0,0]
["Band 4 ($/GJ)",0,0,5.19,5.23,5.5,5.59,{"$f":"'[8]Alternative Tariff Schedule'!C32","v":5.98},0,0,0,0,0]
["Band 5 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
[]
["Demand-Peter",{"$f":"B76","v":"2004/05"},{"$f":"C76","v":"2005/06"},"2006/07","2007/08","2008/09","2009/10","2010/11",{"$f":"I76","v":"2011/12"},{"$f":"J76","v":"2012/13"},{"$f":"K76","v":"2013/14"},{"$f":"L76","v":"2014/15"},{"$f":"M76","v":"2015/16"}]
["Demand customers in region 5"]
[{"$f":"A78","v":"Fixed ($/month)"},0,0,2953,3211,3353,3474,{"$f":"'[8]Alternative Tariff Schedule'!B28","v":3795},0,0,0,0,0]
["Band 1 ($/GJ)",0,0,41.71,42.96,45.28,47.54,{"$f":"'[8]Alternative Tariff Schedule'!B29","v":49.92},0,0,0,0,0]
["Band 2 ($/GJ)",0,0,27.2,27.74,29.18,30.06,{"$f":"'[8]Alternative Tariff Schedule'!B30","v":30.66},0,0,0,0,0]
["Band 3 ($/GJ)",0,0,27.2,27.47,28.87,29.36,{"$f":"'[8]Alternative Tariff Schedule'!B31","v":31.42},0,0,0,0,0]
["Band 4 ($/GJ)",0,0,5.61,5.66,5.95,6.05,{"$f":"'[8]Alternative Tariff Schedule'!B32","v":6.47},0,0,0,0,0]
["Band 5 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
[]
["Demand-River",{"$f":"B85","v":"2004/05"},{"$f":"C85","v":"2005/06"},"2006/07","2007/08","2008/09","2009/10","2010/11",{"$f":"I85","v":"2011/12"},{"$f":"J85","v":"2012/13"},{"$f":"K85","v":"2013/14"},{"$f":"L85","v":"2014/15"},{"$f":"M85","v":"2015/16"}]
["Demand customers in region 6"]
[{"$f":"A87","v":"Fixed ($/month)"},0,0,2953,3211,3353,3474,{"$f":"'[8]Alternative Tariff Schedule'!D28","v":3795},0,0,0,0,0]
["Band 1 ($/GJ)",0,0,41.61,42.86,45.17,47.43,{"$f":"'[8]Alternative Tariff Schedule'!D29","v":49.8},0,0,0,0,0]
["Band 2 ($/GJ)",0,0,27.2,27.74,29.18,30.06,{"$f":"'[8]Alternative Tariff Schedule'!D30","v":30.66},0,0,0,0,0]
["Band 3 ($/GJ)",0,0,27.2,27.47,28.87,29.36,{"$f":"'[8]Alternative Tariff Schedule'!D31","v":31.42},0,0,0,0,0]
["Band 4 ($/GJ)",0,0,5.61,5.66,5.95,6.05,{"$f":"'[8]Alternative Tariff Schedule'!D32","v":6.47},0,0,0,0,0]
["Band 5 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
[]
["Demand-SE",{"$f":"B94","v":"2004/05"},{"$f":"C94","v":"2005/06"},"2006/07","2007/08","2008/09","2009/10","2010/11",{"$f":"I94","v":"2011/12"},{"$f":"J94","v":"2012/13"},{"$f":"K94","v":"2013/14"},{"$f":"L94","v":"2014/15"},{"$f":"M94","v":"2015/16"}]
["Demand customers in region 7"]
[{"$f":"A96","v":"Fixed ($/month)"},0,0,2130,2317,2419,2506,{"$f":"'[8]Alternative Tariff Schedule'!E28","v":2682},0,0,0,0,0]
["Band 1 ($/GJ)",0,0,28.42,29.27,30.85,32.39,{"$f":"'[8]Alternative Tariff Schedule'!E29","v":34.049999999999997},0,0,0,0,0]
["Band 2 ($/GJ)",0,0,15.43,15.74,16.559999999999999,17.059999999999999,{"$f":"'[8]Alternative Tariff Schedule'!E30","v":17.399999999999999},0,0,0,0,0]
["Band 3 ($/GJ)",0,0,15.43,15.58,16.37,16.649999999999999,{"$f":"'[8]Alternative Tariff Schedule'!E31","v":17.82},0,0,0,0,0]
["Band 4 ($/GJ)",0,0,5.61,5.66,5.95,6.05,{"$f":"'[8]Alternative Tariff Schedule'!E32","v":6.47},0,0,0,0,0]
["Band 5 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]
[]
["Demand-Whyal",{"$f":"B103","v":"2004/05"},{"$f":"C103","v":"2005/06"},"2006/07","2007/08","2008/09","2009/10","2010/11",{"$f":"I103","v":"2011/12"},{"$f":"J103","v":"2012/13"},{"$f":"K103","v":"2013/14"},{"$f":"L103","v":"2014/15"},{"$f":"M103","v":"2015/16"}]
["Demand customers in region 8"]
[{"$f":"A105","v":"Fixed ($/month)"},0,0,2130,2317,2419,2506,{"$f":"'[8]Alternative Tariff Schedule'!F28","v":2682},0,0,0,0,0]
["Band 1 ($/GJ)",0,0,28.53,29.39,30.98,32.53,{"$f":"'[8]Alternative Tariff Schedule'!F29","v":34.18},0,0,0,0,0]
["Band 2 ($/GJ)",0,0,15.43,15.74,16.559999999999999,17.059999999999999,{"$f":"'[8]Alternative Tariff Schedule'!F30","v":17.399999999999999},0,0,0,0,0]
["Band 3 ($/GJ)",0,0,15.43,15.58,16.37,16.649999999999999,{"$f":"'[8]Alternative Tariff Schedule'!F31","v":17.82},0,0,0,0,0]
["Band 4 ($/GJ)",0,0,5.61,5.66,5.95,6.05,{"$f":"'[8]Alternative Tariff Schedule'!F32","v":6.47},0,0,0,0,0]
["Band 5 ($/GJ)",0,0,0,0,0,0,0,0,0,0,0,0]

{"sheet":"Cost allocators","index":7,"n_rows":60,"n_cols":16,"rows_kept":60,"cut":false,"hidden":false,"merged":[[57,0,57,1],[25,0,25,1],[3,0,3,1],[0,0,0,11],[10,0,10,1],[30,0,30,15]]}
["Cost Allocators"]
[]
[]
["Tariff D Zonal Allocator Selection"]
[{"$f":"'FDC Calculations'!A4","v":"Return on capital"},"Assets"]
[{"$f":"'FDC Calculations'!A5","v":"Return of capital"},"Assets"]
[{"$f":"'FDC Calculations'!A6","v":"O&M"},"Volume and Customer No"]
[{"$f":"'FDC Calculations'!A7","v":"Carry-over amounts"},"Volume and Customer No"]
[{"$f":"'FDC Calculations'!A8","v":"Benchmark Tax liability"},"Assets"]
[]
["Tariff R+C Allocator Selection",null,"Residential","Commercial"]
[{"$f":"A5","v":"Return on capital"},"Volume and Customer No",{"$f":"IF(B12=$A$20,SUM($C$20:$E$20)/SUM($C$20:$G$20),IF(B12=$A$21,SUM($C$21:$E$21)/SUM($C$21:$G$21),SUM($C$22:$E$22)/SUM($C$22:$G$22)))","v":{"$error":"#NAME?"}},{"$f":"IF(B12=$A$20,SUM($F$20:$G$20)/SUM($C$20:$G$20),IF(B12=$A$21,SUM($F$21:$G$21)/SUM($C$21:$G$21),SUM($F$22:$G$22)/SUM($C$22:$G$22)))","v":{"$error":"#NAME?"}}]
[{"$f":"A6","v":"Return of capital"},"Volume and Customer No",{"$f":"IF(B13=$A$20,SUM($C$20:$E$20)/SUM($C$20:$G$20),IF(B13=$A$21,SUM($C$21:$E$21)/SUM($C$21:$G$21),SUM($C$22:$E$22)/SUM($C$22:$G$22)))","v":{"$error":"#NAME?"}},{"$f":"IF(B13=$A$20,SUM($F$20:$G$20)/SUM($C$20:$G$20),IF(B13=$A$21,SUM($F$21:$G$21)/SUM($C$21:$G$21),SUM($F$22:$G$22)/SUM($C$22:$G$22)))","v":{"$error":"#NAME?"}}]
[{"$f":"A7","v":"O&M"},"Volume and Customer No",{"$f":"IF(B14=$A$20,SUM($C$20:$E$20)/SUM($C$20:$G$20),IF(B14=$A$21,SUM($C$21:$E$21)/SUM($C$21:$G$21),SUM($C$22:$E$22)/SUM($C$22:$G$22)))","v":{"$error":"#NAME?"}},{"$f":"IF(B14=$A$20,SUM($F$20:$G$20)/SUM($C$20:$G$20),IF(B14=$A$21,SUM($F$21:$G$21)/SUM($C$21:$G$21),SUM($F$22:$G$22)/SUM($C$22:$G$22)))","v":{"$error":"#NAME?"}}]
[{"$f":"A8","v":"Carry-over amounts"},"Volume and Customer No",{"$f":"IF(B15=$A$20,SUM($C$20:$E$20)/SUM($C$20:$G$20),IF(B15=$A$21,SUM($C$21:$E$21)/SUM($C$21:$G$21),SUM($C$22:$E$22)/SUM($C$22:$G$22)))","v":{"$error":"#NAME?"}},{"$f":"IF(B15=$A$20,SUM($F$20:$G$20)/SUM($C$20:$G$20),IF(B15=$A$21,SUM($F$21:$G$21)/SUM($C$21:$G$21),SUM($F$22:$G$22)/SUM($C$22:$G$22)))","v":{"$error":"#NAME?"}}]
[{"$f":"A9","v":"Benchmark Tax liability"},"Volume and Customer No",{"$f":"IF(B16=$A$20,SUM($C$20:$E$20)/SUM($C$20:$G$20),IF(B16=$A$21,SUM($C$21:$E$21)/SUM($C$21:$G$21),SUM($C$22:$E$22)/SUM($C$22:$G$22)))","v":{"$error":"#NAME?"}},{"$f":"IF(B16=$A$20,SUM($F$20:$G$20)/SUM($C$20:$G$20),IF(B16=$A$21,SUM($F$21:$G$21)/SUM($C$21:$G$21),SUM($F$22:$G$22)/SUM($C$22:$G$22)))","v":{"$error":"#NAME?"}}]
[]
["Allocators (Percentages)","Total","Residential 1","Residential 2","Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Town","Demand-Whyal"]
["Assets",{"$f":"SUM(C19:P19)","v":6.0259378663977771E-2},null,null,null,null,null,{"$f":"'DORC Calculations'!$B$18/'DORC Calculations'!$B$26*'DORC Calculations'!$I$18","v":1.6771945389136213E-2},{"$f":"'DORC Calculations'!$B$19/'DORC Calculations'!$B$26*'DORC Calculations'!$I$18","v":2.9213345486637256E-2},{"$f":"'DORC Calculations'!$B$20/'DORC Calculations'!$B$26*'DORC Calculations'!$I$18","v":8.9740098265497694E-3},{"$f":"'DORC Calculations'!$B$21/'DORC Calculations'!$B$26*'DORC Calculations'!$I$18","v":3.6046763178581242E-4},{"$f":"'DORC Calculations'!$B$22/'DORC Calculations'!$B$26*'DORC Calculations'!$I$18","v":1.8704804440789501E-3},{"$f":"'DORC Calculations'!$B$23/'DORC Calculations'!$B$26*'DORC Calculations'!$I$18","v":3.1192372367813432E-4},{"$f":"'DORC Calculations'!$B$24/'DORC Calculations'!$B$26*'DORC Calculations'!$I$18","v":2.3295616069848946E-3},null,{"$f":"'DORC Calculations'!$B$25/'DORC Calculations'!$B$26*'DORC Calculations'!$I$18","v":4.2764455512674088E-4}]
["Customer Number",{"$f":"SUM(C20:P20)","v":{"$error":"#NAME?"}},{"$f":"C28/SUM($C$28:$Q$28)","v":{"$error":"#NAME?"}},{"$f":"D28/SUM($C$28:$Q$28)","v":{"$error":"#NAME?"}},{"$f":"E28/SUM($C$28:$Q$28)","v":{"$error":"#NAME?"}},{"$f":"F28/SUM($C$28:$Q$28)","v":{"$error":"#NAME?"}},{"$f":"G28/SUM($C$28:$Q$28)","v":{"$error":"#NAME?"}},{"$f":"H28/SUM($C$28:$P$28)","v":{"$error":"#NAME?"}},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},null,{"$f":"P28/SUM($C$28:$P$28)","v":{"$error":"#NAME?"}}]
["Volume",{"$f":"SUM(C21:P21)","v":1},{"$f":"C29/SUM($C$29:$Q$29)","v":0.34058678229365041},{"$f":"D29/SUM($C$29:$Q$29)","v":0},{"$f":"E29/SUM($C$29:$Q$29)","v":0},{"$f":"F29/SUM($C$29:$Q$29)","v":0.14054534033258007},{"$f":"G29/SUM($C$29:$Q$29)","v":0},{"$f":"H29/SUM($B$29:$P$29)","v":9.6273499758694758E-2},{"$f":"I29/SUM($C$29:$P$29)","v":0.35598038616480637},3.1443315758097022E-2,8.131433835816866E-4,2.0280236099983685E-2,5.3385886690253126E-3,8.2632214749890232E-3,null,{"$f":"P29/SUM($C$29:$P$29)","v":4.7548606459166075E-4}]
["Volume and Customer No",{"$f":"SUM(C22:P22)","v":{"$error":"#NAME?"}},{"$f":"$B$23*C20+$B$24*C21","v":{"$error":"#NAME?"}},{"$f":"$B$23*D20+$B$24*D21","v":{"$error":"#NAME?"}},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},null,{"$error":"#NAME?"}]
["% Volume",0.5]
["% Customer",0.5]
[]
["Allocators (Amounts)",null,{"$f":"C18","v":"Residential 1"},{"$f":"D18","v":"Residential 2"},"Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Town","Demand-Whyal"]
["Assets",null,0,0,0,0,0,{"$f":"'DORC Calculations'!B18","v":17468737.972856034},{"$f":"'DORC Calculations'!B19","v":30427017.604477495},{"$f":"'DORC Calculations'!B20","v":9346836.1951246988},{"$f":"'DORC Calculations'!B21","v":375443.30495143664},{"$f":"'DORC Calculations'!B22","v":1948189.789726557},{"$f":"'DORC Calculations'!B23","v":324882.63406702562},{"$f":"'DORC Calculations'!B24","v":2426343.5373694836},null,{"$f":"'DORC Calculations'!B25","v":445411.10203390452}]
["Customer Number",null,{"$f":"IFERROR(AVERAGE('Connection Numbers Inputs'!$B5:$B9),0)","v":{"$error":"#NAME?"}},{"$f":"IFERROR(AVERAGE('Connection Numbers Inputs'!$C5:$C9),0)","v":{"$error":"#NAME?"}},{"$f":"IFERROR(AVERAGE('Connection Numbers Inputs'!$D5:$D9),0)","v":{"$error":"#NAME?"}},{"$f":"IFERROR(AVERAGE('Connection Numbers Inputs'!$E5:$E9),0)","v":{"$error":"#NAME?"}},{"$f":"IFERROR(AVERAGE('Connection Numbers Inputs'!$F5:$F9),0)","v":{"$error":"#NAME?"}},{"$f":"IFERROR(AVERAGE('Connection Numbers Inputs'!$G5:$G9),0)","v":{"$error":"#NAME?"}},{"$f":"IFERROR(AVERAGE('Connection Numbers Inputs'!$H5:$H9),0)","v":{"$error":"#NAME?"}},{"$f":"IFERROR(AVERAGE('Connection Numbers Inputs'!$I5:$I9),0)","v":{"$error":"#NAME?"}},{"$f":"IFERROR(AVERAGE('Connection Numbers Inputs'!$J5:$J9),0)","v":{"$error":"#NAME?"}},{"$f":"IFERROR(AVERAGE('Connection Numbers Inputs'!$K5:$K9),0)","v":{"$error":"#NAME?"}},{"$f":"IFERROR(AVERAGE('Connection Numbers Inputs'!$L5:$L9),0)","v":{"$error":"#NAME?"}},{"$f":"IFERROR(AVERAGE('Connection Numbers Inputs'!$M5:$M9),0)","v":{"$error":"#NAME?"}},null,{"$f":"IFERROR(AVERAGE('Connection Numbers Inputs'!$O5:$O9),0)","v":{"$error":"#NAME?"}}]
["Volume",null,{"$f":"IF(C33=\"Demand\",C56,AVERAGE('Volume Inputs'!B$65:B$69))","v":7664322.5573218493},{"$f":"IF(D33=\"Demand\",D56,AVERAGE('Volume Inputs'!C$65:C$69))","v":0},{"$f":"IF(E33=\"Demand\",E56,AVERAGE('Volume Inputs'!D$65:D$69))","v":0},{"$f":"IF(F33=\"Demand\",F56,AVERAGE('Volume Inputs'!E$65:E$69))","v":3162732.3144582049},{"$f":"IF(G33=\"Demand\",G56,AVERAGE('Volume Inputs'!F$65:F$69))","v":0},{"$f":"IF(H33=\"Demand\",H56,AVERAGE('Volume Inputs'!G$65:G$69))","v":2166470.3219066761},{"$f":"IF(I33=\"Demand\",I56,AVERAGE('Volume Inputs'!H$65:H$69))","v":8010729.2634002287},{"$f":"IF(J33=\"Demand\",J56,AVERAGE('Volume Inputs'!I$65:I$69))","v":707578},{"$f":"IF(K33=\"Demand\",K56,AVERAGE('Volume Inputs'!J$65:J$69))","v":18298.400000000001},{"$f":"IF(L33=\"Demand\",L56,AVERAGE('Volume Inputs'!K$65:K$69))","v":456372},{"$f":"IF(M33=\"Demand\",M56,AVERAGE('Volume Inputs'!L$65:L$69))","v":120135.8},{"$f":"IF(N33=\"Demand\",N56,AVERAGE('Volume Inputs'!M$65:M$69))","v":185949.65524029205},null,{"$f":"IF(P33=\"Demand\",P56,AVERAGE('Volume Inputs'!O$65:O$69))","v":10700}]
[]
["Calculation of Consumption (GJ)"]
["Total MDQ",null,{"$f":"C26","v":"Residential 1"},{"$f":"D26","v":"Residential 2"},"Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Town","Demand-Whyal"]
["Demand Tariff",null,{"$f":"'General Inputs'!C20","v":"Non-demand"},{"$f":"'General Inputs'!C21","v":"Non-demand"},{"$f":"'General Inputs'!C22","v":"Non-demand"},{"$f":"'General Inputs'!C23","v":"Non-demand"},{"$f":"'General Inputs'!C24","v":"Non-demand"},{"$f":"'General Inputs'!C26","v":"Demand"},{"$f":"'General Inputs'!C25","v":"Demand"},{"$f":"'General Inputs'!C27","v":"Demand"},{"$f":"'General Inputs'!C29","v":"Demand"},{"$f":"'General Inputs'!C28","v":"Demand"},{"$f":"'General Inputs'!C30","v":"Demand"},{"$f":"'General Inputs'!C31","v":"Demand"},{"$f":"'General Inputs'!C33","v":"Demand"},{"$f":"'General Inputs'!C32","v":"Demand"}]
["2006/07",null,{"$f":"IF($C33=\"Demand\",'Volume Inputs'!B65,0)","v":0},{"$f":"IF($D33=\"Demand\",'Volume Inputs'!C65,0)","v":0},{"$f":"IF($E33=\"Demand\",'Volume Inputs'!D65,0)","v":0},{"$f":"IF($F33=\"Demand\",'Volume Inputs'!E65,0)","v":0},{"$f":"IF($G33=\"Demand\",'Volume Inputs'!F65,0)","v":0},{"$f":"IF($H33=\"Demand\",'Volume Inputs'!G65,0)","v":10393.017966939004},{"$f":"IF($I33=\"Demand\",'Volume Inputs'!H65,0)","v":44079.392224810916},{"$f":"IF($J33=\"Demand\",'Volume Inputs'!I65,0)","v":3860},{"$f":"IF($K33=\"Demand\",'Volume Inputs'!J65,0)","v":62},{"$f":"IF($L33=\"Demand\",'Volume Inputs'!K65,0)","v":1316},{"$f":"IF($M33=\"Demand\",'Volume Inputs'!L65,0)","v":750},{"$f":"IF($N33=\"Demand\",'Volume Inputs'!M65,0)","v":916.83923072689004},null,{"$f":"IF($P33=\"Demand\",'Volume Inputs'!O65,0)","v":57}]
["2007/08",null,{"$f":"IF($C33=\"Demand\",'Volume Inputs'!B66,0)","v":0},{"$f":"IF($D33=\"Demand\",'Volume Inputs'!C66,0)","v":0},{"$f":"IF($E33=\"Demand\",'Volume Inputs'!D66,0)","v":0},{"$f":"IF($F33=\"Demand\",'Volume Inputs'!E66,0)","v":0},{"$f":"IF($G33=\"Demand\",'Volume Inputs'!F66,0)","v":0},{"$f":"IF($H33=\"Demand\",'Volume Inputs'!G66,0)","v":10365.946629670852},{"$f":"IF($I33=\"Demand\",'Volume Inputs'!H66,0)","v":50808},{"$f":"IF($J33=\"Demand\",'Volume Inputs'!I66,0)","v":3960},{"$f":"IF($K33=\"Demand\",'Volume Inputs'!J66,0)","v":62},{"$f":"IF($L33=\"Demand\",'Volume Inputs'!K66,0)","v":1316},{"$f":"IF($M33=\"Demand\",'Volume Inputs'!L66,0)","v":750},{"$f":"IF($N33=\"Demand\",'Volume Inputs'!M66,0)","v":947.65988786872765},null,{"$f":"IF($P33=\"Demand\",'Volume Inputs'!O66,0)","v":57}]
["2008/09",null,{"$f":"IF($C33=\"Demand\",'Volume Inputs'!B67,0)","v":0},{"$f":"IF($D33=\"Demand\",'Volume Inputs'!C67,0)","v":0},{"$f":"IF($E33=\"Demand\",'Volume Inputs'!D67,0)","v":0},{"$f":"IF($F33=\"Demand\",'Volume Inputs'!E67,0)","v":0},{"$f":"IF($G33=\"Demand\",'Volume Inputs'!F67,0)","v":0},{"$f":"IF($H33=\"Demand\",'Volume Inputs'!G67,0)","v":10312.473105618095},{"$f":"IF($I33=\"Demand\",'Volume Inputs'!H67,0)","v":52147.339415770504},{"$f":"IF($J33=\"Demand\",'Volume Inputs'!I67,0)","v":4060},{"$f":"IF($K33=\"Demand\",'Volume Inputs'!J67,0)","v":62},{"$f":"IF($L33=\"Demand\",'Volume Inputs'!K67,0)","v":1316},{"$f":"IF($M33=\"Demand\",'Volume Inputs'!L67,0)","v":750},{"$f":"IF($N33=\"Demand\",'Volume Inputs'!M67,0)","v":980.59221700751345},null,{"$f":"IF($P33=\"Demand\",'Volume Inputs'!O67,0)","v":57}]
["2009/10",null,{"$f":"IF($C33=\"Demand\",'Volume Inputs'!B68,0)","v":0},{"$f":"IF($D33=\"Demand\",'Volume Inputs'!C68,0)","v":0},{"$f":"IF($E33=\"Demand\",'Volume Inputs'!D68,0)","v":0},{"$f":"IF($F33=\"Demand\",'Volume Inputs'!E68,0)","v":0},{"$f":"IF($G33=\"Demand\",'Volume Inputs'!F68,0)","v":0},{"$f":"IF($H33=\"Demand\",'Volume Inputs'!G68,0)","v":10272.589171356292},{"$f":"IF($I33=\"Demand\",'Volume Inputs'!H68,0)","v":52351.402584907002},{"$f":"IF($J33=\"Demand\",'Volume Inputs'!I68,0)","v":4160},{"$f":"IF($K33=\"Demand\",'Volume Inputs'!J68,0)","v":62},{"$f":"IF($L33=\"Demand\",'Volume Inputs'!K68,0)","v":1316},{"$f":"IF($M33=\"Demand\",'Volume Inputs'!L68,0)","v":750},{"$f":"IF($N33=\"Demand\",'Volume Inputs'!M68,0)","v":1015.7808989851313},null,{"$f":"IF($P33=\"Demand\",'Volume Inputs'!O68,0)","v":57}]
["2010/11",null,{"$f":"IF($C33=\"Demand\",'Volume Inputs'!B69,0)","v":0},{"$f":"IF($D33=\"Demand\",'Volume Inputs'!C69,0)","v":0},{"$f":"IF($E33=\"Demand\",'Volume Inputs'!D69,0)","v":0},{"$f":"IF($F33=\"Demand\",'Volume Inputs'!E69,0)","v":0},{"$f":"IF($G33=\"Demand\",'Volume Inputs'!F69,0)","v":0},{"$f":"IF($H33=\"Demand\",'Volume Inputs'!G69,0)","v":10236.289221749568},{"$f":"IF($I33=\"Demand\",'Volume Inputs'!H69,0)","v":51302.028944523001},{"$f":"IF($J33=\"Demand\",'Volume Inputs'!I69,0)","v":4260},{"$f":"IF($K33=\"Demand\",'Volume Inputs'!J69,0)","v":62},{"$f":"IF($L33=\"Demand\",'Volume Inputs'!K69,0)","v":1316},{"$f":"IF($M33=\"Demand\",'Volume Inputs'!L69,0)","v":750},{"$f":"IF($N33=\"Demand\",'Volume Inputs'!M69,0)","v":1053.3805274263398},null,{"$f":"IF($P33=\"Demand\",'Volume Inputs'!O69,0)","v":57}]
["2011/12",null,{"$f":"IF($C33=\"Demand\",'Volume Inputs'!B70,0)","v":0},{"$f":"IF($D33=\"Demand\",'Volume Inputs'!C70,0)","v":0},{"$f":"IF($E33=\"Demand\",'Volume Inputs'!D70,0)","v":0},{"$f":"IF($F33=\"Demand\",'Volume Inputs'!E70,0)","v":0},{"$f":"IF($G33=\"Demand\",'Volume Inputs'!F70,0)","v":0},{"$f":"IF($H33=\"Demand\",'Volume Inputs'!G70,0)","v":11626.8},{"$f":"IF($I33=\"Demand\",'Volume Inputs'!H70,0)","v":31548.800000000003},{"$f":"IF($J33=\"Demand\",'Volume Inputs'!I70,0)","v":2901.7},{"$f":"IF($K33=\"Demand\",'Volume Inputs'!J70,0)","v":120.59},{"$f":"IF($L33=\"Demand\",'Volume Inputs'!K70,0)","v":3290.6},{"$f":"IF($M33=\"Demand\",'Volume Inputs'!L70,0)","v":443.45},{"$f":"IF($N33=\"Demand\",'Volume Inputs'!M70,0)","v":895.01},null,{"$f":"IF($P33=\"Demand\",'Volume Inputs'!O70,0)","v":50}]
["2012/13",null,{"$f":"IF($C33=\"Demand\",'Volume Inputs'!B71,0)","v":0},{"$f":"IF($D33=\"Demand\",'Volume Inputs'!C71,0)","v":0},{"$f":"IF($E33=\"Demand\",'Volume Inputs'!D71,0)","v":0},{"$f":"IF($F33=\"Demand\",'Volume Inputs'!E71,0)","v":0},{"$f":"IF($G33=\"Demand\",'Volume Inputs'!F71,0)","v":0},{"$f":"IF($H33=\"Demand\",'Volume Inputs'!G71,0)","v":11436.5},{"$f":"IF($I33=\"Demand\",'Volume Inputs'!H71,0)","v":30723.300000000003},{"$f":"IF($J33=\"Demand\",'Volume Inputs'!I71,0)","v":2968.7},{"$f":"IF($K33=\"Demand\",'Volume Inputs'!J71,0)","v":121.03},{"$f":"IF($L33=\"Demand\",'Volume Inputs'!K71,0)","v":3286.3},{"$f":"IF($M33=\"Demand\",'Volume Inputs'!L71,0)","v":446.86},{"$f":"IF($N33=\"Demand\",'Volume Inputs'!M71,0)","v":888.28},null,{"$f":"IF($P33=\"Demand\",'Volume Inputs'!O71,0)","v":50}]
["2013/14",null,{"$f":"IF($C33=\"Demand\",'Volume Inputs'!B72,0)","v":0},{"$f":"IF($D33=\"Demand\",'Volume Inputs'!C72,0)","v":0},{"$f":"IF($E33=\"Demand\",'Volume Inputs'!D72,0)","v":0},{"$f":"IF($F33=\"Demand\",'Volume Inputs'!E72,0)","v":0},{"$f":"IF($G33=\"Demand\",'Volume Inputs'!F72,0)","v":0},{"$f":"IF($H33=\"Demand\",'Volume Inputs'!G72,0)","v":11138.799999999997},{"$f":"IF($I33=\"Demand\",'Volume Inputs'!H72,0)","v":28946.800000000003},{"$f":"IF($J33=\"Demand\",'Volume Inputs'!I72,0)","v":3001.8},{"$f":"IF($K33=\"Demand\",'Volume Inputs'!J72,0)","v":120.85},{"$f":"IF($L33=\"Demand\",'Volume Inputs'!K72,0)","v":3233.6},{"$f":"IF($M33=\"Demand\",'Volume Inputs'!L72,0)","v":447.98},{"$f":"IF($N33=\"Demand\",'Volume Inputs'!M72,0)","v":869.59},null,{"$f":"IF($P33=\"Demand\",'Volume Inputs'!O72,0)","v":50}]
["2014/15",null,{"$f":"IF($C33=\"Demand\",'Volume Inputs'!B73,0)","v":0},{"$f":"IF($D33=\"Demand\",'Volume Inputs'!C73,0)","v":0},{"$f":"IF($E33=\"Demand\",'Volume Inputs'!D73,0)","v":0},{"$f":"IF($F33=\"Demand\",'Volume Inputs'!E73,0)","v":0},{"$f":"IF($G33=\"Demand\",'Volume Inputs'!F73,0)","v":0},{"$f":"IF($H33=\"Demand\",'Volume Inputs'!G73,0)","v":11212.5},{"$f":"IF($I33=\"Demand\",'Volume Inputs'!H73,0)","v":28986.2},{"$f":"IF($J33=\"Demand\",'Volume Inputs'!I73,0)","v":3063.8999999999996},{"$f":"IF($K33=\"Demand\",'Volume Inputs'!J73,0)","v":121.01},{"$f":"IF($L33=\"Demand\",'Volume Inputs'!K73,0)","v":3213.5},{"$f":"IF($M33=\"Demand\",'Volume Inputs'!L73,0)","v":454.75},{"$f":"IF($N33=\"Demand\",'Volume Inputs'!M73,0)","v":864.73},null,{"$f":"IF($P33=\"Demand\",'Volume Inputs'!O73,0)","v":50}]
["2015/16",null,{"$f":"IF($C33=\"Demand\",'Volume Inputs'!B74,0)","v":0},{"$f":"IF($D33=\"Demand\",'Volume Inputs'!C74,0)","v":0},{"$f":"IF($E33=\"Demand\",'Volume Inputs'!D74,0)","v":0},{"$f":"IF($F33=\"Demand\",'Volume Inputs'!E74,0)","v":0},{"$f":"IF($G33=\"Demand\",'Volume Inputs'!F74,0)","v":0},{"$f":"IF($H33=\"Demand\",'Volume Inputs'!G74,0)","v":11328.600000000002},{"$f":"IF($I33=\"Demand\",'Volume Inputs'!H74,0)","v":29643.199999999997},{"$f":"IF($J33=\"Demand\",'Volume Inputs'!I74,0)","v":3142.8000000000006},{"$f":"IF($K33=\"Demand\",'Volume Inputs'!J74,0)","v":121.44},{"$f":"IF($L33=\"Demand\",'Volume Inputs'!K74,0)","v":3214.6},{"$f":"IF($M33=\"Demand\",'Volume Inputs'!L74,0)","v":463.75},{"$f":"IF($N33=\"Demand\",'Volume Inputs'!M74,0)","v":865.62},null,{"$f":"IF($P33=\"Demand\",'Volume Inputs'!O74,0)","v":50}]
[]
["Calculated Consumption",null,{"$f":"C32","v":"Residential 1"},{"$f":"D32","v":"Residential 2"},"Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Town","Demand-Whyal"]
[{"$f":"A34","v":"2006/07"},null,{"$f":"C34/$B$59*$B$60","v":0},0,0,0,0,2078603.5933878005,8815878.444962183,{"$f":"J34/$B$59*$B$60","v":772000},{"$f":"K34/$B$59*$B$60","v":12400},{"$f":"L34/$B$59*$B$60","v":263200},{"$f":"M34/$B$59*$B$60","v":150000},{"$f":"N34/$B$59*$B$60","v":183367.84614537802},null,{"$f":"P34/$B$59*$B$60","v":11400}]
[{"$f":"A35","v":"2007/08"},null,{"$f":"C35/$B$59*$B$60","v":0},0,0,0,0,2073189.3259341703,10161600,792000,12400,263200,150000,189531.97757374553,null,{"$f":"P35/$B$59*$B$60","v":11400}]
["2008/09",null,{"$f":"C36/$B$59*$B$60","v":0},0,0,0,0,2062494.6211236189,10429467.8831541,812000,12400,263200,150000,196118.44340150268,null,11400]
["2009/10",null,{"$f":"C37/$B$59*$B$60","v":0},0,0,0,0,2054517.8342712584,10470280.516981399,832000,12400,263200,150000,203156.17979702624,null,11400]
["2010/11",null,{"$f":"C38/$B$59*$B$60","v":0},0,0,0,0,2047257.8443499135,10260405.7889046,851999.99999999988,12400,263200,150000,210676.10548526794,null,11400]
["2011/12",null,{"$f":"C39/$B$59*$B$60","v":0},0,0,0,0,2325359.9999999995,6309760.0000000009,580340,24118,658120,88689.999999999985,179002,null,10000]
["2012/13",null,{"$f":"C40/$B$59*$B$60","v":0},0,0,0,0,2287300,6144660.0000000009,593739.99999999988,24206,657260,89372,177656,null,10000]
["2013/14",null,{"$f":"C41/$B$59*$B$60","v":0},0,0,0,0,2227759.9999999995,5789360,600360.00000000012,24169.999999999996,646720,89596,173918,null,10000]
["2014/15",null,{"$f":"C42/$B$59*$B$60","v":0},0,0,0,0,2242500,5797240,612779.99999999988,24202,642699.99999999988,90950,172946,null,10000]
["2015/16",null,{"$f":"C43/$B$59*$B$60","v":0},0,0,0,0,2265720.0000000005,5928639.9999999991,628560.00000000012,24288,642919.99999999988,92750,173124,null,10000]
["Average",null,{"$f":"AVERAGE(C46:C55)","v":0},{"$f":"AVERAGE(D46:D55)","v":0},0,0,0,2166470.3219066761,8010729.2634002287,707578,18298.400000000001,456372,120135.8,185949.65524029205,null,10700]
[]
["Other Calculation of Consumption Inputs"]
["Load factor",1.3]
["Days",260]

{"sheet":"PTRM Inputs","index":8,"n_rows":26,"n_cols":9,"rows_kept":26,"cut":false,"hidden":false,"merged":[[0,0,0,14],[13,0,13,1]]}
["SA PTRM Inputs"]
[]
["Building block components ($M NOMINAL)","2011-12","2012-13","2013-14","2014-15","2015-16","TOTAL"]
[]
["Return on capital",109.7,121.1,133.30000000000001,144.80000000000001,157.4,{"$f":"SUM(B5:F5)","v":666.30000000000007}]
["Return of capital",2.5,3.4,4.4000000000000004,4.5,5.0999999999999996,19.899999999999999]
["O&M",71,73.7,75.2,76.7,76.900000000000006,373.5]
["Carry-over amounts",11.7,3.4,3.4,1.9,0,20.399999999999999]
["Benchmark Tax liability",18.8,16.5,17,16.5,16.2,85]
["TOTAL REVENUE",{"$f":"SUM(B5:B9)","v":213.7},{"$f":"SUM(C5:C9)","v":218.1},{"$f":"SUM(D5:D9)","v":233.30000000000004},{"$f":"SUM(E5:E9)","v":244.4},{"$f":"SUM(F5:F9)","v":255.6},1165.0999999999999,null," "]
["TOTAL REVENUE (SMOOTHED)",177.9,213.3,247.7,259.3,270.10000000000002,1168.3000000000002]
[]
[]
["PTRM Opening RAB 2011-12"]
["Asset Class Name","Opening Asset Value"]
["Mains & Inlets",434.75134411640096]
["Meters",22.39789983358612]
["Regulators/Odorising",203.22883269043834]
["Telemetry",0]
["Mains",253.78168055497957]
["Inlets",40.76174794446306]
["Meters",65.810285206752397]
["Telemetry",4.3302290369565624]
["IT Systems",3.9338866633090399]
["Other Distribution Equipment",7.171477391926004]
["Other Assets",5.3777425172472242]

{"sheet":"DORC Calculations","index":9,"n_rows":366,"n_cols":16,"rows_kept":366,"cut":false,"hidden":false,"merged":[[354,0,354,8],[1,0,1,8],[0,0,0,8]]}
["DORC Inputs and Calculations"]
["Tariff D DORC Calculations"]
[]
["Tariff D Summary - 1 July 1999 DORC","Total","Total Cost","Total Inlet","Total Meter and RDL","Total Gate Station","Average Length","Average Cost/m"]
["Central",{"$f":"SUMIF($B$31:$B$189,A5,$J$31:$J$189)","v":10945456.405142499},{"$f":"SUMIF($B$31:$B$189,A5,$F$31:$F$189)","v":8459300.7586881574},{"$f":"SUMIF($B$31:$B$189,$A5,$G$31:$G$189)","v":733200},{"$f":"SUMIF($B$31:$B$189,$A5,$H$31:$H$189)","v":1043068},{"$f":"SUMIF($B$31:$B$189,$A5,$I$31:$I$189)","v":709887.64645434229},14567.768518518518,13.285864184262019]
["Northern",{"$f":"SUMIF($B$31:$B$189,A6,$J$31:$J$189)+SUMIF($B$31:$B$189,\"North Western\",$J$31:$J$189)","v":19064777.046046797},{"$f":"SUMIF($B$31:$B$189,A6,$F$31:$F$189)+SUMIF($B$31:$B$189,\"NORTH WESTERN\",$F$31:$F$189)","v":14808805.077328676},{"$f":"SUMIF($B$31:$B$189,$A6,$G$31:$G$189)+SUMIF($B$31:$B$189,\"NORTH WESTERN\",$G$31:$G$189)","v":1297200},{"$f":"SUMIF($B$31:$B$189,$A6,$H$31:$H$189)+SUMIF($B$31:$B$189,\"NORTH WESTERN\",$H$31:$H$189)","v":1734068},{"$f":"SUMIF($B$31:$B$189,$A6,$I$31:$I$189)+SUMIF($B$31:$B$189,\"NORTH WESTERN\",$I$31:$I$189)","v":1224703.9687181222}]
["Southern",5856484.2096042437,4716231.9454083918,352500,472183,315569.26419585157]
["Peterborough",235243,175560,14100,15583,30000]
["Port Pirie",1220685,1034099.9999999999,42300,69285,75000]
["Riverland",203563,173880,14100,15583,0]
["South East",1520283.6892649862,1232504.9979798403,84600,93498,109680.69128514596]
["Whyalla",279083,248400,14100,15583,1000]
["Total",{"$f":"SUM(B5:B12)","v":39325575.350058518}]
[]
["Checks",{"$f":"B13-J190","v":0}]
[]
["Tariff D Summary - Closing 2010-11 RAB","Total","Total Cost","Total Inlet","Total Meter and RDL","Total Gate Station","Total 2010-11 RAB","Total 1 July 1999 RAB","Tariff D % (based on 1999-00)"]
["Central",{"$f":"SUMIF($B$193:$B$351,A18,$J$193:$J$351)","v":17468737.972856034},{"$f":"SUMIF($B$193:$B$351,A18,$F$193:$F$351)","v":13500881.362761391},{"$f":"SUMIF($B$193:$B$351,$A18,$G$193:$G$351)","v":1170173.1026657249},{"$f":"SUMIF($B$193:$B$351,$A18,$H$193:$H$351)","v":1664716.4727923255},{"$f":"SUMIF($B$193:$B$351,$A18,$I$193:$I$351)","v":1132967.0346365897},{"$f":"SUM('PTRM Inputs'!B16:B26)*1000000","v":1041545125.9560593},652605058.697142,{"$f":"B13/H18","v":6.0259378663977771E-2}]
["Northern",{"$f":"SUMIF($B$193:$B$351,A19,$J$193:$J$351)+SUMIF($B$193:$B$351,\"North Western\",$J$193:$J$351)","v":30427017.604477495},{"$f":"SUMIF($B$193:$B$351,A19,$F$193:$F$351)+SUMIF($B$193:$B$351,\"NORTH WESTERN\",$F$193:$F$351)","v":23634568.172544517},{"$f":"SUMIF($B$193:$B$351,$A19,$G$193:$G$351)+SUMIF($B$193:$B$351,\"NORTH WESTERN\",$G$193:$G$351)","v":2070306.2585624352},{"$f":"SUMIF($B$193:$B$351,$A19,$H$193:$H$351)+SUMIF($B$193:$B$351,\"NORTH WESTERN\",$H$193:$H$351)","v":2767539.1868430823},{"$f":"SUMIF($B$193:$B$351,$A19,$I$193:$I$351)+SUMIF($B$193:$B$351,\"NORTH WESTERN\",$I$193:$I$351)","v":1954603.986527432}]
["Southern",9346836.1951246988,7527015.5052506151,562583.22243544518,753594.98927442799,503642.4781642115]
["Peterborough",375443.30495143664,280190.38448444469,22503.32889741781,24870.168383578839,47879.423185995336]
["Port Pirie",1948189.789726557,1650403.7172212589,67509.986692253427,110577.52784805623,119698.55796498833]
["Riverland",324882.63406702562,277509.13678602898,22503.32889741781,24870.168383578839,0]
["South East",2426343.5373694836,1967054.2792377032,135019.97338450685,149221.01030147303,175048.27444580046]
["Whyalla",445411.10203390452,396441.62398004136,22503.32889741781,24870.168383578839,1595.9807728665112]
["Total",{"$f":"SUM(B18:B25)","v":62762862.140606634}]
[]
["Checks",{"$f":"B26-J352","v":0}]
[]
["Individual Customers as at 1 July 1999","District Name","Consumption","Flow (MDQ)","Length","Cost","Inlet","Meter and RDL","Gate Station","Total"]
["Adelaide Aquatic Centre","Central",43127.635335057596,258,15749.8,47695.376674242187,14100,15583,4174.5590313197035,{"$f":"SUM(F31:I31)","v":81552.935705561889}]
["Adelaide Festival Centre Trust","Central",9515.3438996462555,73,{"$f":"$G$5","v":14567.768518518518},{"$f":"E32*$H$5","v":193545.39400480496},{"$f":"P132","v":14100},{"$f":"P136","v":15583},{"$f":"P141","v":4175},{"$f":"SUM(F32:I32)","v":227403.39400480496}]
["Arnotts Biscuits","Central",67493.056746470247,295,20402,96098.134401434276,14100,30583,4174.5590313197035,144955.69343275399]
["Ashford Community Hospital Inc","Central",18409.792945020989,131,20901,66028.467905824247,14100,15583,4174.5590313197035,99886.02693714395]
["Asphalt SA","Central",21379.6301611009,146,{"$f":"$G$5","v":14567.768518518518},{"$f":"E35*$H$5","v":193545.39400480496},{"$f":"P132","v":14100},{"$f":"P136","v":15583},{"$f":"P141","v":4175},227403.39400480496]
["Australia Post","Central",7945.7593973756502,84,22249.8,114364.73439170944,14100,15583,4174.5590313197035,148222.29342302916]
["Brown Wood Panels Pty Ltd","Central",20497.096099303111,125,23602,64923.051450739156,14100,15583,4174.5590313197035,98780.610482058852]
["Buttercup Bakeries - Forestville","Central",34915.566064549188,143,21401,122293.10307018369,14100,15583,4174.5590313197035,156150.6621015034]
["Castalloy Manufacturing Pty Ltd (ION Automotive: Nth Plympton)","Central",336502.68299999996,1300,23202,453743.10756604932,28200,53702,78749.851940005043,614394.95950605441]
["Coca Cola Bottlers Adelaide","Central",25398.214081801201,134,14601,32214.39821612895,14100,15583,4174.5590313197035,66071.957247448649]
["CSR Building Materials","Central",368560.90067061078,1300,22701,864275.98512770666,28200,53702,78749.851940005043,1024927.8370677117]
["Dept For The Arts","Central",11921.2485869136,68,19449.8,39529.186666383634,14100,15583,4174.5590313197035,73386.745697703343]
["Hallet Brick (Austral Bricks)","Central",214414.52148781798,800,{"$f":"$G$5","v":14567.768518518518},{"$f":"E43*$H$5","v":193545.39400480496},{"$f":"P133","v":28200},{"$f":"P138","v":53702},{"$f":"P142","v":78750},354197.39400480496]
["Healthscope Ltd","Central",27658.835195549644,187,{"$f":"$G$5","v":14567.768518518518},{"$f":"E44*$H$5","v":193545.39400480496},{"$f":"P132","v":14100},{"$f":"P136","v":15583},{"$f":"P141","v":4175},227403.39400480496]
["Hilton International Adelaide","Central",17136.522049238978,78,21049.8,57544.946426840281,14100,15583,4174.5590313197035,91402.505458159983]
["Hyatt Regency Adelaide","Central",12258.204905315069,63,20049.8,56422.418052261797,14100,15583,4174.5590313197035,90279.9770835815]
["Inghams Enterprises Pty Ltd","Central",21065.521155654009,90,{"$f":"$G$5","v":14567.768518518518},{"$f":"E47*$H$5","v":193545.39400480496},{"$f":"P132","v":14100},{"$f":"P136","v":15583},{"$f":"P141","v":4175},227403.39400480496]
["International Linen Service Pty Ltd","Central",68467.858768940292,280,17102,166541.66059305237,14100,15583,4174.5590313197035,200399.21962437208]
["Julia Farr Services","Central",16301.910631877685,149,26049.8,310200.01780566981,14100,15583,4174.5590313197035,344057.57683698949]
["Myer Centre Adelaide Intro International Ltd","Central",9186.9302471317769,76,{"$f":"$G$5","v":14567.768518518518},{"$f":"E50*$H$5","v":193545.39400480496},{"$f":"P132","v":14100},{"$f":"P136","v":15583},{"$f":"P141","v":4175},227403.39400480496]
["North Eastern Community Hospital Inc","Central",8964.9635188614793,75,13910,385214.20521470916,14100,15583,4174.5590313197035,419071.76424602885]
["North Eastern Community Hospital Inc","Central",10782.672829384977,50,{"$f":"$G$5","v":14567.768518518518},{"$f":"E52*$H$5","v":193545.39400480496},{"$f":"P132","v":14100},{"$f":"P136","v":15583},{"$f":"P141","v":4175},227403.39400480496]
["Novotel Adelaide On Hindley","Central",5761.7496994328876,null,{"$f":"$G$5","v":14567.768518518518},{"$f":"E53*$H$5","v":193545.39400480496},{"$f":"P132","v":14100},{"$f":"P136","v":15583},{"$f":"P141","v":4175},227403.39400480496]
["Performance Wheel Co Pty Ltd","Central",37767.353056243948,175,{"$f":"$G$5","v":14567.768518518518},{"$f":"E54*$H$5","v":193545.39400480496},{"$f":"P132","v":14100},{"$f":"P136","v":15583},{"$f":"P141","v":4175},227403.39400480496]
["Pioneer Road Services Pty Ltd","Central",68978.741994893266,350,18301,10058.775701743018,14100,15583,4174.5590313197035,43916.334733062722]
["PMP","Central",17916.333440697406,62,{"$f":"$G$5","v":14567.768518518518},{"$f":"E56*$H$5","v":193545.39400480496},{"$f":"P132","v":14100},{"$f":"P136","v":15583},{"$f":"P141","v":4175},227403.39400480496]
["Riviera Bakery Pty Ltd","Central",14114.087095068475,66,16602,34677.016352059138,14100,15583,4174.5590313197035,68534.575383378848]
["Royal Adelaide Hospital","Central",169112.28846732224,810,19049.8,311385.99915005645,28200,53702,78749.851940005043,472037.85109006148]
["S A Linen Services Pty Ltd","Central",18992.90105878656,67,15602,23522.177753728902,14100,15583,4174.5590313197035,57379.736785048604]
["San Remo Macaroni Co Pty Ltd","Central",68832.901664347679,440,12310,643545.99945824035,14100,30583,4174.5590313197035,692403.55848956003]
["San Remo Macaroni Co Pty Ltd","Central",50631.117155662265,164,{"$f":"$G$5","v":14567.768518518518},{"$f":"E61*$H$5","v":193545.39400480496},{"$f":"P132","v":14100},{"$f":"P137","v":30583},{"$f":"P141","v":4175},242403.39400480496]
["South Australian Brewing Co Pty Ltd","Central",117926.71400000001,890,14201,115689.00870457313,28200,53702,78749.851940005043,276340.86064457818]
["South Australian Water Corporation","Central",37049.553107065847,131,26602,257372.47310780315,14100,15583,4174.5590313197035,291230.03213912284]
["St Andrews Hospital Inc","Central",43287.453469352666,134,22649.8,191603.53499844761,14100,15583,4174.5590313197035,225461.09402976732]
["Stamford Plaza Adelaide","Central",11773.462101823759,59,20049.8,24382.632368697217,14100,15583,4174.5590313197035,58240.19140001692]
["Statewide Mental Health Service","Central",12240.579470222854,99,23849.8,192388.69386320063,14100,15583,4174.5590313197035,226246.25289452035]
["The Adelaide Casino","Central",10906.264493637404,51,19949.8,18280.354921434857,14100,15583,4174.5590313197035,52137.913952754563]
["The Radisson Playford Hotel","Central",12983.220229362558,53,{"$f":"$G$5","v":14567.768518518518},{"$f":"E68*$H$5","v":193545.39400480496},{"$f":"P132","v":14100},{"$f":"P136","v":15583},{"$f":"P141","v":4175},227403.39400480496]
["Thermal Ceramics Australia Pty Ltd","Central",13440.064723344578,150,11800,206061.84395795106,14100,30583,4174.5590313197035,254919.40298927078]
["Tip Top Dry Cleaners Pty Ltd","Central",13186.392198345306,109,18701,54815.825995744781,14100,15583,4174.5590313197035,88673.385027064491]
["Torrens Transit","Central",69909.57123565962,516,28701,700488.33272949513,28200,53702,78749.851940005043,861140.18466950022]
["Torrens Transit (2) (Non OER)","Central",73103.274963093922,246,{"$f":"$G$5","v":14567.768518518518},{"$f":"E72*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$137","v":30583},{"$f":"$P$141","v":4175},242403.39400480496]
["University Of Adelaide","Central",12236.094660971867,68,19649.8,15026.332322273825,14100,15583,4174.5590313197035,48883.891353593528]
["Western Community Hospital Inc","Central",11400.647571257372,52,14561,147619.53176042956,14100,15583,4174.5590313197035,181477.09079174927]
["Women's & Children's Hospital","Central",195770.74692009133,560,17649.8,119203.30991687863,28200,53702,78749.851940005043,279855.16185688367]
["Adelaide Brighton Cement Ltd (Birkenhead)","North Western",5152894.2539999997,17852,3100,463538.69759700407,28200,53702,78749.851940005043,624190.54953700909]
["Boral Plasterboard","North Western",15022.542359459319,550,3650,206084.1206395349,28200,38702,78749.851940005043,351735.97257953993]
["Pacific Terminals Largs Bay","North Western",1979.9731380242192,null,{"$f":"$G$5","v":14567.768518518518},{"$f":"E78*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["A I Automotive","Northern",13463.644954565287,68,{"$f":"$G$5","v":14567.768518518518},{"$f":"E79*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["ACI Glass Packaging","Northern",428102.96399999998,4800,{"$f":"$G$5","v":14567.768518518518},{"$f":"E80*$H$5","v":193545.39400480496},{"$f":"P133","v":28200},{"$f":"$P$138","v":53702},{"$f":"$P$142","v":78750},354197.39400480496]
["ACI Glass Packaging","Northern",1759835.1292132651,7300,10700,309603.73394743004,28200,53702,78749.851940005043,470255.58588743507]
["Adelaide Galvanising Industries","Northern",12228.27466968593,39,{"$f":"$G$5","v":14567.768518518518},{"$f":"E82*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Adelaide Malting Co Pty Ltd","Northern",74531.823999999993,287,1000,12391.739141374801,28200,53702,78749.851940005043,173043.59108137985]
["Adelaide Malting Co Pty Ltd","Northern",198075.07755660347,633,2050,48528.021140722383,14100,15583,4174.5590313197035,82385.580172042086]
["ALLOY TECHNOLOGIES INTERNATIONAL","Northern",0,50,{"$f":"$G$5","v":14567.768518518518},{"$f":"E85*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Alsco Linen Service Pty Ltd","Northern",29821.587839565935,130,13001,31283.086066389904,14100,15583,4174.5590313197035,65140.64509770961]
["Amcor Fibre Packaging Australia","Northern",45000.257013033995,229,5200,9970.2986189024687,14100,15583,4174.5590313197035,43827.857650222169]
["Ani Bradken","Northern",121086.60731104895,500,4960,67066.978683275898,14100,15583,4174.5590313197035,100924.5377145956]
["Arrowcrest Group Pty Ltd","Northern",166434.23025939657,780,6200,33492.447523028372,28200,53702,78749.851940005043,194144.29946303341]
["Avery Dennison Materials Pty Ltd","Northern",44172.684172670793,237,14301,202960.41491601316,14100,15583,4174.5590313197035,236817.97394733288]
["Balfours (Dudley Park)","Northern",10896.23,154,21249.8,137119.57682292775,14100,15583,4174.5590313197035,170977.13585424746]
["Balfours (Seaton)","Northern",10197.172,72,{"$f":"$G$5","v":14567.768518518518},{"$f":"E92*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Boral Asphalt","Northern",15242.640221939706,134,18801,80476.733879101535,14100,15583,4174.5590313197035,114334.29291042124]
["Boral Hollostone Masonary SA Pty Ltd","Northern",12905.605428869059,86,5500,192939.16200674255,14100,15583,4174.5590313197035,226796.72103806227]
["Bridgestone Australia Ltd","Northern",179286.43553944275,900,10801,331888.81874799868,28200,53702,78749.851940005043,492540.67068800371]
["Carter Holt Harvey - Demand","Northern",{"$f":"7601.155","v":7601.1549999999997},357,{"$f":"$G$5","v":14567.768518518518},{"$f":"E96*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},{"$f":"SUM(F96:I96)","v":227403.39400480496}]
["Carter Holt Harvey - Term Sheet","Northern",31515.7128037613,null,{"$f":"$G$5","v":14567.768518518518},{"$f":"E97*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Castalloy Wingfield (ION Automotive)","Northern",93638.046410564988,519,10710,185312.31122041357,14100,15583,4174.5590313197035,219169.87025173329]
["Central Linen Service","Northern",100790.49558704789,445,10710,468557.57396722335,14100,30583,4174.5590313197035,517415.13299854303]
["Chief Kitchenware Pty Ltd","Northern",13611.434733939508,90,2310,5846.7832067711779,14100,15583,4174.5590313197035,39704.342238090881]
["Collex Waste Management Pty Ltd","Northern",12500.813727954077,52,3510,34767.723089686566,14100,15583,4174.5590313197035,68625.282121006268]
["Conroy'S Smallgoods Pty Ltd","Northern",12379.594912578312,72,14049.8,19462.168935408012,14100,15583,4174.5590313197035,53319.727966727718]
["Crane Aluminium Extrusions","Northern",38667.918256238037,169,{"$f":"$G$5","v":14567.768518518518},{"$f":"E103*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["CSR Emoleum","Northern",41548.471462831054,249,3920,43063.140212762984,14100,15583,4174.5590313197035,76920.699244082687]
["CSR Humes Ltd","Northern",15046.628077520003,135,35502,660698.70302745514,14100,15583,4174.5590313197035,694556.26205877482]
["Dept Of Correctional Services Sa","Northern",15327.138795541796,96,7510,88677.521707388762,14100,15583,4174.5590313197035,122535.08073870846]
["DSTO","Northern",8158.121589948325,78,{"$f":"$G$5","v":14567.768518518518},{"$f":"E107*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Electrolux Appliance","Northern",5362.3278187883479,null,{"$f":"$G$5","v":14567.768518518518},{"$f":"E108*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Electrolux Cooking Products Division","Northern",114006.07180397314,600,10810,331937.50333962915,14100,15583,4174.5590313197035,365795.06237094884]
["Electrolux Home Products Pty Ltd","Northern",31101.921145158361,170,6400,33979.486922255339,14100,15583,4174.5590313197035,67837.045953575041]
["Elizabeth Swimming Centre","Northern",7704.7720472307301,61,11101,52912.783508639986,14100,15583,4174.5590313197035,86770.342539959689]
["F H Faulding & Co Pty Ltd","Northern",24835.783068096513,132,12201,55018.814516747007,14100,15583,4174.5590313197035,88876.373548066709]
["Foamex South Australia P/L","Northern",17587.552363774979,91,{"$f":"$G$5","v":14567.768518518518},{"$f":"E113*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["G H Michell & Sons Pty Ltd","Northern",194622.36373178003,1150,12301,468357.60815444845,28200,53702,78749.851940005043,629009.46009445353]
["G N B Battery Technologies Ltd","Northern",69900.236056726921,278,13901,360418.81995121494,14100,15583,4174.5590313197035,394276.37898253463]
["Gawler Health Service","Northern",20676.002515469045,72,27101,1249184.3316734273,14100,15583,4174.5590313197035,1283041.8907047471]
["Hampstead Rehabilitation Centre","Northern",9548.8676571693068,56,7910,74830.801969373802,14100,15583,4174.5590313197035,108688.36100069351]
["Holden Ltd","Northern",746123.11199999996,3700,7000,480436.07672010153,28200,53702,78749.851940005043,641087.92866010661]
["Industrial Engineers & Springmakers","Northern",39767.085999999996,190,12801,44697.789922073134,14100,15583,4174.5590313197035,78555.348953392837]
["Inghams Enterprises Pty Ltd","Northern",60988.911272946607,260,2300,5164.0412646046807,14100,15583,4174.5590313197035,39021.600295924385]
["Inghams Enterprises Pty Ltd","Northern",24760.119884353851,100,17501,15272.128511603743,14100,15583,4174.5590313197035,49129.68754292345]
["Intercast & Forge","Northern",15291.318119350082,65,{"$f":"$G$5","v":14567.768518518518},{"$f":"E122*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["International Hydroponics Pty Ltd","Northern",1552.5662147218318,259,{"$f":"$G$5","v":14567.768518518518},{"$f":"E123*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Jarrett Industries","Northern",12813.021930132101,65,{"$f":"$G$5","v":14567.768518518518},{"$f":"E124*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Joe White Maltings Ltd","Northern",296942.44606570643,1093,1950,{"$f":"E125*$H$5","v":25907.435159310939},28200,53702,78749.851940005043,186559.28709931596]
["John Shearer Ltd","Northern",12311.397006373751,120,{"$f":"$G$5","v":14567.768518518518},{"$f":"E126*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Korvest Galvanisers","Northern",31094.020261846599,190,4610,47706.706140786708,14100,15583,4174.5590313197035,81564.265172106403]
["Lyell Mc Ewin Hospital Inc","Northern",28988.752854243008,157,7901,53744.291317576513,14100,15583,4174.5590313197035,87601.850348896216]
["Master Butchers Ltd","Northern",100544.3288816126,468,5110,109449.27244588063,14100,15583,4174.5590313197035,143306.83147720035]
["Mobil Oil Australia","Northern",12917.141271135137,161,2000,3954.7585579001366,14100,15583,4174.5590313197035,37812.317589219834]
["Mullins Wheels Pty Ltd","Northern",37386.138648126645,180,11501,46362.315667996554,14100,15583,4174.5590313197035,80219.874699316264,null,null,null,null,"Assumed Inlet Sizes"]
["National Foods Milk Limited","Northern",29202.323565829247,110,17701,24928.815166022981,14100,15583,4174.5590313197035,58786.37419734268,null,null,null,null,"0 - 100TJ",14100]
["Polyrib","Northern",9956.5423290004037,58,{"$f":"$G$5","v":14567.768518518518},{"$f":"E133*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496,null,null,null,null,"Over 100TJ",28200]
["P'Petual Holdings Pty Ltd Hydroponics Shed","Northern",46555.074296630301,218,{"$f":"$G$5","v":14567.768518518518},{"$f":"E134*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Preventative Maintenance Programs","Northern",11204.04,236,{"$f":"$G$5","v":14567.768518518518},{"$f":"E135*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496,null,null,null,null,"Assumed Meter Sizes"]
["Quality Dry Cleaners","Northern",11452.863663176007,53,3700,{"$f":"E136*$H$5","v":49157.697481769472},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},83015.697481769472,null,null,null,null,"Under 50TJ",15583]
["Quality Foods","Northern",0,40,{"$f":"$G$5","v":14567.768518518518},{"$f":"E137*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496,null,null,null,null,"50-100TJ",30583]
["Queen Elizabeth Hospital","Northern",62264.374462413049,320,9311,81571.718518399386,14100,30583,4174.5590313197035,130429.27754971909,null,null,null,null,"100-200TJ",53702]
["Regency Institute of TAFE","Northern",9345.3173469890226,177,9310,123315.97309365237,14100,15583,4174.5590313197035,157173.53212497209]
["R-Max","Northern",32101.181352387561,200,13801,145134.34413726995,14100,15583,4174.5590313197035,178991.90316858966,null,null,null,null,"Assumed Gate Station Sizes"]
["Rocla Pipe & Precast Products","Northern",10104.880647284386,94,{"$f":"$G$5","v":14567.768518518518},{"$f":"E141*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496,null,null,null,null,"0 - 100TJ",4175]
["S Smith & Sons Pty Ltd","Northern",9942.5830634494905,84,null,465187.15596330276,14100,15583,null,494870.15596330276,null,null,null,null,"Over 100TJ",78750]
["SAFCOL Canning Pty Ltd","Northern",7634.5006277838038,60,7501,44411.486868226275,14100,15583,4174.5590313197035,78269.045899545978]
["Salisbury Brick Pty Ltd","Northern",{"$f":"54349.031876793+3968.414","v":58317.445876792997},311,22501,1276454.5494267703,28200,53702,78749.851940005043,1437106.4013667754]
["Sheridan Australia","Northern",39854.933459262109,null,7500,82323.440569358747,28200,53702,78749.851940005043,242975.29250936379]
["South Australian Saw Milling Pty Ltd","Northern",66701.695874818455,250,3400,7370.8360262738397,14100,15583,4174.5590313197035,41228.395057593545]
["South Australian Water Corporation","Northern",6021.081787350563,null,5800,379621.51527482003,14100,15583,4174.5590313197035,413479.07430613972]
["Southcorp Wines Pty Ltd","Northern",14102.460437864451,62,11901,21958.315510340406,14100,15583,4174.5590313197035,55815.874541660109]
["Strathmont Centre","Northern",14842.883812363738,94,9210,61976.177083993607,14100,15583,4174.5590313197035,95833.73611531331]
["Tarac Technologies Pty Ltd","Northern",36826.733332724041,864,{"$f":"$G$5","v":14567.768518518518},{"$f":"E150*$H$5","v":193545.39400480496},0,0,0,193545.39400480496]
["The Smith'S Snackfood Company Ltd","Northern",203898.30377673014,845,6810,206061.84395795106,14100,30583,4174.5590313197035,254919.40298927078]
["Tip Top Bakeries","Northern",58339.91331530959,254,3210,53988.194151798307,14100,15583,4174.5590313197035,87845.753183118009]
["Top Coat Asphalt Contractors","Northern",33751.108537381078,223,800,704.85354707201384,14100,15583,4174.5590313197035,34562.412578391719]
["University Of SA - Levels Campus","Northern",5571.0085410953316,null,{"$f":"$G$5","v":14567.768518518518},{"$f":"E154*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Visy Board Pty Ltd","Northern",57435.410429913885,261,3510,46483.98359520729,14100,15583,4174.5590313197035,80341.542626526993]
["Woodbridge Henderson","Northern",13241.061461841709,112,{"$f":"$G$5","v":14567.768518518518},{"$f":"E156*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Metro Velda Pty Ltd","Peterborough",10594.315842458091,62,0,175560,14100,15583,30000,235243]
["Conroys Port Pirie Abattoirs","Port Pirie",55685.333469930483,316,0,615896.74260959425,14100,15583,4670.3462161592206,650250.08882575342]
["Pasminco Port Pirie Smelter Pty Ltd","Port Pirie",948572.96418687585,3281,0,418203.25739040563,28200,53702,70329.653783840782,570434.91117424646]
["Murray Bridge Bacon","Riverland",32329.885782799687,650,0,{"$f":"E160*$H$5","v":0},0,0,0,{"$f":"SUM(F160:I160)","v":0}]
["Ridley Agriproducts Pty Ltd","Riverland",24374.442580747753,100,0,173880,14100,15583,null,203563]
["Carter Holt Harvey Panels","South East",23013.58927623511,109,{"$f":"$G$5","v":14567.768518518518},{"$f":"E162*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Dairy Vale Foods Limited","South East",13460.87618718589,71,null,122936.18164111421,14100,15583,11500.624319605922,164119.80596072011]
["Green Triangle Forest Products Ltd","South East",99322.183182838591,536,null,268681.99619291094,14100,15583,38599.214433545443,336964.21062645636]
["Kraft Foods Ltd","South East",13524.981730986963,69,null,453796.03213620512,28200,31166,51230.852531994598,564392.88466819969]
["McDonnell Industries","South East",13330.74,75,{"$f":"$G$5","v":14567.768518518518},{"$f":"E166*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Adelaide Mushroom Nominees","Southern",9743.2422148710211,42,{"$f":"$G$5","v":14567.768518518518},{"$f":"E167*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Bridgestone TG Australia Pty Ltd","Southern",33002.663034870136,185,10801,227059.96889625106,14100,15583,4174.5590313197035,260917.52792757077]
["BRL Hardy Ltd Winery","Southern",17968.713478441896,72,{"$f":"$G$5","v":14567.768518518518},{"$f":"E169*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Dairy Vale Foods Limited","Southern",8849.0134561956966,70,{"$f":"$G$5","v":14567.768518518518},{"$f":"E170*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Flinders Medical Centre","Southern",105710.48372033473,630,28701,114106.61205846729,14100,30583,4174.5590313197035,162964.17108978701]
["Flinders University Of SA","Southern",10444.607023688412,89,29201,72529.577312990921,14100,15583,4174.5590313197035,106387.13634431062]
["Hills Industries Limited","Southern",42229.865060677119,250,24001,107660.30642693627,14100,15583,4174.5590313197035,141517.86545825598]
["Kimberley Clark (Lonsdale)","Southern",6205.1021313632082,54,{"$f":"$G$5","v":14567.768518518518},{"$f":"E174*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Marshall Furniture Pty Ltd","Southern",16541.277801889948,95,25802,57777.036504930882,14100,15583,4174.5590313197035,91634.595536250577]
["Minda Inc","Southern",10474.92290391184,58,31502,121747.57477664428,14100,15583,4174.5590313197035,155605.13380796401]
["Mitsubishi Motors Australia Ltd","Southern",169459.22044536492,1900,26901,623467.73602483375,28200,53702,78749.851940005043,784119.58796483884]
["Mitsubishi Motors Australia Ltd","Southern",38185.606405075669,270,42601,432599.78203513531,28200,53702,78749.851940005043,593251.6339751404]
["Monroe Australia Pty Ltd","Southern",33037.938089548676,171,27301,58127.564856324934,14100,15583,4174.5590313197035,91985.12388764463]
["NCCRA Inc","Southern",17843.558918650007,104,{"$f":"$G$5","v":14567.768518518518},{"$f":"E180*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Olympic Aluminium Diecasting Pty Ltd","Southern",44007.15428454573,151,42502,200123.57582694964,14100,15583,4174.5590313197035,233981.13485826936]
["Repatriation General Hospital","Southern",24602.685676920275,165,{"$f":"$G$5","v":14567.768518518518},{"$f":"E182*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Schefenacker Vision Systems","Southern",16725.282911396385,92,42101,69982.470338853978,14100,15583,4174.5590313197035,103840.02937017368]
["Serco Australia Pty Ltd","Southern",159221.86279326159,611,{"$f":"$G$5","v":14567.768518518518},{"$f":"E184*$H$5","v":193545.39400480496},28200,53702,78749.851940005043,354197.24594480998]
["South Australian Research &","Southern",23486.092652820549,137,28950,724006.52049776504,14100,15583,4174.5590313197035,757864.07952908473]
["Stamford Grand Adelaide","Southern",11781.246797596183,46,28502,204056.82599523588,14100,15583,4174.5590313197035,237914.3850265556]
["Team Poly Pty Ltd","Southern",41679.519749632498,198,42702,154623.2418186327,14100,15583,4174.5590313197035,188480.80084995241]
["Walker Australia Pty Ltd","Southern",13770.642215932485,90,{"$f":"$G$5","v":14567.768518518518},{"$f":"E188*$H$5","v":193545.39400480496},{"$f":"$P$132","v":14100},{"$f":"$P$136","v":15583},{"$f":"$P$141","v":4175},227403.39400480496]
["Whyalla Hospital","Whyalla",9906.9059345938749,57,0,248400,14100,15583,1000,279083]
["Totals",null,{"$f":"SUM(C31:C189)","v":16005769.946148545},73570,2258004.1203703689,30848782.779405028,2552100,3458851,2465841.5706534684,39325575.350058511]
[]
["Individual Customers - Closing 2010-11","District Name","Consumption","Flow (MDQ)","Length","Cost","Inlet","Meter and RDL","Gate Station","Total"]
[{"$f":"A31","v":"Adelaide Aquatic Centre"},"Central",null,null,null,{"$f":"F31/$J$190*$I$18*$G$18","v":76120.904126716414},22503.32889741781,24870.168383578839,6662.5159491824943,{"$f":"SUM(F193:I193)","v":130156.91735689556}]
[{"$f":"A32","v":"Adelaide Festival Centre Trust"},"Central",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,{"$f":"SUM(F194:I194)","v":362931.44451625639}]
["Arnotts Biscuits","Central",null,null,null,153370.77481303093,22503.32889741781,48809.879976576507,6662.5159491824943,231346.49963620777]
["Ashford Community Hospital Inc","Central",null,null,null,105380.165239529,22503.32889741781,24870.168383578839,6662.5159491824943,159416.17846970816]
["Asphalt SA","Central",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Australia Post","Central",null,null,null,182523.91718315371,22503.32889741781,24870.168383578839,6662.5159491824943,236559.93041333286]
["Brown Wood Panels Pty Ltd","Central",null,null,null,103615.94183120294,22503.32889741781,24870.168383578839,6662.5159491824943,157651.95506138209]
["Buttercup Bakeries - Forestville","Central",null,null,null,195177.44115419567,22503.32889741781,24870.168383578839,6662.5159491824943,249213.45438437481]
["Castalloy Manufacturing Pty Ltd (ION Automotive: Nth Plympton)","Central",null,null,null,724165.27549611591,45006.657794835621,85707.359464477384,125683.24956233257,980562.54231776146]
["Coca Cola Bottlers Adelaide","Central",null,null,null,51413.56016240704,22503.32889741781,24870.168383578839,6662.5159491824943,105449.57339258619]
["CSR Building Materials","Central",null,null,null,1379367.8547140828,45006.657794835621,85707.359464477384,125683.24956233257,1635765.1215357282]
["Dept For The Arts","Central",null,null,null,63087.82188659953,22503.32889741781,24870.168383578839,6662.5159491824943,117123.83511677868]
["Hallet Brick (Austral Bricks)","Central",null,null,null,308894.72750854207,45006.657794835621,85707.359464477384,125683.48586323776,565292.2306310928]
["Healthscope Ltd","Central",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Hilton International Adelaide","Central",null,null,null,91840.628072870531,22503.32889741781,24870.168383578839,6662.5159491824943,145876.64130304969]
["Hyatt Regency Adelaide","Central",null,null,null,90049.094370046179,22503.32889741781,24870.168383578839,6662.5159491824943,144085.10760022534]
["Inghams Enterprises Pty Ltd","Central",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["International Linen Service Pty Ltd","Central",null,null,null,265797.28818777192,22503.32889741781,24870.168383578839,6662.5159491824943,319833.30141795106]
["Julia Farr Services","Central",null,null,null,495073.26416069845,22503.32889741781,24870.168383578839,6662.5159491824943,549109.2773908776]
["Myer Centre Adelaide Intro International Ltd","Central",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["North Eastern Community Hospital Inc","Central",null,null,null,{"$f":"F51/$J$190*$I$18*$G$18","v":614794.46495773038},22503.32889741781,24870.168383578839,6662.5159491824943,668830.47818790947]
["North Eastern Community Hospital Inc","Central",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Novotel Adelaide On Hindley","Central",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Performance Wheel Co Pty Ltd","Central",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Pioneer Road Services Pty Ltd","Central",null,null,null,16053.612618558705,22503.32889741781,24870.168383578839,6662.5159491824943,70089.625848737851]
["PMP","Central",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Riviera Bakery Pty Ltd","Central",null,null,null,55343.851358263993,22503.32889741781,24870.168383578839,6662.5159491824943,109379.86458844313]
["Royal Adelaide Hospital","Central",null,null,null,496966.06758331793,45006.657794835621,85707.359464477384,125683.24956233257,753363.33440496342]
["S A Linen Services Pty Ltd","Central",null,null,null,37540.943430899708,22503.32889741781,24870.168383578839,6662.5159491824943,91576.956661078846]
["San Remo Macaroni Co Pty Ltd","Central",null,null,null,1027087.0415905137,22503.32889741781,48809.879976576507,6662.5159491824943,1105062.7664136903]
["San Remo Macaroni Co Pty Ltd","Central",null,null,null,308894.72750854207,22503.32889741781,48809.879976576507,6663.2197267176844,386871.15610925405]
["South Australian Brewing Co Pty Ltd","Central",null,null,null,184637.43352448518,45006.657794835621,85707.359464477384,125683.24956233257,441034.70034613076]
["South Australian Water Corporation","Central",null,null,null,410761.51854515699,22503.32889741781,24870.168383578839,6662.5159491824943,464797.53177533613]
["St Andrews Hospital Inc","Central",null,null,null,305795.55787077802,22503.32889741781,24870.168383578839,6662.5159491824943,359831.57110095717]
["Stamford Plaza Adelaide","Central",null,null,null,38914.21245231339,22503.32889741781,24870.168383578839,6662.5159491824943,92950.225682492528]
["Statewide Mental Health Service","Central",null,null,null,307048.65632256959,22503.32889741781,24870.168383578839,6662.5159491824943,361084.66955274873]
["The Adelaide Casino","Central",null,null,null,29175.094975785734,22503.32889741781,24870.168383578839,6662.5159491824943,83211.108205964876]
["The Radisson Playford Hotel","Central",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Thermal Ceramics Australia Pty Ltd","Central",null,null,null,328870.74097830919,22503.32889741781,48809.879976576507,6662.5159491824943,406846.46580148599]
["Tip Top Dry Cleaners Pty Ltd","Central",null,null,null,87485.004338004946,22503.32889741781,24870.168383578839,6662.5159491824943,141521.01756818409]
["Torrens Transit","Central",null,null,null,{"$f":"F71/$J$190*$I$18*$G$18","v":1117965.9106535933},45006.657794835621,85707.359464477384,125683.24956233257,1374363.1774752387]
["Torrens Transit (2) (Non OER)","Central",null,null,null,308894.72750854207,22503.32889741781,48809.879976576507,6663.2197267176844,386871.15610925405]
["University Of Adelaide","Central",null,null,null,23981.737473051617,22503.32889741781,24870.168383578839,6662.5159491824943,78017.750703230762]
["Western Community Hospital Inc","Central",null,null,null,235597.93438920286,22503.32889741781,24870.168383578839,6662.5159491824943,289633.947619382]
["Women's & Children's Hospital","Central",null,null,null,190246.19068938622,45006.657794835621,85707.359464477384,125683.24956233257,446643.45751103183]
["Adelaide Brighton Cement Ltd (Birkenhead)","North Western",null,null,null,739798.84884440259,45006.657794835621,85707.359464477384,125683.24956233257,996196.11566604814]
["Boral Plasterboard","North Western",null,null,null,328906.2941338002,45006.657794835621,61767.647871479719,125683.24956233257,561363.84936244809]
["Pacific Terminals Largs Bay","North Western",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["A I Automotive","Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["ACI Glass Packaging","Northern",null,null,null,308894.72750854207,45006.657794835621,85707.359464477384,125683.48586323776,565292.2306310928]
["ACI Glass Packaging","Northern",null,null,null,494121.60658777709,45006.657794835621,85707.359464477384,125683.24956233257,750518.87340942258]
["Adelaide Galvanising Industries","Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Adelaide Malting Co Pty Ltd","Northern",null,null,null,19776.977412011551,45006.657794835621,85707.359464477384,125683.24956233257,276174.24423365714]
["Adelaide Malting Co Pty Ltd","Northern",null,null,null,77449.788685852502,22503.32889741781,24870.168383578839,6662.5159491824943,131485.80191603166]
["ALLOY TECHNOLOGIES INTERNATIONAL","Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Alsco Linen Service Pty Ltd","Northern",null,null,null,49927.203877886539,22503.32889741781,24870.168383578839,6662.5159491824943,103963.21710806568]
["Amcor Fibre Packaging Australia","Northern",null,null,null,15912.40489550587,22503.32889741781,24870.168383578839,6662.5159491824943,69948.418125685013]
["Ani Bradken","Northern",null,null,null,107037.60847275649,22503.32889741781,24870.168383578839,6662.5159491824943,161073.62170293563]
["Arrowcrest Group Pty Ltd","Northern",null,null,null,53453.302282993885,45006.657794835621,85707.359464477384,125683.24956233257,309850.56910463946]
["Avery Dennison Materials Pty Ltd","Northern",null,null,null,323920.91985896649,22503.32889741781,24870.168383578839,6662.5159491824943,377956.93308914563]
["Balfours (Dudley Park)","Northern",null,null,null,{"$f":"F91/$J$190*$I$18*$G$18","v":218840.20819298518},22503.32889741781,24870.168383578839,6662.5159491824943,272876.22142316436]
["Balfours (Seaton)","Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Boral Asphalt","Northern",null,null,null,128439.31993414101,22503.32889741781,24870.168383578839,6662.5159491824943,182475.33316432015]
["Boral Hollostone Masonary SA Pty Ltd","Northern",null,null,null,307927.192895738,22503.32889741781,24870.168383578839,6662.5159491824943,361963.20612591715]
["Bridgestone Australia Ltd","Northern",null,null,null,529688.1734511843,45006.657794835621,85707.359464477384,125683.24956233257,786085.44027282984]
[{"$f":"A96","v":"Carter Holt Harvey - Demand"},"Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,{"$f":"SUM(F258:I258)","v":362931.44451625639}]
["Carter Holt Harvey - Term Sheet","Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Castalloy Wingfield (ION Automotive)","Northern",null,null,null,295754.88568323513,22503.32889741781,24870.168383578839,6662.5159491824943,349790.89891341428]
["Central Linen Service","Northern",null,null,null,747808.87903266656,22503.32889741781,48809.879976576507,6662.5159491824943,825784.60385584331]
["Chief Kitchenware Pty Ltd","Northern",null,null,null,9331.3535811256043,22503.32889741781,24870.168383578839,6662.5159491824943,63367.366811304753]
["Collex Waste Management Pty Ltd","Northern",null,null,null,55488.617567486814,22503.32889741781,24870.168383578839,6662.5159491824943,109524.63079766596]
["Conroy'S Smallgoods Pty Ltd","Northern",null,null,null,31061.247419191084,22503.32889741781,24870.168383578839,6662.5159491824943,85097.260649370219]
["Crane Aluminium Extrusions","Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["CSR Emoleum","Northern",null,null,null,68727.943798824403,22503.32889741781,24870.168383578839,6662.5159491824943,122763.95702900355]
["CSR Humes Ltd","Northern",null,null,null,1054462.4266896592,22503.32889741781,24870.168383578839,6662.5159491824943,1108498.4399198382]
["Dept Of Correctional Services Sa","Northern",null,null,null,141527.61963044512,22503.32889741781,24870.168383578839,6662.5159491824943,195563.63286062426]
["DSTO","Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Electrolux Appliance","Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Electrolux Cooking Products Division","Northern",null,null,null,529765.8731233615,22503.32889741781,24870.168383578839,6662.5159491824943,583801.88635354058]
["Electrolux Home Products Pty Ltd","Northern",null,null,null,54230.60779978858,22503.32889741781,24870.168383578839,6662.5159491824943,108266.62102996772]
["Elizabeth Swimming Centre","Northern",null,null,null,{"$f":"F111/$J$190*$I$18*$G$18","v":84447.785118637621},22503.32889741781,24870.168383578839,6662.5159491824943,138483.79834881678]
["F H Faulding & Co Pty Ltd","Northern",null,null,null,87808.970114637123,22503.32889741781,24870.168383578839,6662.5159491824943,141844.98334481628]
["Foamex South Australia P/L","Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["G H Michell & Sons Pty Ltd","Northern",null,null,null,747489.73744024732,45006.657794835621,85707.359464477384,125683.24956233257,1003887.0042618929]
["G N B Battery Technologies Ltd","Northern",null,null,null,575221.50682137592,22503.32889741781,24870.168383578839,6662.5159491824943,629257.52005155501]
["Gawler Health Service","Northern",null,null,null,1993674.1751168924,22503.32889741781,24870.168383578839,6662.5159491824943,2047710.1883470714]
["Hampstead Rehabilitation Centre","Northern",null,null,null,119428.52116130205,22503.32889741781,24870.168383578839,6662.5159491824943,173464.5343914812]
["Holden Ltd","Northern",null,null,null,766766.74103670206,45006.657794835621,85707.359464477384,125683.24956233257,1023164.0078583476]
["Industrial Engineers & Springmakers","Northern",null,null,null,71336.813305255244,22503.32889741781,24870.168383578839,6662.5159491824943,125372.82653543439]
["Inghams Enterprises Pty Ltd","Northern",null,null,null,8241.7105685983333,22503.32889741781,24870.168383578839,6662.5159491824943,62277.723798777479]
["Inghams Enterprises Pty Ltd","Northern",null,null,null,24374.023465266022,22503.32889741781,24870.168383578839,6662.5159491824943,78410.03669544516]
["Intercast & Forge","Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["International Hydroponics Pty Ltd","Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Jarrett Industries","Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Joe White Maltings Ltd","Northern",null,null,null,41347.768388546101,45006.657794835621,85707.359464477384,125683.24956233257,297745.03521019168]
["John Shearer Ltd","Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Korvest Galvanisers","Northern",null,null,null,76138.985737488314,22503.32889741781,24870.168383578839,6662.5159491824943,130174.99896766746]
["Lyell Mc Ewin Hospital Inc","Northern",null,null,null,85774.855594188688,22503.32889741781,24870.168383578839,6662.5159491824943,139810.86882436785]
["Master Butchers Ltd","Northern",null,null,null,174678.93442785394,22503.32889741781,24870.168383578839,6662.5159491824943,228714.94765803308]
["Mobil Oil Australia","Northern",null,null,null,6311.7186197379087,22503.32889741781,24870.168383578839,6662.5159491824943,60347.731849917058]
["Mullins Wheels Pty Ltd","Northern",null,null,null,{"$f":"F131/$J$190*$I$18*$G$18","v":73993.364391690295},22503.32889741781,24870.168383578839,6662.5159491824943,128029.37762186944]
["National Foods Milk Limited","Northern",null,null,null,39785.909695315764,22503.32889741781,24870.168383578839,6662.5159491824943,93821.922925494902]
["Polyrib","Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["P'Petual Holdings Pty Ltd Hydroponics Shed","Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Preventative Maintenance Programs","Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Quality Dry Cleaners","Northern",null,null,null,78454.740019292585,22503.32889741781,24870.168383578839,6663.2197267176844,132491.45702700692]
["Quality Foods","Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Queen Elizabeth Hospital","Northern",null,null,null,130186.89436504454,22503.32889741781,48809.879976576507,6662.5159491824943,208162.61918822138]
["Regency Institute of TAFE","Northern",null,null,null,196809.92204479317,22503.32889741781,24870.168383578839,6662.5159491824943,250845.93527497232]
["R-Max","Northern",null,null,null,231631.62272567427,22503.32889741781,24870.168383578839,6662.5159491824943,285667.63595585345]
["Rocla Pipe & Precast Products","Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["S Smith & Sons Pty Ltd","Northern",null,null,null,742429.75670188619,22503.32889741781,24870.168383578839,0,789803.25398288283]
["SAFCOL Canning Pty Ltd","Northern",null,null,null,70879.879136102682,22503.32889741781,24870.168383578839,6662.5159491824943,124915.89236628183]
["Salisbury Brick Pty Ltd","Northern",null,null,null,2037196.9183231108,45006.657794835621,85707.359464477384,125683.24956233257,2293594.185144756]
["Sheridan Australia","Northern",null,null,null,131386.62830491544,45006.657794835621,85707.359464477384,125683.24956233257,387783.89512656105]
["South Australian Saw Milling Pty Ltd","Northern",null,null,null,11763.712577884846,22503.32889741781,24870.168383578839,6662.5159491824943,65799.725808063988]
["South Australian Water Corporation","Northern",null,null,null,605868.63934506325,22503.32889741781,24870.168383578839,6662.5159491824943,659904.65257524233]
["Southcorp Wines Pty Ltd","Northern",null,null,null,35045.049359039782,22503.32889741781,24870.168383578839,6662.5159491824943,89081.062589218927]
["Strathmont Centre","Northern",null,null,null,98912.787001823875,22503.32889741781,24870.168383578839,6662.5159491824943,152948.80023200304]
["Tarac Technologies Pty Ltd","Northern",null,null,null,308894.72750854207,0,0,0,308894.72750854207]
["The Smith'S Snackfood Company Ltd","Northern",null,null,null,{"$f":"F151/$J$190*$I$18*$G$18","v":328870.74097830919},22503.32889741781,48809.879976576507,6662.5159491824943,406846.46580148599]
["Tip Top Bakeries","Northern",null,null,null,86164.119828054332,22503.32889741781,24870.168383578839,6662.5159491824943,140200.13305823348]
["Top Coat Asphalt Contractors","Northern",null,null,null,1124.9327088136943,22503.32889741781,24870.168383578839,6662.5159491824943,55160.945938992845]
["University Of SA - Levels Campus","Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Visy Board Pty Ltd","Northern",null,null,null,74187.544064193164,22503.32889741781,24870.168383578839,6662.5159491824943,128223.55729437231]
["Woodbridge Henderson","Northern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Metro Velda Pty Ltd","Peterborough",null,null,null,280190.38448444469,22503.32889741781,24870.168383578839,47879.423185995336,375443.30495143664]
["Conroys Port Pirie Abattoirs","Port Pirie",null,null,null,982959.35927602684,22503.32889741781,24870.168383578839,7453.7827636199791,1037786.6393206435]
["Pasminco Port Pirie Smelter Pty Ltd","Port Pirie",null,null,null,667444.35794523207,45006.657794835621,85707.359464477384,112244.77520136835,910403.15040591347]
[{"$f":"A160","v":"Murray Bridge Bacon"},"Riverland",null,null,null,0,0,0,0,{"$f":"SUM(F322:I322)","v":0}]
["Ridley Agriproducts Pty Ltd","Riverland",null,null,null,277509.13678602898,22503.32889741781,24870.168383578839,0,324882.63406702562]
["Carter Holt Harvey Panels","South East",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Dairy Vale Foods Limited","South East",null,null,null,196203.78218884327,22503.32889741781,24870.168383578839,18354.77529005205,261932.05475989197]
["Green Triangle Forest Products Ltd","South East",null,null,null,428811.29993927904,22503.32889741781,24870.168383578839,61603.604083690057,537788.40130396571]
["Kraft Foods Ltd","South East",null,null,null,724249.74209249672,45006.657794835621,49740.336767157678,81763.455618622989,900760.19227311295]
["McDonnell Industries","South East",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Adelaide Mushroom Nominees","Southern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Bridgestone TG Australia Pty Ltd","Southern",null,null,null,362383.34464608476,22503.32889741781,24870.168383578839,6662.5159491824943,416419.35787626391]
["BRL Hardy Ltd Winery","Southern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Dairy Vale Foods Limited","Southern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Flinders Medical Centre","Southern",null,null,null,{"$f":"F171/$J$190*$I$18*$G$18","v":182111.95890225179},22503.32889741781,48809.879976576507,6662.5159491824943,260087.68372542862]
["Flinders University Of SA","Southern",null,null,null,115755.81085566863,22503.32889741781,24870.168383578839,6662.5159491824943,169791.82408584777]
["Hills Industries Limited","Southern",null,null,null,171823.77905830715,22503.32889741781,24870.168383578839,6662.5159491824943,225859.79228848629]
["Kimberley Clark (Lonsdale)","Southern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Marshall Furniture Pty Ltd","Southern",null,null,null,92211.039375076216,22503.32889741781,24870.168383578839,6662.5159491824943,146247.05260525536]
["Minda Inc","Southern",null,null,null,194306.78848665211,22503.32889741781,24870.168383578839,6662.5159491824943,248342.80171683125]
["Mitsubishi Motors Australia Ltd","Southern",null,null,null,995042.51919824805,45006.657794835621,85707.359464477384,125683.24956233257,1251439.7860198936]
["Mitsubishi Motors Australia Ltd","Southern",null,null,null,690420.93447431945,45006.657794835621,85707.359464477384,125683.24956233257,946818.201295965]
["Monroe Australia Pty Ltd","Southern",null,null,null,92770.475884245723,22503.32889741781,24870.168383578839,6662.5159491824943,146806.48911442488]
["NCCRA Inc","Southern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Olympic Aluminium Diecasting Pty Ltd","Southern",null,null,null,319393.37921710499,22503.32889741781,24870.168383578839,6662.5159491824943,373429.39244728413]
["Repatriation General Hospital","Southern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Schefenacker Vision Systems","Southern",null,null,null,111690.67709851186,22503.32889741781,24870.168383578839,6662.5159491824943,165726.69032869101]
["Serco Australia Pty Ltd","Southern",null,null,null,308894.72750854207,45006.657794835621,85707.359464477384,125683.24956233257,565291.99433018768]
["South Australian Research &","Southern",null,null,null,1155500.4861444165,22503.32889741781,24870.168383578839,6662.5159491824943,1209536.4993745955]
["Stamford Grand Adelaide","Southern",null,null,null,325670.77086056373,22503.32889741781,24870.168383578839,6662.5159491824943,379706.78409074288]
["Team Poly Pty Ltd","Southern",null,null,null,246775.72098082685,22503.32889741781,24870.168383578839,6662.5159491824943,300811.73421100597]
["Walker Australia Pty Ltd","Southern",null,null,null,308894.72750854207,22503.32889741781,24870.168383578839,6663.2197267176844,362931.44451625639]
["Whyalla Hospital","Whyalla",null,null,null,396441.62398004136,22503.32889741781,24870.168383578839,1595.9807728665112,445411.10203390452]
["Totals",null,null,null,null,{"$f":"SUM(F193:F351)","v":49234064.182266034},{"$f":"SUM(G193:G351)","v":4073102.5304326313},{"$f":"SUM(H193:H351)","v":5520259.6922100978},{"$f":"SUM(I193:I351)","v":3935435.7356978883},{"$f":"SUM(J193:J351)","v":62762862.140606619}]
[]
[]
["Meter Cost Calculations"]
[]
["Tariff D - Summary by Region","Meters and RDL by Region as a % of Total Tariff D RAB","Meter Cost: Pro-Rata of 2011-12 Tariff D Revenue Requirement ($M)","Meter Cost: Pro-Rata of 2011-12 Tariff R Revenue Requirement ($M)","Meter Cost: Pro-Rata of 2011-12 Tariff C Revenue Requirement ($M)"]
["Central",{"$f":"(D18+E18)/$B$26","v":4.5168264779051871E-2},{"$f":"B358*'FDC Calculations'!$B$41","v":{"$error":"#NAME?"}},{"$f":"B366*'FDC Calculations'!B25","v":{"$error":"#NAME?"}},{"$f":"B366*'FDC Calculations'!B33","v":{"$error":"#NAME?"}}]
["Northern",{"$f":"(D19+E19)/$B$26","v":7.7081338874689459E-2},{"$f":"B359*'FDC Calculations'!$B$41","v":{"$error":"#NAME?"}}]
["Southern",2.0970653134990247E-2,{"$f":"B360*'FDC Calculations'!$B$41","v":{"$error":"#NAME?"}}]
["Peterborough",7.5480141703650422E-4,{"$f":"B361*'FDC Calculations'!$B$41","v":{"$error":"#NAME?"}}]
["Port Pirie",2.8374664326388283E-3,{"$f":"B362*'FDC Calculations'!$B$41","v":{"$error":"#NAME?"}}]
["Riverland",7.5480141703650422E-4,{"$f":"B363*'FDC Calculations'!$B$41","v":{"$error":"#NAME?"}}]
["South East",4.5288085022190247E-3,{"$f":"B364*'FDC Calculations'!$B$41","v":{"$error":"#NAME?"}}]
["Whyalla",7.5480141703650422E-4,{"$f":"B365*'FDC Calculations'!$B$41","v":{"$error":"#NAME?"}}]
["All dedicated assets as a % of RAB (for tariffs R, C and D combined)",{"$f":"('PTRM Inputs'!B17+'PTRM Inputs'!B21+'PTRM Inputs'!B22)/SUM('PTRM Inputs'!B16:B26)","v":0.12382558352084551}]

{"sheet":"FDC Calculations","index":10,"n_rows":94,"n_cols":11,"rows_kept":94,"cut":false,"hidden":false,"merged":[[0,0,0,12]]}
["Fully Distributed Cost Calculations"]
[]
["Building block components - Total ($M NOMINAL)","2011-12","2012-13","2013-14","2014-15","2015-16","TOTAL"]
["Return on capital",{"$f":"'PTRM Inputs'!B5","v":109.7},{"$f":"'PTRM Inputs'!C5","v":121.1},{"$f":"'PTRM Inputs'!D5","v":133.30000000000001},{"$f":"'PTRM Inputs'!E5","v":144.80000000000001},{"$f":"'PTRM Inputs'!F5","v":157.4},{"$f":"SUM(B4:F4)","v":666.30000000000007}]
["Return of capital",{"$f":"'PTRM Inputs'!B6","v":2.5},{"$f":"'PTRM Inputs'!C6","v":3.4},{"$f":"'PTRM Inputs'!D6","v":4.4000000000000004},{"$f":"'PTRM Inputs'!E6","v":4.5},{"$f":"'PTRM Inputs'!F6","v":5.0999999999999996},19.899999999999999]
["O&M",{"$f":"'PTRM Inputs'!B7","v":71},{"$f":"'PTRM Inputs'!C7","v":73.7},{"$f":"'PTRM Inputs'!D7","v":75.2},{"$f":"'PTRM Inputs'!E7","v":76.7},{"$f":"'PTRM Inputs'!F7","v":76.900000000000006},373.5]
["Carry-over amounts",{"$f":"'PTRM Inputs'!B8","v":11.7},{"$f":"'PTRM Inputs'!C8","v":3.4},{"$f":"'PTRM Inputs'!D8","v":3.4},{"$f":"'PTRM Inputs'!E8","v":1.9},{"$f":"'PTRM Inputs'!F8","v":0},20.399999999999999]
["Benchmark Tax liability",{"$f":"'PTRM Inputs'!B9","v":18.8},{"$f":"'PTRM Inputs'!C9","v":16.5},{"$f":"'PTRM Inputs'!D9","v":17},{"$f":"'PTRM Inputs'!E9","v":16.5},{"$f":"'PTRM Inputs'!F9","v":16.2},85]
["Total Revenue",{"$f":"SUM(B4:B8)","v":213.7},{"$f":"SUM(C4:C8)","v":218.1},{"$f":"SUM(D4:D8)","v":233.30000000000004},{"$f":"SUM(E4:E8)","v":244.4},{"$f":"SUM(F4:F8)","v":255.6},1165.0999999999999]
[]
["Building block components R+C ($M NOMINAL)","2011-12","2012-13","2013-14","2014-15","2015-16","TOTAL"]
[{"$f":"A4","v":"Return on capital"},{"$f":"B4-B36","v":103.08954616056164},113.80258924379228,125.26742482409178,136.07444196945602,147.91517379828991,{"$f":"SUM(B12:F12)","v":626.14917599619162}]
[{"$f":"A5","v":"Return of capital"},2.3493515533400555,3.1951181125424757,4.1348587338784979,4.2288327960120995,4.7926771688137126,18.700838364586843]
[{"$f":"A6","v":"O&M"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"}]
[{"$f":"A7","v":"Carry-over amounts"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"}]
[{"$f":"A8","v":"Benchmark Tax liability"},17.667123681117218,15.505720252044366,15.975590562712378,15.505720252044366,15.223798065643559,79.87795281356189]
["Total Revenue",{"$f":"SUM(B12:B16)","v":{"$error":"#NAME?"}},{"$f":"SUM(C12:C16)","v":{"$error":"#NAME?"}},{"$f":"SUM(D12:D16)","v":{"$error":"#NAME?"}},{"$f":"SUM(E12:E16)","v":{"$error":"#NAME?"}},{"$f":"SUM(F12:F16)","v":{"$error":"#NAME?"}},{"$error":"#NAME?"}]
[]
["Building block components R ($M NOMINAL)","2011-12","2012-13","2013-14","2014-15","2015-16","TOTAL"]
[{"$f":"A12","v":"Return on capital"},{"$f":"'Cost allocators'!$C12*B12","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$C12*C12","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$C12*D12","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$C12*E12","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$C12*F12","v":{"$error":"#NAME?"}},{"$f":"SUM(B20:F20)","v":{"$error":"#NAME?"}}]
[{"$f":"A13","v":"Return of capital"},{"$f":"'Cost allocators'!$C13*B13","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$C13*C13","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$C13*D13","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$C13*E13","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$C13*F13","v":{"$error":"#NAME?"}},{"$error":"#NAME?"}]
[{"$f":"A14","v":"O&M"},{"$f":"'Cost allocators'!$C14*B14","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$C14*C14","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$C14*D14","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$C14*E14","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$C14*F14","v":{"$error":"#NAME?"}},{"$error":"#NAME?"}]
[{"$f":"A15","v":"Carry-over amounts"},{"$f":"'Cost allocators'!$C15*B15","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$C15*C15","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$C15*D15","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$C15*E15","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$C15*F15","v":{"$error":"#NAME?"}},{"$error":"#NAME?"}]
[{"$f":"A16","v":"Benchmark Tax liability"},{"$f":"'Cost allocators'!$C16*B16","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$C16*C16","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$C16*D16","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$C16*E16","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$C16*F16","v":{"$error":"#NAME?"}},{"$error":"#NAME?"}]
["Total Revenue",{"$f":"SUM(B20:B24)","v":{"$error":"#NAME?"}},{"$f":"SUM(C20:C24)","v":{"$error":"#NAME?"}},{"$f":"SUM(D20:D24)","v":{"$error":"#NAME?"}},{"$f":"SUM(E20:E24)","v":{"$error":"#NAME?"}},{"$f":"SUM(F20:F24)","v":{"$error":"#NAME?"}},{"$error":"#NAME?"}]
[]
["Building block components C ($M NOMINAL)","2011-12","2012-13","2013-14","2014-15","2015-16","TOTAL"]
[{"$f":"A20","v":"Return on capital"},{"$f":"'Cost allocators'!$D12*B12","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$D12*C12","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$D12*D12","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$D12*E12","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$D12*F12","v":{"$error":"#NAME?"}},{"$f":"SUM(B28:F28)","v":{"$error":"#NAME?"}}]
[{"$f":"A21","v":"Return of capital"},{"$f":"'Cost allocators'!$D13*B13","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$D13*C13","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$D13*D13","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$D13*E13","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$D13*F13","v":{"$error":"#NAME?"}},{"$error":"#NAME?"}]
[{"$f":"A22","v":"O&M"},{"$f":"'Cost allocators'!$D14*B14","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$D14*C14","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$D14*D14","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$D14*E14","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$D14*F14","v":{"$error":"#NAME?"}},{"$error":"#NAME?"}]
[{"$f":"A23","v":"Carry-over amounts"},{"$f":"'Cost allocators'!$D15*B15","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$D15*C15","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$D15*D15","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$D15*E15","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$D15*F15","v":{"$error":"#NAME?"}},{"$error":"#NAME?"}]
[{"$f":"A24","v":"Benchmark Tax liability"},{"$f":"'Cost allocators'!$D16*B16","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$D16*C16","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$D16*D16","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$D16*E16","v":{"$error":"#NAME?"}},{"$f":"'Cost allocators'!$D16*F16","v":{"$error":"#NAME?"}},{"$error":"#NAME?"}]
["Total Revenue",{"$f":"SUM(B28:B32)","v":{"$error":"#NAME?"}},{"$f":"SUM(C28:C32)","v":{"$error":"#NAME?"}},{"$f":"SUM(D28:D32)","v":{"$error":"#NAME?"}},{"$f":"SUM(E28:E32)","v":{"$error":"#NAME?"}},{"$f":"SUM(F28:F32)","v":{"$error":"#NAME?"}},{"$error":"#NAME?"}]
[]
["Building block components D ($M NOMINAL)","2011-12","2012-13","2013-14","2014-15","2015-16","TOTAL"]
[{"$f":"A12","v":"Return on capital"},{"$f":"B47","v":6.6104538394383621},{"$f":"B57","v":7.2974107562077064},{"$f":"B67","v":8.0325751759082369},{"$f":"B77","v":8.7255580305439828},{"$f":"B87","v":9.4848262017101046},{"$f":"SUM(B36:F36)","v":40.150824003808388}]
[{"$f":"A13","v":"Return of capital"},{"$f":"B48","v":0.1506484466599444},{"$f":"B58","v":0.20488188745752442},{"$f":"B68","v":0.26514126612150224},{"$f":"B78","v":0.27116720398790006},{"$f":"B88","v":0.30732283118628662},1.1991616354131578]
[{"$f":"A14","v":"O&M"},{"$f":"B49","v":{"$error":"#NAME?"}},{"$f":"B59","v":{"$error":"#NAME?"}},{"$f":"B69","v":{"$error":"#NAME?"}},{"$f":"B79","v":{"$error":"#NAME?"}},{"$f":"B89","v":{"$error":"#NAME?"}},{"$error":"#NAME?"}]
[{"$f":"A15","v":"Carry-over amounts"},{"$f":"B50","v":{"$error":"#NAME?"}},{"$f":"B60","v":{"$error":"#NAME?"}},{"$f":"B70","v":{"$error":"#NAME?"}},{"$f":"B80","v":{"$error":"#NAME?"}},{"$f":"B90","v":{"$error":"#NAME?"}},{"$error":"#NAME?"}]
[{"$f":"A16","v":"Benchmark Tax liability"},{"$f":"B51","v":1.132876318882782},{"$f":"B61","v":0.99427974795563323},{"$f":"B71","v":1.024409437287622},{"$f":"B81","v":0.99427974795563323},{"$f":"B91","v":0.97620193435643998},5.1220471864381105]
["Total Revenue",{"$f":"SUM(B36:B40)","v":{"$error":"#NAME?"}},{"$f":"SUM(C36:C40)","v":{"$error":"#NAME?"}},{"$f":"SUM(D36:D40)","v":{"$error":"#NAME?"}},{"$f":"SUM(E36:E40)","v":{"$error":"#NAME?"}},{"$f":"SUM(F36:F40)","v":{"$error":"#NAME?"}},{"$error":"#NAME?"}]
[]
["Checks",{"$f":"B9-SUM(B25,B33,B41)","v":{"$error":"#NAME?"}},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"}]
[]
["Building Blocks by Zone for Tariff D"]
["2011-12","Total","Demand-AdNr","Demand-AdC","Demand-AdS","Demand-PP","Demand-Peter","Demand-River","Demand-SE","Demand-Whyal","Demand-Town"]
[{"$f":"A12","v":"Return on capital"},{"$f":"SUM(C47:K47)","v":6.6104538394383621},{"$f":"$B4*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":3.2047039998841069},{"$f":"$B4*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":1.8398824091882426},{"$f":"$B4*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":0.98444887797250968},{"$f":"$B4*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":0.20519170471546083},{"$f":"$B4*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":3.9543299206903623E-2},{"$f":"$B4*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":3.4218032487491334E-2},{"$f":"$B4*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":0.25555290828624294},{"$f":"$B4*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":4.6912607697403477E-2},{"$f":"$B4*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
[{"$f":"A13","v":"Return of capital"},{"$f":"SUM(C48:K48)","v":0.1506484466599444},{"$f":"$B5*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":7.3033363716593136E-2},{"$f":"$B5*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":4.1929863472840528E-2},{"$f":"$B5*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":2.2435024566374424E-2},{"$f":"$B5*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":4.6762011101973752E-3},{"$f":"$B5*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":9.0116907946453104E-4},{"$f":"$B5*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":7.798093091953358E-4},{"$f":"$B5*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":5.8239040174622361E-3},{"$f":"$B5*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":1.0691113878168522E-3},{"$f":"$B5*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
[{"$f":"A14","v":"O&M"},{"$f":"SUM(C49:K49)","v":{"$error":"#NAME?"}},{"$f":"$B6*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$B6*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$B6*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$B6*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$B6*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$B6*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$B6*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$B6*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$B6*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
[{"$f":"A15","v":"Carry-over amounts"},{"$f":"SUM(C50:K50)","v":{"$error":"#NAME?"}},{"$f":"$B7*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$B7*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$B7*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$B7*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$B7*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$B7*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$B7*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$B7*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$B7*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
[{"$f":"A16","v":"Benchmark Tax liability"},{"$f":"SUM(C51:K51)","v":1.132876318882782},{"$f":"$B8*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":0.54921089514878041},{"$f":"$B8*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":0.31531257331576079},{"$f":"$B8*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":0.16871138473913566},{"$f":"$B8*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":3.5165032348684261E-2},{"$f":"$B8*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":6.7767914775732734E-3},{"$f":"$B8*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":5.8641660051489252E-3},{"$f":"$B8*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":4.3795758211316017E-2},{"$f":"$B8*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":8.0397176363827295E-3},{"$f":"$B8*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
["Total Revenue",{"$f":"SUM(B47:B51)","v":{"$error":"#NAME?"}},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},0]
[]
["Checks",{"$f":"B52-B$41","v":{"$error":"#NAME?"}}]
[]
["2012-13","Total",{"$f":"C46","v":"Demand-AdNr"},{"$f":"D46","v":"Demand-AdC"},"Demand-AdS","Demand-PP","Demand-Peter","Demand-River","Demand-SE","Demand-Whyal","Demand-Town"]
[{"$f":"A47","v":"Return on capital"},{"$f":"SUM(C57:K57)","v":7.2974107562077064},{"$f":"$C4*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":3.5377361384317716},{"$f":"$C4*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":2.0310825866243953},{"$f":"$C4*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":1.0867525899951771},{"$f":"$C4*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":0.22651518177796084},{"$f":"$C4*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":4.3652630209261883E-2},{"$f":"$C4*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":3.7773962937422065E-2},{"$f":"$C4*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":0.28210991060587071},{"$f":"$C4*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":5.1787755625848315E-2},{"$f":"$C4*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
[{"$f":"A48","v":"Return of capital"},{"$f":"SUM(C58:K58)","v":0.20488188745752442},{"$f":"$C5*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":9.9325374654566673E-2},{"$f":"$C5*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":5.7024614323063119E-2},{"$f":"$C5*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":3.0511633410269214E-2},{"$f":"$C5*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":6.3596335098684304E-3},{"$f":"$C5*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":1.2255899480717622E-3},{"$f":"$C5*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":1.0605406605056567E-3},{"$f":"$C5*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":7.9205094637486411E-3},{"$f":"$C5*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":1.4539914874309189E-3},{"$f":"$C5*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
[{"$f":"A49","v":"O&M"},{"$f":"SUM(C59:K59)","v":{"$error":"#NAME?"}},{"$f":"$C6*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$C6*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$C6*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$C6*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$C6*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$C6*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$C6*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$C6*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$C6*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
[{"$f":"A50","v":"Carry-over amounts"},{"$f":"SUM(C60:K60)","v":{"$error":"#NAME?"}},{"$f":"$C7*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$C7*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$C7*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$C7*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$C7*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$C7*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$C7*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$C7*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$C7*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
[{"$f":"A51","v":"Benchmark Tax liability"},{"$f":"SUM(C61:K61)","v":0.99427974795563323},{"$f":"$C8*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":0.48202020052951472},{"$f":"$C8*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":0.27673709892074749},{"$f":"$C8*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":0.1480711621380712},{"$f":"$C8*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":3.0862927327302676E-2},{"$f":"$C8*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":5.947715924465905E-3},{"$f":"$C8*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":5.1467414406892158E-3},{"$f":"$C8*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":3.8437766515250764E-2},{"$f":"$C8*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":7.0561351595912246E-3},{"$f":"$C8*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
["Total Revenue",{"$f":"SUM(B57:B61)","v":{"$error":"#NAME?"}},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},0]
[]
["Checks",{"$f":"B62-C$41","v":{"$error":"#NAME?"}}]
[]
["2013-14","Total",{"$f":"C56","v":"Demand-AdNr"},{"$f":"D56","v":"Demand-AdC"},"Demand-AdS","Demand-PP","Demand-Peter","Demand-River","Demand-SE","Demand-Whyal","Demand-Town"]
[{"$f":"A57","v":"Return on capital"},{"$f":"SUM(C67:K67)","v":8.0325751759082369},{"$f":"$D4*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":3.8941389533687465},{"$f":"$D4*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":2.2357003203718575},{"$f":"$D4*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":1.1962355098790844},{"$f":"$D4*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":0.24933504319572408},{"$f":"$D4*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":4.8050335317048797E-2},{"$f":"$D4*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":4.1579432366295306E-2},{"$f":"$D4*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":0.31053056221108649},{"$f":"$D4*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":5.7005019198394562E-2},{"$f":"$D4*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
[{"$f":"A58","v":"Return of capital"},{"$f":"SUM(C68:K68)","v":0.26514126612150224},{"$f":"$D5*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":0.12853872014120393},{"$f":"$D5*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":7.3796559712199339E-2},{"$f":"$D5*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":3.9485643236818989E-2},{"$f":"$D5*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":8.2301139539473819E-3},{"$f":"$D5*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":1.5860575798575748E-3},{"$f":"$D5*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":1.3724643841837912E-3},{"$f":"$D5*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":1.0250071070733537E-2},{"$f":"$D5*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":1.88163604255766E-3},{"$f":"$D5*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
[{"$f":"A59","v":"O&M"},{"$f":"SUM(C69:K69)","v":{"$error":"#NAME?"}},{"$f":"$D6*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$D6*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$D6*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$D6*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$D6*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$D6*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$D6*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$D6*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$D6*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
[{"$f":"A60","v":"Carry-over amounts"},{"$f":"SUM(C70:K70)","v":{"$error":"#NAME?"}},{"$f":"$D7*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$D7*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$D7*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$D7*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$D7*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$D7*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$D7*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$D7*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$D7*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
[{"$f":"A61","v":"Benchmark Tax liability"},{"$f":"SUM(C71:K71)","v":1.024409437287622},{"$f":"$D8*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":0.49662687327283334},{"$f":"$D8*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":0.28512307161531564},{"$f":"$D8*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":0.15255816705134609},{"$f":"$D8*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":3.179816754934215E-2},{"$f":"$D8*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":6.1279497403588113E-3},{"$f":"$D8*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":5.3027033025282834E-3},{"$f":"$D8*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":3.9602547318743207E-2},{"$f":"$D8*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":7.2699574371545951E-3},{"$f":"$D8*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
["Total Revenue",{"$f":"SUM(B67:B71)","v":{"$error":"#NAME?"}},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},0]
[]
["Checks",{"$f":"B72-D$41","v":{"$error":"#NAME?"}}]
[]
["2014-15","Total",{"$f":"C66","v":"Demand-AdNr"},{"$f":"D66","v":"Demand-AdC"},"Demand-AdS","Demand-PP","Demand-Peter","Demand-River","Demand-SE","Demand-Whyal","Demand-Town"]
[{"$f":"A67","v":"Return on capital"},{"$f":"SUM(C77:K77)","v":8.7255580305439828},{"$f":"$E4*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":4.2300924264650748},{"$f":"$E4*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":2.428577692346924},{"$f":"$E4*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":1.2994366228844068},{"$f":"$E4*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":0.27084556830263201},{"$f":"$E4*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":5.2195713082585644E-2},{"$f":"$E4*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":4.5166555188593853E-2},{"$f":"$E4*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":0.33732052069141277},{"$f":"$E4*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":6.1922931582352084E-2},{"$f":"$E4*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
[{"$f":"A68","v":"Return of capital"},{"$f":"SUM(C78:K78)","v":0.27116720398790006},{"$f":"$E5*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":0.13146005468986766},{"$f":"$E5*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":7.5473754251112954E-2},{"$f":"$E5*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":4.038304421947396E-2},{"$f":"$E5*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":8.4171619983552763E-3},{"$f":"$E5*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":1.622104343036156E-3},{"$f":"$E5*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":1.4036567565516044E-3},{"$f":"$E5*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":1.0483027231432025E-2},{"$f":"$E5*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":1.924400498070334E-3},{"$f":"$E5*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
[{"$f":"A69","v":"O&M"},{"$f":"SUM(C79:K79)","v":{"$error":"#NAME?"}},{"$f":"$E6*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$E6*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$E6*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$E6*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$E6*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$E6*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$E6*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$E6*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$E6*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
[{"$f":"A70","v":"Carry-over amounts"},{"$f":"SUM(C80:K80)","v":{"$error":"#NAME?"}},{"$f":"$E7*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$E7*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$E7*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$E7*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$E7*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$E7*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$E7*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$E7*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$E7*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
[{"$f":"A71","v":"Benchmark Tax liability"},{"$f":"SUM(C81:K81)","v":0.99427974795563323},{"$f":"$E8*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":0.48202020052951472},{"$f":"$E8*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":0.27673709892074749},{"$f":"$E8*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":0.1480711621380712},{"$f":"$E8*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":3.0862927327302676E-2},{"$f":"$E8*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":5.947715924465905E-3},{"$f":"$E8*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":5.1467414406892158E-3},{"$f":"$E8*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":3.8437766515250764E-2},{"$f":"$E8*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":7.0561351595912246E-3},{"$f":"$E8*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
["Total Revenue",{"$f":"SUM(B77:B81)","v":{"$error":"#NAME?"}},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},0]
[]
["Checks",{"$f":"B82-E$41","v":{"$error":"#NAME?"}}]
[]
["2015-16","Total",{"$f":"C76","v":"Demand-AdNr"},{"$f":"D76","v":"Demand-AdC"},"Demand-AdS","Demand-PP","Demand-Peter","Demand-River","Demand-SE","Demand-Whyal","Demand-Town"]
[{"$f":"A77","v":"Return on capital"},{"$f":"SUM(C87:K87)","v":9.4848262017101046},{"$f":"$F4*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":4.5981805795967041},{"$f":"$F4*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":2.63990420425004},{"$f":"$F4*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":1.4125091466989337},{"$f":"$F4*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":0.29441362189802678},{"$f":"$F4*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":5.6737605243086874E-2},{"$f":"$F4*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":4.9096794106938346E-2},{"$f":"$F4*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":0.3666729969394224},{"$f":"$F4*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":6.7311252976949024E-2},{"$f":"$F4*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$5,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
[{"$f":"A78","v":"Return of capital"},{"$f":"SUM(C88:K88)","v":0.30732283118628662},{"$f":"$F5*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":0.14898806198185},{"$f":"$F5*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":8.5536921484594686E-2},{"$f":"$F5*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":4.576745011540382E-2},{"$f":"$F5*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":9.5394502648026448E-3},{"$f":"$F5*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":1.8383849221076433E-3},{"$f":"$F5*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":1.5908109907584848E-3},{"$f":"$F5*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":1.1880764195622961E-2},{"$f":"$F5*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":2.1809872311463782E-3},{"$f":"$F5*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$6,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
[{"$f":"A79","v":"O&M"},{"$f":"SUM(C89:K89)","v":{"$error":"#NAME?"}},{"$f":"$F6*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$F6*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$F6*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$F6*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$F6*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$F6*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$F6*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$F6*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$F6*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$7,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
[{"$f":"A80","v":"Carry-over amounts"},{"$f":"SUM(C90:K90)","v":{"$error":"#NAME?"}},{"$f":"$F7*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$F7*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$F7*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$F7*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$F7*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$F7*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$F7*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$F7*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":{"$error":"#NAME?"}},{"$f":"$F7*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$8,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
[{"$f":"A81","v":"Benchmark Tax liability"},{"$f":"SUM(C91:K91)","v":0.97620193435643998},{"$f":"$F8*HLOOKUP(C$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":0.47325619688352355},{"$f":"$F8*HLOOKUP(D$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":0.27170551530400666},{"$f":"$F8*HLOOKUP(E$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":0.14537895919010627},{"$f":"$F8*HLOOKUP(F$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":3.0301783194078991E-2},{"$f":"$F8*HLOOKUP(G$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":5.839575634930161E-3},{"$f":"$F8*HLOOKUP(H$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":5.053164323585776E-3},{"$f":"$F8*HLOOKUP(I$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":3.7738898033155291E-2},{"$f":"$F8*HLOOKUP(J$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":6.9278417930532018E-3},{"$f":"$F8*HLOOKUP(K$46,'Cost allocators'!$H$18:$P$22,(MATCH('Cost allocators'!$B$9,'Cost allocators'!$A$19:$A$22)+1))","v":0}]
["Total Revenue",{"$f":"SUM(B87:B91)","v":{"$error":"#NAME?"}},{"$f":"SUM(C87:C91)","v":{"$error":"#NAME?"}},{"$f":"SUM(D87:D91)","v":{"$error":"#NAME?"}},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"},0]
[]
["Checks",{"$f":"B92-F$41","v":{"$error":"#NAME?"}}]

{"sheet":"StandAlone & Avoidable Tests","index":11,"n_rows":14,"n_cols":8,"rows_kept":14,"cut":false,"hidden":false,"merged":[[2,0,2,7],[0,0,0,9]]}
["Standalone and Avoidable Cost Tests"]
[]
["Standalone and Avoidable Cost Tests"]
["Tariff","FDC Cost","Avoidable Cost","Expected Revenue 2011-12 ($M)","Standalone Cost","All Tests Met?","Avoidable Test Met?","Standalone Test Met?"]
["Tariff R",{"$f":"'FDC Calculations'!B25","v":{"$error":"#NAME?"}},{"$f":"'DORC Calculations'!D358","v":{"$error":"#NAME?"}},{"$f":"'[8]Tariff Impacts'!$D$36/1000000","v":100.17932024383798},{"$f":"'FDC Calculations'!$B$25+'FDC Calculations'!B41","v":{"$error":"#NAME?"}},{"$f":"IF(AND(D5>=C5,D5<=E5),\"Test Met\",\"Test Failed\")","v":{"$error":"#NAME?"}},{"$f":"IF(D5>=C5,\"Test Met\",\"Test Failed\")","v":{"$error":"#NAME?"}},{"$f":"IF(D5<=E5,\"Test Met\",\"Test Failed\")","v":{"$error":"#NAME?"}}]
["Tariff C",{"$f":"'FDC Calculations'!B33","v":{"$error":"#NAME?"}},{"$f":"'DORC Calculations'!E358","v":{"$error":"#NAME?"}},{"$f":"'[8]Tariff Impacts'!$D$43/1000000","v":18.999222232144547},{"$f":"'FDC Calculations'!B33+'FDC Calculations'!B41","v":{"$error":"#NAME?"}},{"$error":"#NAME?"},{"$f":"IF(D6>=C6,\"Test Met\",\"Test Failed\")","v":{"$error":"#NAME?"}},{"$f":"IF(D6<=E6,\"Test Met\",\"Test Failed\")","v":{"$error":"#NAME?"}}]
["Tariff D - Adelaide Northern",{"$f":"'FDC Calculations'!C52","v":{"$error":"#NAME?"}},{"$f":"'DORC Calculations'!C359","v":{"$error":"#NAME?"}},{"$f":"'[8]Tariff Impacts'!$D$53/1000000","v":11.465217603131247},{"$f":"'FDC Calculations'!B41","v":{"$error":"#NAME?"}},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"}]
["Tariff D - Adelaide Central",{"$f":"'FDC Calculations'!D52","v":{"$error":"#NAME?"}},{"$f":"'DORC Calculations'!C358","v":{"$error":"#NAME?"}},{"$f":"'[8]Tariff Impacts'!$D$52/1000000","v":4.6314570177291463},{"$f":"'FDC Calculations'!B41","v":{"$error":"#NAME?"}},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"}]
["Tariff D - Adelaide Southern",{"$f":"'FDC Calculations'!E52","v":{"$error":"#NAME?"}},{"$f":"'DORC Calculations'!C360","v":{"$error":"#NAME?"}},{"$f":"'[8]Tariff Impacts'!$D$54/1000000","v":1.6003792843480622},{"$f":"'FDC Calculations'!B41","v":{"$error":"#NAME?"}},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"}]
["Tariff D - Port Pirie",{"$f":"'FDC Calculations'!F52","v":{"$error":"#NAME?"}},{"$f":"'DORC Calculations'!C362","v":{"$error":"#NAME?"}},{"$f":"'[8]Tariff Impacts'!$D$56/1000000","v":0.37673145599999996},{"$f":"'FDC Calculations'!B41","v":{"$error":"#NAME?"}},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"}]
["Tariff D - Petersborough",{"$f":"'FDC Calculations'!G52","v":{"$error":"#NAME?"}},{"$f":"'DORC Calculations'!C361","v":{"$error":"#NAME?"}},{"$f":"'[8]Tariff Impacts'!$D$55/1000000","v":0.53736999747178582},{"$f":"'FDC Calculations'!B41","v":{"$error":"#NAME?"}},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"}]
["Tariff D - Riverlands",{"$f":"'FDC Calculations'!H52","v":{"$error":"#NAME?"}},{"$f":"'DORC Calculations'!C363","v":{"$error":"#NAME?"}},{"$f":"'[8]Tariff Impacts'!$D$57/1000000","v":0.18764045219871989},{"$f":"'FDC Calculations'!B41","v":{"$error":"#NAME?"}},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"}]
["Tariff D - South East",{"$f":"'FDC Calculations'!I52","v":{"$error":"#NAME?"}},{"$f":"'DORC Calculations'!C364","v":{"$error":"#NAME?"}},{"$f":"'[8]Tariff Impacts'!$D$58/1000000","v":0.40991608800000001},{"$f":"'FDC Calculations'!B41","v":{"$error":"#NAME?"}},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"}]
["Tariff D - Whyalla",{"$f":"'FDC Calculations'!J52","v":{"$error":"#NAME?"}},{"$f":"'DORC Calculations'!C365","v":{"$error":"#NAME?"}},{"$f":"'[8]Tariff Impacts'!$D$60/1000000","v":0.16830288000000002},{"$f":"'FDC Calculations'!B41","v":{"$error":"#NAME?"}},{"$error":"#NAME?"},{"$error":"#NAME?"},{"$error":"#NAME?"}]

{"sheet":"Tariff & Rebalancing Tests","index":12,"n_rows":102,"n_cols":16,"rows_kept":102,"cut":false,"hidden":false,"merged":[[11,10,15,10],[11,4,15,4],[11,1,15,1],[11,6,15,6],[11,7,15,7],[11,8,15,8],[11,2,15,3],[16,2,16,3],[54,0,54,11],[11,11,15,11],[0,0,0,11],[11,9,15,9],[10,0,10,5],[10,6,10,11],[2,5,2,6]]}
["Tariff Control and Rebalancing Tests - Does not apply for 2011-12"]
[]
[null,null,null,null,null,"Input Selection"]
[null,null,null,null,null,"CPI t",{"$f":"'General Inputs'!L16","v":2.8880866425992746E-2}]
[null,null,null,null,null,"X t ",-0.191]
[null,null,null,null,null,"Y t ",0.01]
[null,null,null,null,null," t ",2010]
[null,null,null,null,null," t – 1 ",2009]
[null,null,null,null,null," t – 2 ",2008]
[]
["Tariff Control",null,null,null,null,null,"Rebalancing Control"]
[null,"CPIt(Mar)(1 – Xt)","                             -1",null,"Constraint met?",null,"Tariff class","CPIt (1 – Xt)(1 + Yt)",null,null,-1,"Constraint met?"]
[]
[]
[]
[]
[null,{"$f":"G4*(1-G5)","v":3.4397111913357363E-2},{"$f":"(SUM(I17:I30)/SUM(J17:J30))-1","v":4.0654385198453769E-2},null,{"$f":"IF(B17>=C17,\"Yes\",\"No\")","v":"No"},null,{"$f":"C96","v":"Residential 1"},{"$f":"G4*(1-G5)*(1+G6)","v":3.4741083032490939E-2},{"$f":"SUM(C97:C102)","v":114193843.80156776},{"$f":"SUM(C89:C94)","v":109555821.84339307},{"$f":"IFERROR((I17/J17)-1,\"\")","v":{"$error":"#NAME?"}},{"$f":"IF(K17=\"\",\"\",IF(H17>=K17,\"Yes\",\"No\"))","v":{"$error":"#NAME?"}}]
[null,null,null,null,null,null,{"$f":"D96","v":"Residential 2"},{"$f":"H17","v":3.4741083032490939E-2},{"$f":"SUM(D97:D102)","v":0},{"$f":"SUM(D89:D94)","v":0},{"$error":"#NAME?"},{"$f":"IF(K18=\"\",\"\",IF(H18>=K18,\"Yes\",\"No\"))","v":{"$error":"#NAME?"}}]
[null,null,null,null,null,null,{"$f":"E96","v":"Residential 3"},{"$f":"H18","v":3.4741083032490939E-2},{"$f":"SUM(E97:E102)","v":0},{"$f":"SUM(E89:E94)","v":0},{"$error":"#NAME?"},{"$error":"#NAME?"}]
[null,null,null,null,null,null,{"$f":"F96","v":"Commercial 1"},3.4741083032490939E-2,{"$f":"SUM(F97:F102)","v":19605606.392587237},{"$f":"SUM(F89:F94)","v":19152267.914579518},{"$error":"#NAME?"},{"$error":"#NAME?"}]
[null,null,null,null,null,null,{"$f":"G96","v":"Commercial 2"},3.4741083032490939E-2,{"$f":"SUM(G97:G102)","v":0},{"$f":"SUM(G89:G94)","v":0},{"$error":"#NAME?"},{"$error":"#NAME?"}]
[null,null,null,null,null,null,{"$f":"H96","v":"Demand-AdC"},3.4741083032490939E-2,{"$f":"SUM(H97:H102)","v":1557094.0658798981},{"$f":"SUM(H89:H94)","v":1458588.2031417491},{"$error":"#NAME?"},{"$error":"#NAME?"}]
[null,null,null,null,null,null,{"$f":"I96","v":"Demand-AdNr"},3.4741083032490939E-2,{"$f":"SUM(I97:I102)","v":2664403.1857731575},{"$f":"SUM(I89:I94)","v":2495486.5485930601},{"$error":"#NAME?"},{"$error":"#NAME?"}]
[null,null,null,null,null,null,{"$f":"J96","v":"Demand-AdS"},{"$f":"H23","v":3.4741083032490939E-2},{"$f":"SUM(J97:J102)","v":808725.1808938547},{"$f":"SUM(J89:J94)","v":757998.77061452507},{"$error":"#NAME?"},{"$error":"#NAME?"}]
[null,null,null,null,null,null,{"$f":"K96","v":"Demand-Peter"},{"$f":"H24","v":3.4741083032490939E-2},{"$f":"SUM(K97:K102)","v":48403.92},{"$f":"SUM(K89:K94)","v":44425.72},{"$error":"#NAME?"},{"$error":"#NAME?"}]
[null,null,null,null,null,null,{"$f":"L96","v":"Demand-PP"},3.4741083032490939E-2,{"$f":"SUM(L97:L102)","v":77024.44},{"$f":"SUM(L89:L94)","v":72109.759999999995},{"$error":"#NAME?"},{"$error":"#NAME?"}]
[null,null,null,null,null,null,{"$f":"M96","v":"Demand-River"},3.4741083032490939E-2,{"$f":"SUM(M97:M102)","v":116407},{"$f":"SUM(M89:M94)","v":107273},{"$error":"#NAME?"},{"$error":"#NAME?"}]
[null,null,null,null,null,null,{"$f":"N96","v":"Demand-SE"},3.4741083032490939E-2,{"$f":"SUM(N97:N102)","v":181923.75428168522},{"$f":"SUM(N89:N94)","v":170229.24979711475},{"$error":"#NAME?"},{"$error":"#NAME?"}]
[null,null,null,null,null,null,{"$f":"O96","v":"Demand-Town"},3.4741083032490939E-2,{"$f":"SUM(O97:O102)","v":0},{"$f":"SUM(O89:O94)","v":0},{"$error":"#NAME?"},{"$error":"#NAME?"}]
[null,null,null,null,null,null,{"$f":"P96","v":"Demand-Whyal"},3.4741083032490939E-2,{"$f":"SUM(P97:P102)","v":34014.800000000003},{"$f":"SUM(P89:P94)","v":31817.919999999998},{"$error":"#NAME?"},{"$error":"#NAME?"}]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["Calculations"]
["2008/09","Existing Quantities","Residential 1","Residential 2","Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Town","Demand-Whyal"]
[null,"Volumes Band 1",{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,2)","v":5090813.14115451},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,3)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,4)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,5)","v":1234779.3942563587},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,6)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,7)","v":2112.8879276202028},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,8)","v":3699.1571207803777},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,9)","v":1177.1731843575419},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,10)","v":50},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,11)","v":100},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,12)","v":100},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,13)","v":221.25275654501652},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,14)","v":145.54285714285712},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,15)","v":50}]
[null,"Volumes Band 2",{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,2)","v":2810587.4451109674},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,3)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,4)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,5)","v":1182708.1604937487},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,6)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,7)","v":1569.2994880597325},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,8)","v":2989.9753996798759},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,9)","v":873.24022346368702},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,10)","v":12},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,11)","v":100},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,12)","v":100},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,13)","v":146.02681931971094},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,14)","v":137.45714285714283},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,15)","v":7}]
[null,"Volumes Band 3",{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,2)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,3)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,4)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,5)","v":572374.2723577643},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,6)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,7)","v":6342.164608899041},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,8)","v":14534.018588157158},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,9)","v":2009.5865921787708},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,10)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,11)","v":616},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,12)","v":550},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,13)","v":613.31264114278599},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,14)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,15)","v":0}]
[null,"Volumes Band 4",{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,2)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,3)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,4)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,5)","v":284531.29526304791},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,6)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,7)","v":288.12108103911856},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,8)","v":30924.18830715309},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,9)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,10)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,11)","v":500},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,12)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,13)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,14)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,15)","v":0}]
[null,"Volumes Band 5",{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,2)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,3)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,4)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,5)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,6)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,7)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,8)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,9)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,10)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,11)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,12)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,13)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,14)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,15)","v":0}]
[null,"Customer Numbers",{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,2)","v":381428},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,3)","v":0},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,4)","v":0},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,5)","v":9506},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,6)","v":0},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,7)","v":43},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,8)","v":74.000000000000014},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,9)","v":22},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,10)","v":1},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,11)","v":2},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,12)","v":2},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,13)","v":5},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,14)","v":3},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,15)","v":1}]
[]
["2008/09","Alternative Quantities","Residential 1","Residential 2","Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Town","Demand-Whyal"]
[null,"Volumes Band 1",{"$f":"'[9]2008-09 Consumption Bands'!$G$67","v":3307282.6577320378},0,0,{"$f":"SUM('[10]2008-09 Consumption Bands'!$I$67+'[11]2008-09 Consumption Bands'!$I$67)","v":1141530.2809764347},0,{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,7)","v":2112.8879276202028},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,8)","v":3699.1571207803777},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,9)","v":1177.1731843575419},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,10)","v":50},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,11)","v":100},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,12)","v":100},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,13)","v":221.25275654501652},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,14)","v":145.54285714285712},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$5:$O$9,15)","v":50}]
[null,"Volumes Band 2",{"$f":"'[9]2008-09 Consumption Bands'!$H$67","v":1782508.3714224708},0,0,{"$f":"SUM('[10]2008-09 Consumption Bands'!$J$67+'[11]2008-09 Consumption Bands'!$J$67)","v":1262476.8804622106},0,{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,7)","v":1569.2994880597325},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,8)","v":2989.9753996798759},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,9)","v":873.24022346368702},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,10)","v":12},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,11)","v":100},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,12)","v":100},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,13)","v":146.02681931971094},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,14)","v":137.45714285714283},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$17:$O$21,15)","v":7}]
[null,"Volumes Band 3",{"$f":"'[9]2008-09 Consumption Bands'!$I$67","v":2811609.5571109685},0,0,{"$f":"SUM('[10]2008-09 Consumption Bands'!$K$67+'[11]2008-09 Consumption Bands'!$K$67)","v":583363.23984268552},0,{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,7)","v":6342.164608899041},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,8)","v":14534.018588157158},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,9)","v":2009.5865921787708},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,10)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,11)","v":616},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,12)","v":550},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,13)","v":613.31264114278599},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,14)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$29:$O$33,15)","v":0}]
[null,"Volumes Band 4",0,0,0,{"$f":"SUM('[10]2008-09 Consumption Bands'!$L$67+'[11]2008-09 Consumption Bands'!$L$67)","v":287022.72108958877},0,{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,7)","v":288.12108103911856},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,8)","v":30924.18830715309},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,9)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,10)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,11)","v":500},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,12)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,13)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,14)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$41:$O$45,15)","v":0}]
[null,"Volumes Band 5",0,0,0,0,0,{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,7)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,8)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,9)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,10)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,11)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,12)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,13)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,14)","v":0},{"$f":"VLOOKUP($A$56,'Volume Inputs'!$A$53:$O$57,15)","v":0}]
[null,"Customer Numbers",{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,2)","v":381428},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,3)","v":0},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,4)","v":0},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,5)","v":9506},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,6)","v":0},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,7)","v":43},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,8)","v":74.000000000000014},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,9)","v":22},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,10)","v":1},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,11)","v":2},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,12)","v":2},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,13)","v":5},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,14)","v":3},{"$f":"VLOOKUP($A$56,'Connection Numbers Inputs'!$A$77:$O$81,15)","v":1}]
[]
["2009/10","Prices","Residential 1","Residential 2","Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Town","Demand-Whyal"]
[null,"Volumes Band 1 ($/GJ)",{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$4:$H$11,4)","v":11.02},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$13:$H$20,4)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$22:$H$29,4)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$31:$H$38,4)","v":8.3000000000000007},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$40:$H$47,4)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$58:$H$65,4)","v":38.619999999999997},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$49:$H$56,4)","v":32.4},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$67:$H$74,4)","v":45.54},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$85:$H$92,4)","v":47.54},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$76:$H$83,4)","v":32.39},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$94:$H$101,4)","v":47.43},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$103:$H$110,4)","v":32.39},0,{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$112:$H$119,4)","v":32.53}]
[null,"Volumes Band 2 ($/GJ)",{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$4:$H$11,5)","v":5.14},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$13:$H$20,5)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$22:$H$29,5)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$31:$H$38,5)","v":4.6900000000000004},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$40:$H$47,5)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$58:$H$65,5)","v":25.29},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$49:$H$56,5)","v":20.91},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$67:$H$74,5)","v":29.39},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$85:$H$92,5)","v":30.06},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$76:$H$83,5)","v":17.059999999999999},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$94:$H$101,5)","v":30.06},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$103:$H$110,5)","v":17.059999999999999},0,{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$112:$H$119,5)","v":17.059999999999999}]
[null,"Volumes Band 3 ($/GJ)",{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$4:$H$11,6)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$13:$H$20,6)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$22:$H$29,6)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$31:$H$38,6)","v":2.04},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$40:$H$47,6)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$58:$H$65,6)","v":6.97},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$49:$H$56,6)","v":6.04},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$67:$H$74,6)","v":8.5299999999999994},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$85:$H$92,6)","v":29.36},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$76:$H$83,6)","v":6.86},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$94:$H$101,6)","v":29.36},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$103:$H$110,6)","v":16.649999999999999},0,{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$112:$H$119,6)","v":16.649999999999999}]
[null,"Volumes Band 4 ($/GJ)",{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$4:$H$11,7)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$13:$H$20,7)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$22:$H$29,7)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$31:$H$38,7)","v":0.86},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$40:$H$47,7)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$58:$H$65,7)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$49:$H$56,7)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$67:$H$74,7)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$85:$H$92,7)","v":6.05},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$76:$H$83,7)","v":5.59},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$94:$H$101,7)","v":6.05},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$103:$H$110,7)","v":6.05},0,{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$112:$H$119,7)","v":6.05}]
[null,"Volumes Band 5 ($/GJ)",{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$4:$H$11,8)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$13:$H$20,8)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$22:$H$29,8)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$31:$H$38,8)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$40:$H$47,8)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$58:$H$65,8)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$49:$H$56,8)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$67:$H$74,8)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$85:$H$92,8)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$76:$H$83,8)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$94:$H$101,8)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$103:$H$110,8)","v":0},0,{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$112:$H$119,8)","v":0}]
[null,"Daily or Monthly Charge",{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$4:$H$11,3)","v":0.28000000000000003},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$13:$H$20,3)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$22:$H$29,3)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$31:$H$38,3)","v":0.56000000000000005},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$40:$H$47,3)","v":0},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$58:$H$65,3)","v":2506},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$49:$H$56,3)","v":2506},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$67:$H$74,3)","v":2506},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$85:$H$92,3)","v":3474},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$76:$H$83,3)","v":2506},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$94:$H$101,3)","v":3474},{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$103:$H$110,3)","v":2506},0,{"$f":"HLOOKUP($A$72,'Tariff Inputs'!$B$112:$H$119,3)","v":2506}]
[]
["2010/11","Prices","Residential 1","Residential 2","Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Town","Demand-Whyal"]
[null,"Volumes Band 1 ($/GJ)",{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$4:$H$11,4)","v":14},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$13:$H$20,4)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$22:$H$29,4)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$31:$H$38,4)","v":8.8000000000000007},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$40:$H$47,4)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$58:$H$65,4)","v":40.590000000000003},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$49:$H$56,4)","v":34.06},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$67:$H$74,4)","v":47.86},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$85:$H$92,4)","v":49.92},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$76:$H$83,4)","v":34.049999999999997},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$94:$H$101,4)","v":49.8},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$103:$H$110,4)","v":34.049999999999997},0,{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$112:$H$119,4)","v":34.18}]
[null,"Volumes Band 2 ($/GJ)",{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$4:$H$11,5)","v":8.3446499999999997},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$13:$H$20,5)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$22:$H$29,5)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$31:$H$38,5)","v":4.72},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$40:$H$47,5)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$58:$H$65,5)","v":25.8},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$49:$H$56,5)","v":21.33},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$67:$H$74,5)","v":29.97},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$85:$H$92,5)","v":30.66},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$76:$H$83,5)","v":17.399999999999999},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$94:$H$101,5)","v":30.66},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$103:$H$110,5)","v":17.399999999999999},0,{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$112:$H$119,5)","v":17.399999999999999}]
[null,"Volumes Band 3 ($/GJ)",{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$4:$H$11,6)","v":3.4959830097564191},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$13:$H$20,6)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$22:$H$29,6)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$31:$H$38,6)","v":2.06},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$40:$H$47,6)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$58:$H$65,6)","v":7.4},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$49:$H$56,6)","v":6.4},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$67:$H$74,6)","v":9.0399999999999991},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$85:$H$92,6)","v":31.42},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$76:$H$83,6)","v":7.34},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$94:$H$101,6)","v":31.42},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$103:$H$110,6)","v":17.82},0,{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$112:$H$119,6)","v":17.82}]
[null,"Volumes Band 4 ($/GJ)",{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$4:$H$11,7)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$13:$H$20,7)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$22:$H$29,7)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$31:$H$38,7)","v":0.86},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$40:$H$47,7)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$58:$H$65,7)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$49:$H$56,7)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$67:$H$74,7)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$85:$H$92,7)","v":6.47},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$76:$H$83,7)","v":5.98},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$94:$H$101,7)","v":6.47},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$103:$H$110,7)","v":6.47},0,{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$112:$H$119,7)","v":6.47}]
[null,"Volumes Band 5 ($/GJ)",{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$4:$H$11,8)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$13:$H$20,8)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$22:$H$29,8)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$31:$H$38,8)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$40:$H$47,8)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$58:$H$65,8)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$49:$H$56,8)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$67:$H$74,8)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$85:$H$92,8)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$76:$H$83,8)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$94:$H$101,8)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$103:$H$110,8)","v":0},0,{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$112:$H$119,8)","v":0}]
[null,"Daily or Monthly Charge",{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$4:$H$11,3)","v":0.31},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$13:$H$20,3)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$22:$H$29,3)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$31:$H$38,3)","v":0.62},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$40:$H$47,3)","v":0},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$58:$H$65,3)","v":2682},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$49:$H$56,3)","v":2682},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$67:$H$74,3)","v":2682},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$85:$H$92,3)","v":3795},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$76:$H$83,3)","v":2682},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$94:$H$101,3)","v":3795},{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$103:$H$110,3)","v":2682},0,{"$f":"HLOOKUP($A$80,'Tariff Inputs'!$B$112:$H$119,3)","v":2682}]
[]
["2009/10 p*q",null,"Residential 1","Residential 2","Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Town","Demand-Whyal"]
[null,"Volumes Band 1",{"$f":"C73*C57","v":56100760.815522701},0,0,10248668.972327778,0,81599.731764692231,{"$f":"I73*I57","v":119852.69071328423},53608.46681564246,2377,3239,4743,7166.3767844930853,0,1626.5]
[null,"Volumes Band 2",14446419.467870371,0,0,5546901.2727156822,0,39687.584053030638,{"$f":"I74*I58","v":62520.385607306205},25664.530167597761,360.71999999999997,1705.9999999999998,3006,2491.2175375942684,0,119.41999999999999]
[null,"Volumes Band 3",0,0,0,1167643.5156098392,0,44204.887324026313,{"$f":"I75*I59","v":87785.47227246924},17141.773631284916,0,4225.76,16148,10211.655475027386,0,0]
[null,"Volumes Band 4",0,0,0,244696.9139262212,0,0,{"$f":"I76*I60","v":0},0,0,2795,0,0,0,0]
[null,"Volumes Band 5",0,0,0,0,0,0,{"$f":"I77*I61","v":0},0,0,0,0,0,0,0]
[null,"Daily Charge",{"$f":"C78*365.25*C62","v":39008641.560000002},{"$f":"D78*365.25*D62","v":0},{"$f":"E78*365.25*E62","v":0},{"$f":"F78*365.25*F62","v":1944357.2400000002},{"$f":"G78*365.25*G62","v":0},{"$f":"H78*H62*12","v":1293096},{"$f":"I78*I62*12","v":2225328.0000000005},661584,41688,60144,83376,150360,0,30072]
[]
["2010/11 p*q",null,"Residential 1","Residential 2","Residential 3","Commercial 1","Commercial 2","Demand-AdC","Demand-AdNr","Demand-AdS","Demand-Peter","Demand-PP","Demand-River","Demand-SE","Demand-Town","Demand-Whyal"]
[null,"Volumes Band 1",{"$f":"C81*C65","v":46301957.208248526},0,0,10045466.472592626,0,85762.120982104039,{"$f":"I81*I65","v":125993.29153377967},56339.508603351955,2496,3404.9999999999995,4980,7533.6563603578124,0,1709]
[null,"Volumes Band 2",14874408.481590521,0,0,5958890.8757816339,0,40487.9267919411,{"$f":"I82*I66","v":63776.17527517175},26171.009497206698,367.92,1739.9999999999998,3066,2540.8666561629702,0,121.79999999999998]
[null,"Volumes Band 3",9829339.2417287156,0,0,1201728.2740759321,0,46932.018105852905,{"$f":"I83*I67","v":93017.718964205822},18166.662793296087,0,4521.4399999999996,17281,10929.231265164446,0,0]
[null,"Volumes Band 4",0,0,0,246839.54013704634,0,0,{"$f":"I84*I68","v":0},0,0,2990,0,0,0,0]
[null,"Volumes Band 5",0,0,0,0,0,0,{"$f":"I85*I69","v":0},0,0,0,0,0,0,0]
[null,"Daily Charge",{"$f":"C86*365.25*C70","v":43188138.870000005},{"$f":"D86*D70","v":0},{"$f":"E86*E70","v":0},{"$f":"F86*365.25*F70","v":2152681.23},{"$f":"G86*365.25*G70","v":0},{"$f":"H86*H70*12","v":1383912},{"$f":"I86*I70*12","v":2381616.0000000005},708048,45540,64368,91080,160920,0,32184]